{"id":5280,"date":"2025-09-01T00:00:00","date_gmt":"2025-09-01T00:00:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/knowledge-center\/optical-transceiver-insertion-loss-definition-impact\/"},"modified":"2026-06-22T07:58:23","modified_gmt":"2026-06-22T07:58:23","slug":"optical-transceiver-insertion-loss-definition-impact","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/th\/knowledge-center\/optical-transceiver-insertion-loss-definition-impact","title":{"rendered":"\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e2a\u0e2d\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e41\u0e2a\u0e07: \u0e19\u0e34\u0e22\u0e32\u0e21 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a"},"content":{"rendered":"<h2 class=\"wp-block-heading\" >\u25b6 \u0e1a\u0e17\u0e19\u0e33<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e14\u0e49\u0e27\u0e22\u0e41\u0e2a\u0e07 \u0e04\u0e48\u0e32\u0e17\u0e28\u0e19\u0e34\u0e22\u0e21\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e28\u0e29\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e14\u0e0b\u0e34\u0e40\u0e1a\u0e25\u0e2d\u0e32\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e27\u0e48\u0e32\u0e25\u0e34\u0e07\u0e01\u0e4c\u0e08\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e25\u0e49\u0e21\u0e40\u0e2b\u0e25\u0e27\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e20\u0e32\u0e23\u0e30\u0e07\u0e32\u0e19 <strong>\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e2a\u0e2d\u0e14 (IL)<\/strong> \u2014 \u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e44\u0e1b\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e07\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e31\u0e27\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d \u0e2b\u0e23\u0e37\u0e2d\u0e25\u0e34\u0e07\u0e01\u0e4c\u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e2a\u0e2d\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e33\u0e19\u0e27\u0e13\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e25\u0e34\u0e07\u0e01\u0e4c \u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\">\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e23\u0e32\u0e22\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e19\u0e35\u0e49\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e2a\u0e2d\u0e14\u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14 \u0e04\u0e48\u0e32\u0e42\u0e14\u0e22\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e2b\u0e15\u0e38\u0e43\u0e14\u0e08\u0e36\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e42\u0e21\u0e14\u0e39\u0e25\u0e41\u0e2a\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e21\u0e14\u0e39\u0e25\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e14\u0e22 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/page\/aboutus.htm\"><strong>\u0e25\u0e34\u0e07\u0e01\u0e4c-\u0e1e\u0e35\u0e1e\u0e35<\/strong><\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/283194d74a2a4ae4857bfb467fb58fca.webp\" alt=\"Optical transceiver insertion loss visualized across LC and MPO connectors in a data center link\" class=\"wp-image-5276\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/283194d74a2a4ae4857bfb467fb58fca.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/283194d74a2a4ae4857bfb467fb58fca-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/283194d74a2a4ae4857bfb467fb58fca-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/283194d74a2a4ae4857bfb467fb58fca-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/283194d74a2a4ae4857bfb467fb58fca-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 \u201c\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e2a\u0e2d\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e41\u0e2a\u0e07\u201d \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23?<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >\u0e19\u0e34\u0e22\u0e32\u0e21\u0e43\u0e19\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e2a\u0e2d\u0e14\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e25\u0e14\u0e25\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e02\u0e32\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e02\u0e32\u0e2d\u0e2d\u0e01\u0e02\u0e2d\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e25\u0e34\u0e07\u0e01\u0e4c \u0e21\u0e31\u0e19\u0e08\u0e30\u0e16\u0e39\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e43\u0e19\u0e2b\u0e19\u0e48\u0e27\u0e22 <strong>\u0e40\u0e14\u0e0b\u0e34\u0e40\u0e1a\u0e25 (dB)<\/strong>. \u0e04\u0e48\u0e32 IL \u0e17\u0e35\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07\u0e41\u0e2a\u0e07\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e08\u0e30\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e15\u0e31\u0e27\u0e23\u0e31\u0e1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e04\u0e13\u0e34\u0e15\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"320\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/222f8c7683aa4833bd4b9e10f9448198.webp\" alt=\"Optical Transceiver Insertion Loss\" class=\"wp-image-5277\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/222f8c7683aa4833bd4b9e10f9448198.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/222f8c7683aa4833bd4b9e10f9448198-300x80.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/222f8c7683aa4833bd4b9e10f9448198-1024x273.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/222f8c7683aa4833bd4b9e10f9448198-768x205.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/222f8c7683aa4833bd4b9e10f9448198-18x5.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e14\u0e22\u0e17\u0e35\u0e48:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>Pin<\/strong> = \u0e01\u0e33\u0e25\u0e31\u0e07\u0e41\u0e2a\u0e07\u0e02\u0e32\u0e40\u0e02\u0e49\u0e32<\/p><\/li><li><p><strong>Pout<\/strong> = \u0e01\u0e33\u0e25\u0e31\u0e07\u0e41\u0e2a\u0e07\u0e02\u0e32\u0e2d\u0e2d\u0e01<\/p><\/li>\n<\/ul>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e1b\u0e49\u0e2d\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13 \u20132 dBm \u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e43\u0e19\u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13 \u20132.5 dBm \u0e17\u0e35\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e2a\u0e2d\u0e14\u0e08\u0e30\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e1a 0.5 dB.<\/p><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\" >\u0e40\u0e2b\u0e15\u0e38\u0e43\u0e14 IL \u0e08\u0e36\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e15\u0e31\u0e27\u0e23\u0e31\u0e1a\u0e41\u0e2a\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e01\u0e33\u0e25\u0e31\u0e07\u0e02\u0e32\u0e40\u0e02\u0e49\u0e32\u0e02\u0e31\u0e49\u0e19\u0e15\u0e48\u0e33\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e2a\u0e2d\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e19\u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e08\u0e30\u0e25\u0e14\u0e23\u0e30\u0e22\u0e30\u0e40\u0e1c\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e08\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e15\u0e31\u0e27\u0e23\u0e31\u0e1a\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32\u0e04\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e1a\u0e34\u0e15 (BER) <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/th\/glossary\/understanding-what-is-bit-error-rate\/\">\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19<\/a> \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e21\u0e49\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 \u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e2a\u0e2d\u0e14<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e2a\u0e2d\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e35\u0e01\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49 \u0e41\u0e15\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e14\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d<\/strong> \u2014 \u0e0a\u0e48\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e07\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e41\u0e19\u0e27\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e2a\u0e01\u0e1b\u0e23\u0e01\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e15\u0e31\u0e27\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e2a\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e08\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22.<\/p><\/li><li><p><strong>\u0e01\u0e32\u0e23\u0e14\u0e39\u0e14\u0e01\u0e25\u0e37\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22<\/strong> \u2014 \u0e41\u0e21\u0e49\u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e42\u0e2b\u0e21\u0e14\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e01\u0e47\u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e25\u0e14\u0e17\u0e2d\u0e19\u0e15\u0e32\u0e21\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 (\u0e40\u0e0a\u0e48\u0e19 ~0.35 dB\/km \u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e04\u0e25\u0e37\u0e48\u0e19 1310 \u0e19\u0e32\u0e42\u0e19\u0e40\u0e21\u0e15\u0e23, ~0.2 dB\/km \u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e04\u0e25\u0e37\u0e48\u0e19 1550 \u0e19\u0e32\u0e42\u0e19\u0e40\u0e21\u0e15\u0e23).<\/p><\/li><li><p><strong>\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d<\/strong> \u2014 \u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e41\u0e1a\u0e1a\u0e01\u0e25\u0e44\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1a\u0e1a\u0e1f\u0e34\u0e27\u0e0a\u0e31\u0e19\u0e21\u0e31\u0e01\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22 0.05\u20130.3 dB.<\/p><\/li><li><p><strong>\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e08\u0e32\u0e01\u0e41\u0e23\u0e07\u0e42\u0e04\u0e49\u0e07<\/strong> \u2014 \u0e01\u0e32\u0e23\u0e42\u0e04\u0e49\u0e07\u0e17\u0e35\u0e48\u0e04\u0e21\u0e0a\u0e31\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e42\u0e04\u0e49\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e08\u0e38\u0e25\u0e20\u0e32\u0e04\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e23\u0e31\u0e48\u0e27\u0e44\u0e2b\u0e25.<\/p><\/li><li><p><strong>\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e42\u0e21\u0e14\u0e39\u0e25<\/strong> \u2014 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/475859.htm\">\u0e15\u0e31\u0e27\u0e41\u0e1b\u0e25\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e2d\u0e2d\u0e1b\u0e15\u0e34\u0e01<\/a> \u0e21\u0e35\u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e0b\u0e43\u0e19\u0e15\u0e31\u0e27\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e48\u0e32 IL \u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e2a\u0e2d\u0e14<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >OLTS (Optical Loss Test Set)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01 (IL) \u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 OLTS: \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e41\u0e2a\u0e07\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e44\u0e27\u0e49\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e25\u0e34\u0e07\u0e01\u0e4c \u0e41\u0e25\u0e30\u0e21\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e27\u0e31\u0e14\u0e01\u0e33\u0e25\u0e31\u0e07\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 <strong>\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48 1<\/strong> \u0e14\u0e49\u0e32\u0e19\u0e43\u0e22\u0e41\u0e01\u0e49\u0e27\u0e19\u0e33\u0e41\u0e2a\u0e07.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19:<\/p>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p>\u0e15\u0e48\u0e2d\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e41\u0e2a\u0e07\u0e41\u0e25\u0e30\u0e21\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e32\u0e22\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e17\u0e35\u0e48\u0e17\u0e23\u0e32\u0e1a\u0e04\u0e48\u0e32.<\/p><\/li><li><p>\u0e27\u0e31\u0e14\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07 (Pin).<\/p><\/li><li><p>\u0e15\u0e48\u0e2d\u0e25\u0e34\u0e07\u0e01\u0e4c\u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a.<\/p><\/li><li><p>\u0e27\u0e31\u0e14\u0e01\u0e33\u0e25\u0e31\u0e07\u0e02\u0e32\u0e2d\u0e2d\u0e01 (Pout).<\/p><\/li><li><p>\u0e04\u0e33\u0e19\u0e27\u0e13 IL = 10\u00b7log<sub>10<\/sub>(Pin\/Pout).<\/p><\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\" >OTDR (\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e41\u0e1a\u0e1a\u0e40\u0e27\u0e25\u0e32\u0e41\u0e2a\u0e07)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">OTDR \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e04\u0e48\u0e32 IL \u0e44\u0e14\u0e49\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e41\u0e15\u0e48\u0e42\u0e14\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e43\u0e0a\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2b\u0e32\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e1a\u0e01\u0e1e\u0e23\u0e48\u0e2d\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49 OLTS.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e20\u0e32\u0e04\u0e2a\u0e19\u0e32\u0e21<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e02\u0e31\u0e49\u0e27\u0e15\u0e48\u0e2d\u0e40\u0e2a\u0e21\u0e2d\u0e01\u0e48\u0e2d\u0e19\u0e17\u0e33\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a \u2014 \u0e21\u0e25\u0e20\u0e32\u0e27\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e40\u0e01\u0e34\u0e19\u0e04\u0e48\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49.<\/p><\/li><li><p>\u0e17\u0e33\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07 (A\u2192B \u0e41\u0e25\u0e30 B\u2192A) \u0e41\u0e25\u0e49\u0e27\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c.<\/p><\/li><li><p>\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e22\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e48\u0e32 IL \u0e15\u0e48\u0e33\u0e41\u0e25\u0e30\u0e17\u0e23\u0e32\u0e1a\u0e04\u0e48\u0e32\u0e41\u0e19\u0e48\u0e0a\u0e31\u0e14.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 \u0e04\u0e48\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e42\u0e14\u0e22\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e04\u0e48\u0e32 IL \u0e42\u0e14\u0e22\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e25\u0e34\u0e07\u0e01\u0e4c:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>\u0e02\u0e31\u0e49\u0e27\u0e15\u0e48\u0e2d\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27:<\/strong> 1\u20130.5 dB (\u0e02\u0e31\u0e14\u0e40\u0e07\u0e32\u0e14\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e30\u0e2d\u0e32\u0e14).<\/p><\/li><li><p><strong>\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e41\u0e1a\u0e1a\u0e01\u0e25\u0e44\u0e01:<\/strong> 2\u20130.5 dB.<\/p><\/li><li><p><strong>\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e41\u0e1a\u0e1a\u0e1f\u0e34\u0e27\u0e0a\u0e31\u0e19:<\/strong> 05\u20130.1 dB.<\/p><\/li><li><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/482604.htm\"><strong>\u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27<\/strong><\/a><strong> \u0e01\u0e32\u0e23\u0e25\u0e14\u0e17\u0e2d\u0e19:<\/strong> 35 dB\/km \u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e04\u0e25\u0e37\u0e48\u0e19 1310 \u0e19\u0e32\u0e42\u0e19\u0e40\u0e21\u0e15\u0e23, 0.2 dB\/km \u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e04\u0e25\u0e37\u0e48\u0e19 1550 \u0e19\u0e32\u0e42\u0e19\u0e40\u0e21\u0e15\u0e23.<\/p><\/li><li><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/488477.htm\"><strong>\u0e43\u0e22\u0e41\u0e01\u0e49\u0e27\u0e19\u0e33\u0e41\u0e2a\u0e07\u0e41\u0e1a\u0e1a multimode<\/strong><\/a><strong> \u0e01\u0e32\u0e23\u0e25\u0e14\u0e17\u0e2d\u0e19:<\/strong> 0 dB\/km \u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e04\u0e25\u0e37\u0e48\u0e19 850 \u0e19\u0e32\u0e42\u0e19\u0e40\u0e21\u0e15\u0e23, 1.0 dB\/km \u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e04\u0e25\u0e37\u0e48\u0e19 1300 \u0e19\u0e32\u0e42\u0e19\u0e40\u0e21\u0e15\u0e23.<\/p><\/li>\n<\/ul>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19 \u0e25\u0e34\u0e07\u0e01\u0e4c\u0e41\u0e1a\u0e1a single-mode \u0e22\u0e32\u0e27 10 \u0e01\u0e21. \u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e04\u0e25\u0e37\u0e48\u0e19 1550 \u0e19\u0e32\u0e42\u0e19\u0e40\u0e21\u0e15\u0e23 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e31\u0e49\u0e27\u0e15\u0e48\u0e2d\u0e2a\u0e2d\u0e07\u0e08\u0e38\u0e14\u0e41\u0e25\u0e30\u0e23\u0e2d\u0e22\u0e15\u0e48\u0e2d\u0e2a\u0e2d\u0e07\u0e08\u0e38\u0e14 \u0e2d\u0e32\u0e08\u0e21\u0e35\u0e04\u0e48\u0e32 IL \u0e23\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 0.2 \u00d7 10 + 0.3 + 0.1 = 2.4 dB.<\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 \u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e33\u0e19\u0e27\u0e13\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e25\u0e34\u0e07\u0e01\u0e4c<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e25\u0e34\u0e07\u0e01\u0e4c\u0e04\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e15\u0e48\u0e32\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e02\u0e32\u0e2d\u0e2d\u0e01\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13 \u0e42\u0e14\u0e22\u0e1b\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e41\u0e25\u0e30\u0e04\u0e48\u0e32\u0e40\u0e1c\u0e37\u0e48\u0e2d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>\u0e01\u0e33\u0e25\u0e31\u0e07\u0e15\u0e31\u0e27\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13 (Tx): 0 dBm<\/p><\/li><li><p>\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e15\u0e31\u0e27\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13 (Rx): \u201314 dBm<\/p><\/li><li><p>\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e17\u0e35\u0e48\u0e21\u0e35 = 14 dB<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2b\u0e32\u0e01 IL = 10 dB \u0e04\u0e48\u0e32\u0e40\u0e1c\u0e37\u0e48\u0e2d = 4 dB \u2192 <strong>\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49<\/strong>.<br\/>\u0e2b\u0e32\u0e01 IL = 15 dB \u0e04\u0e48\u0e32\u0e40\u0e1c\u0e37\u0e48\u0e2d = \u20131 dB \u2192 <strong>\u0e25\u0e34\u0e07\u0e01\u0e4c\u0e25\u0e49\u0e21\u0e40\u0e2b\u0e25\u0e27<\/strong>.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u0e2a\u0e34\u0e48\u0e07\u0e19\u0e35\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e41\u0e21\u0e49\u0e41\u0e15\u0e48\u0e40\u0e28\u0e29\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07 dB \u0e01\u0e47\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d.<\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 \u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e17\u0e23\u0e32\u0e19\u0e0b\u0e35\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e41\u0e2a\u0e07<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\">\u0e42\u0e21\u0e14\u0e39\u0e25\u0e41\u0e2a\u0e07\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07<\/a> \u0e15\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e43\u0e19\u0e2a\u0e32\u0e21\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e01:<\/p>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p><strong>\u0e04\u0e48\u0e32\u0e40\u0e1c\u0e37\u0e48\u0e2d\u0e25\u0e14\u0e25\u0e07:<\/strong> IL \u0e2a\u0e39\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e48\u0e32\u0e40\u0e1c\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e25\u0e14\u0e25\u0e07 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e25\u0e34\u0e07\u0e01\u0e4c\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e23\u0e32\u0e30\u0e1a\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e2a\u0e20\u0e32\u0e1e\u0e15\u0e32\u0e21\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34.<\/p><\/li><li><p><strong>\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e1a\u0e34\u0e15 (BER) \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19:<\/strong> \u0e2d\u0e31\u0e15\u0e23\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e23\u0e1a\u0e01\u0e27\u0e19 (SNR) \u0e17\u0e35\u0e48\u0e15\u0e31\u0e27\u0e23\u0e31\u0e1a\u0e25\u0e14\u0e25\u0e07 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e1a\u0e34\u0e15\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19.<\/p><\/li><li><p><strong>\u0e23\u0e30\u0e22\u0e30\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e25\u0e14\u0e25\u0e07:<\/strong> \u0e42\u0e21\u0e14\u0e39\u0e25\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e27\u0e48\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e44\u0e14\u0e49\u0e44\u0e01\u0e25\u0e16\u0e36\u0e07 40 \u0e01\u0e21. \u0e2d\u0e32\u0e08\u0e2a\u0e48\u0e07\u0e44\u0e14\u0e49\u0e44\u0e01\u0e25\u0e40\u0e1e\u0e35\u0e22\u0e07 30 \u0e01\u0e21. \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e2b\u0e32\u0e01\u0e04\u0e48\u0e32 IL \u0e40\u0e01\u0e34\u0e19\u0e2a\u0e21\u0e21\u0e38\u0e15\u0e34\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49.<\/p><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/482907.htm\"><strong>LS-CW3110-40I \u0e02\u0e2d\u0e07 LINK-PP<\/strong><\/a><strong> \u0e15\u0e31\u0e27\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e41\u0e2a\u0e07<\/strong> \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e23\u0e30\u0e22\u0e30 40 \u0e01\u0e21. \u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27 10G \u0e2b\u0e32\u0e01\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e41\u0e0b\u0e07 (IL) \u0e40\u0e01\u0e34\u0e19\u0e04\u0e48\u0e32\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 (\u0e40\u0e0a\u0e48\u0e19 \u0e2b\u0e31\u0e27\u0e15\u0e48\u0e2d\u0e2a\u0e01\u0e1b\u0e23\u0e01 \u0e23\u0e2d\u0e22\u0e15\u0e48\u0e2d\u0e44\u0e21\u0e48\u0e14\u0e35) \u0e23\u0e30\u0e22\u0e30\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e08\u0e23\u0e34\u0e07\u0e08\u0e30\u0e25\u0e14\u0e25\u0e07 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e04\u0e48\u0e32 IL \u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e33\u0e40\u0e1e\u0e32\u0e30\u0e43\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 \u0e27\u0e34\u0e18\u0e35\u0e25\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e41\u0e0b\u0e07\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2b\u0e31\u0e27\u0e15\u0e48\u0e2d<\/strong> \u0e01\u0e48\u0e2d\u0e19\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e04\u0e23\u0e31\u0e49\u0e07\u0e14\u0e49\u0e27\u0e22\u0e1c\u0e49\u0e32\u0e44\u0e21\u0e48\u0e21\u0e35\u0e02\u0e19\u0e41\u0e25\u0e30\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e44\u0e2d\u0e42\u0e0b\u0e42\u0e1e\u0e23\u0e1e\u0e34\u0e25.<\/p><\/li><li><p><strong>\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e1c\u0e34\u0e27\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e25\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22<\/strong> \u0e14\u0e49\u0e27\u0e22\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e2a\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e41\u0e2a\u0e07.<\/p><\/li><li><p><strong>\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e41\u0e1a\u0e1a\u0e1f\u0e34\u0e27\u0e0a\u0e31\u0e19<\/strong> \u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e41\u0e1a\u0e1a\u0e01\u0e25\u0e44\u0e01\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49.<\/p><\/li><li><p><strong>\u0e2b\u0e25\u0e35\u0e01\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e01\u0e32\u0e23\u0e42\u0e04\u0e49\u0e07\u0e07\u0e2d\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e09\u0e35\u0e22\u0e1a\u0e04\u0e21<\/strong> \u2014 \u0e43\u0e2b\u0e49\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e04\u0e48\u0e32\u0e23\u0e31\u0e28\u0e21\u0e35\u0e01\u0e32\u0e23\u0e42\u0e04\u0e49\u0e07\u0e07\u0e2d\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e41\u0e2a\u0e07.<\/p><\/li><li><p><strong>\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07<\/strong> \u2014 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\">\u0e42\u0e21\u0e14\u0e39\u0e25<\/a>, <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-21644-fiber-optic-cages-connectors.htm\">\u0e02\u0e31\u0e49\u0e27\u0e15\u0e48\u0e2d<\/a>, \u0e41\u0e25\u0e30 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-26454-dac-aoc-aec-cables.htm\">\u0e2a\u0e32\u0e22\u0e41\u0e1e\u0e15\u0e0a\u0e4c<\/a> \u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e04\u0e48\u0e32 IL \u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e44\u0e27\u0e49.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 \u0e08\u0e38\u0e14\u0e17\u0e35\u0e48 LINK-PP \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d9cc5ec3f48c48f3b5b28dfe28abb572.webp\" alt=\"LINK-PP Solutions\" class=\"wp-image-5278\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d9cc5ec3f48c48f3b5b28dfe28abb572.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d9cc5ec3f48c48f3b5b28dfe28abb572-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d9cc5ec3f48c48f3b5b28dfe28abb572-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d9cc5ec3f48c48f3b5b28dfe28abb572-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d9cc5ec3f48c48f3b5b28dfe28abb572-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27 1G\u2013800G LINK-PP \u0e08\u0e30\u0e43\u0e2b\u0e49\u0e42\u0e21\u0e14\u0e39\u0e25\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49 \u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e32\u0e1a\u0e23\u0e37\u0e48\u0e19:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>\u0e17\u0e23\u0e32\u0e19\u0e0b\u0e35\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e2d\u0e2d\u0e1b\u0e15\u0e34\u0e04\u0e31\u0e25: \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 SFP\/SFP+, SFP28, QSFP28, QSFP-DD \u0e41\u0e25\u0e30 OSFP \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 IEEE Ethernet optics \u0e14\u0e39\u0e20\u0e32\u0e1e\u0e23\u0e27\u0e21\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25\u0e17\u0e35\u0e48\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e42\u0e21\u0e14\u0e39\u0e25\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/resourceslp.szlogic.cn\/th\/knowledge-center\/why-choose-link-pp-fiber-optical-modules\/\">\u0e40\u0e2b\u0e15\u0e38\u0e43\u0e14\u0e08\u0e36\u0e07\u0e04\u0e27\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e21\u0e14\u0e39\u0e25\u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e2d\u0e2d\u0e1b\u0e15\u0e34\u0e04\u0e31\u0e25 LINK-PP<\/a>.<\/p><\/li><li><p>\u0e15\u0e31\u0e27\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e41\u0e25\u0e30\u0e0a\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a: \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e41\u0e1a\u0e1a LC \u0e41\u0e1a\u0e1a\u0e04\u0e39\u0e48 \u0e41\u0e25\u0e30 MPO\/MTP \u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d \u0e42\u0e1b\u0e23\u0e14\u0e14\u0e39 <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/resourceslp.szlogic.cn\/th\/knowledge-center\/common-fiber-connector-types-optical-transceivers\/\">\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e43\u0e22\u0e41\u0e01\u0e49\u0e27\u0e19\u0e33\u0e41\u0e2a\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e42\u0e14\u0e22\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e43\u0e19\u0e15\u0e31\u0e27\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e41\u0e2a\u0e07<\/a>.<\/p><\/li><li><p>\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e17\u0e33\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22: \u0e02\u0e2d\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1f\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e04\u0e48\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01 (IL) \u0e41\u0e25\u0e30\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e02\u0e2d\u0e07\u0e25\u0e34\u0e07\u0e01\u0e4c\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u2014 \u0e14\u0e39\u0e1b\u0e38\u0e48\u0e21\u0e40\u0e23\u0e35\u0e22\u0e01\u0e23\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 (CTA) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\/\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e1a\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e2b\u0e19\u0e49\u0e32 <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.l-p.com\/store-26155-1g-sfp.htm\">\u0e41\u0e04\u0e15\u0e15\u0e32\u0e25\u0e47\u0e2d\u0e01\u0e42\u0e21\u0e14\u0e39\u0e25 SFP \u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27 1 Gbps \u0e02\u0e2d\u0e07 LINK-PP<\/a>.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 \u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22\u0e41\u0e1a\u0e1a\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48 1: \u0e04\u0e48\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01 (insertion loss) \u0e17\u0e35\u0e48\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e15\u0e48\u0e2d\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e15\u0e31\u0e27\u0e04\u0e37\u0e2d\u0e40\u0e17\u0e48\u0e32\u0e43\u0e14?<\/strong><br\/>\u0e04\u0e33\u0e15\u0e2d\u0e1a: \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e21\u0e31\u0e01\u0e08\u0e30\u0e21\u0e35\u0e04\u0e48\u0e32\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32 0.3 \u0e40\u0e14\u0e0b\u0e34\u0e40\u0e1a\u0e25.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48 2: \u0e04\u0e27\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01 (IL) \u0e1a\u0e48\u0e2d\u0e22\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19?<\/strong><br\/>\u0e04\u0e33\u0e15\u0e2d\u0e1a: \u0e04\u0e27\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e43\u0e19\u0e02\u0e13\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e23\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e38\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e34\u0e07\u0e01\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2d\u0e32\u0e08\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e0b\u0e49\u0e33\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e15\u0e32\u0e21\u0e01\u0e33\u0e2b\u0e19\u0e14.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48 3: \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e49\u0e27\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48?<\/strong><br\/>\u0e04\u0e33\u0e15\u0e2d\u0e1a: \u0e42\u0e14\u0e22\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49 \u2014 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e2b\u0e21\u0e48 (re-terminating) \u0e08\u0e38\u0e14\u0e15\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e2a\u0e39\u0e07 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e14\u0e04\u0e48\u0e32 IL \u0e44\u0e14\u0e49.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 \u0e2a\u0e23\u0e38\u0e1b<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e2d\u0e32\u0e08\u0e14\u0e39\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 \u0e41\u0e15\u0e48\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e41\u0e2a\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07 \u0e17\u0e38\u0e01\u0e40\u0e28\u0e29\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e14\u0e0b\u0e34\u0e40\u0e1a\u0e25\u0e25\u0e49\u0e27\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d \u0e25\u0e49\u0e27\u0e19\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e44\u0e14\u0e49.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\"><strong>\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/strong><\/a>, \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e08\u0e23\u0e34\u0e07\u0e43\u0e19\u0e42\u0e25\u0e01\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e23\u0e34\u0e07. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01 \u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e25\u0e14\u0e04\u0e48\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e08\u0e23\u0e34\u0e07 \u0e1c\u0e39\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e25\u0e34\u0e07\u0e01\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d \u0e2a\u0e39\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e15\u0e31\u0e27\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e41\u0e2a\u0e07 (optical transceiver insertion loss) \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e33\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e02\u0e2d\u0e07\u0e25\u0e34\u0e07\u0e01\u0e4c (link budgets) \u0e2d\u0e31\u0e15\u0e23\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e1a\u0e34\u0e15 (BER) \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e25\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e49\u0e32 (FEC) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a LC\/MPO \u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e0a\u0e34\u0e07\u0e25\u0e36\u0e01\u0e08\u0e32\u0e01 LINK-PP.<\/p>","protected":false},"author":1,"featured_media":5279,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[19,21,26],"class_list":["post-5280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowledge-center","tag-aoc-dac-cables","tag-fiber-optic-cage-and-connector","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/th\/wp-json\/wp\/v2\/posts\/5280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/th\/wp-json\/wp\/v2\/comments?post=5280"}],"version-history":[{"count":4,"href":"https:\/\/resourceslp.szlogic.cn\/th\/wp-json\/wp\/v2\/posts\/5280\/revisions"}],"predecessor-version":[{"id":11203,"href":"https:\/\/resourceslp.szlogic.cn\/th\/wp-json\/wp\/v2\/posts\/5280\/revisions\/11203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/th\/wp-json\/wp\/v2\/media\/5279"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/th\/wp-json\/wp\/v2\/media?parent=5280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/th\/wp-json\/wp\/v2\/categories?post=5280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/th\/wp-json\/wp\/v2\/tags?post=5280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}