{"id":5271,"date":"2025-09-01T00:00:00","date_gmt":"2025-09-01T00:00:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/knowledge-center\/long-haul-transmission-explained-how-it-works-simply\/"},"modified":"2026-06-22T07:57:17","modified_gmt":"2026-06-22T07:57:17","slug":"long-haul-transmission-explained-how-it-works-simply","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/pt\/knowledge-center\/long-haul-transmission-explained-how-it-works-simply","title":{"rendered":"Percorrendo Dist\u00e2ncias: A Tecnologia por Tr\u00e1s da Transmiss\u00e3o \u00d3ptica de Longa Dist\u00e2ncia"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/91d09f3b5c884e2595a77623738bcb3d.webp\" alt=\"Long-Haul Transmission Explained in Simple Words\" class=\"wp-image-5268\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/91d09f3b5c884e2595a77623738bcb3d.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/91d09f3b5c884e2595a77623738bcb3d-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/91d09f3b5c884e2595a77623738bcb3d-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/91d09f3b5c884e2595a77623738bcb3d-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/91d09f3b5c884e2595a77623738bcb3d-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Vivemos em um <strong>hiperconectado<\/strong> mundo onde uma chamada de v\u00eddeo com algu\u00e9m a 10.000 milhas de dist\u00e2ncia parece perfeita. Por tr\u00e1s desse milagre moderno est\u00e1 o imenso poder da <strong>transmiss\u00e3o \u00f3ptica de longa dist\u00e2ncia<\/strong>, a espinha dorsal silenciosa da internet global. Mas como a luz viaja atrav\u00e9s de oceanos e continentes com degrada\u00e7\u00e3o m\u00ednima do sinal?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este artigo explora as maravilhas de engenharia que tornam poss\u00edvel a transmiss\u00e3o de dados ultra-longa dist\u00e2ncia, os desafios superados e o papel cr\u00edtico dos componentes \u00f3pticos avan\u00e7ados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd O Everest dos Dados: Principais Desafios na Transmiss\u00e3o de Longa Dist\u00e2ncia<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Enviar dados por centenas ou milhares de quil\u00f4metros n\u00e3o \u00e9 simples. Os principais inimigos de um sinal \u00f3ptico limpo s\u00e3o:<\/p>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p style=\"margin: 0px;\"><strong>Atenua\u00e7\u00e3o:<\/strong> A perda gradual da intensidade do sinal luminoso \u00e0 medida que ele viaja pela fibra. \u00c9 a barreira principal para viagens de longa dist\u00e2ncia.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Dispers\u00e3o:<\/strong> O \u201cespalhamento\u201d ou alargamento de um pulso de luz durante sua propaga\u00e7\u00e3o. Esse borr\u00e3o nos pulsos dificulta sua distin\u00e7\u00e3o na extremidade receptora, causando erros.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Efeitos N\u00e3o Lineares:<\/strong> Em n\u00edveis de pot\u00eancia muito altos, o pr\u00f3prio sinal luminoso pode alterar as propriedades da fibra, gerando distor\u00e7\u00f5es complexas e interfer\u00eancia entre canais.<\/p><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Superar esses desafios exige uma combina\u00e7\u00e3o de f\u00edsica brilhante e hardware de ponta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd O Arsenal da Tecnologia de Longa Dist\u00e2ncia: DWDM, Amplificadores e Mais<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para combater a atenua\u00e7\u00e3o e maximizar a capacidade de uma \u00fanica fibra, os engenheiros utilizam uma combina\u00e7\u00e3o poderosa de tecnologias:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Multiplexa\u00e7\u00e3o Densa por Divis\u00e3o de Comprimento de Onda <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/glossary\/what-is-dwdm-explaining-dense-wavelength-division-multiplexing\/\"><strong>(DWDM)<\/strong><\/a><strong>:<\/strong> Essa \u00e9 a estrela m\u00e1xima em capacidade. A tecnologia DWDM permite que m\u00faltiplos <strong>sinais portadores \u00f3pticos<\/strong> (cada um em um comprimento de onda\/diferente cor de laser) sejam transmitidos simultaneamente na mesma fibra. Imagine transformar uma estrada de pista \u00fanica em uma gigantesca autoestrada com m\u00faltiplas faixas.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Amplificadores \u00d3pticos:<\/strong> Em vez de converter o sinal \u00f3ptico novamente em el\u00e9trico para amplific\u00e1-lo (o que \u00e9 lento e caro em cadeias longas), <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/glossary\/erbium-doped-fiber-amplifier-optical-networks\/\"><strong>Amplificadores \u00d3pticos de Fibra Dopada com \u00c9rbio (EDFAs)<\/strong><\/a> s\u00e3o utilizados. Eles amplificam diretamente o sinal luminoso em sua forma \u00f3ptica, fornecendo um impulso crucial de pot\u00eancia a cada 80\u2013100 km.<\/p><\/li><li><p style=\"margin: 0px;\"><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/what-is-optical-modulation-and-how-it-works-explained\/\"><strong>Formatos avan\u00e7ados de modula\u00e7\u00e3o<\/strong><\/a><strong>:<\/strong> T\u00e9cnicas como <strong>DP-QPSK (Modula\u00e7\u00e3o por Deslocamento de Fase Quadr\u00e1tica com Dupla Polariza\u00e7\u00e3o)<\/strong> and <strong>\u00f3ptica coerente<\/strong> empacotam mais dados em cada pulso de luz, tornando a transmiss\u00e3o mais eficiente e resistente ao ru\u00eddo e \u00e0 dispers\u00e3o.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd O Her\u00f3i An\u00f4nimo: O Transceptor \u00d3ptico Adequado para Longa Dist\u00e2ncia<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/efa40824d05245eeaf088716b73413ce.webp\" alt=\"optical transceivers\" class=\"wp-image-5269\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/efa40824d05245eeaf088716b73413ce.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/efa40824d05245eeaf088716b73413ce-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/efa40824d05245eeaf088716b73413ce-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/efa40824d05245eeaf088716b73413ce-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/efa40824d05245eeaf088716b73413ce-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">No cora\u00e7\u00e3o de cada liga\u00e7\u00e3o de longa dist\u00e2ncia est\u00e3o os <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\"><strong>transceptores \u00f3pticos<\/strong><\/a>. N\u00e3o basta qualquer transceptor. \u00c9 necess\u00e1rio um <strong>\u00f3pticos de longa dist\u00e2ncia<\/strong> especificamente projetado, capaz de alta pot\u00eancia de sa\u00edda, sensibilidade superior e suporte a modula\u00e7\u00e3o avan\u00e7ada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqui, desempenho e confiabilidade s\u00e3o imprescind\u00edveis. Marcas como <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\"><strong>LINK-PP<\/strong><\/a> especializam-se na fabrica\u00e7\u00e3o de transceptores \u00f3pticos robustos e de alto desempenho, projetados para essas aplica\u00e7\u00f5es exigentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por exemplo, o <strong>M\u00f3dulo coerente 400G-ZR+ QSFP-DD<\/strong> \u00e9 um divisor de \u00e1guas para <strong>interconex\u00f5es de data centers de longa dist\u00e2ncia <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/knowledge-center\/data-center-interconnect-definition-benefits-and-role-of-optical-modules\/\"><strong>(DCI)<\/strong><\/a>. Ele suporta transmiss\u00e3o at\u00e9 800 km usando tecnologia coerente e foi projetado para <strong>sistemas de linha DWDM de alta densidade<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outra excelente op\u00e7\u00e3o para redes legadas e modernas \u00e9 o <strong>LINK-PP <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/482513.htm\"><strong>LQ-LW100-ZR4C<\/strong><\/a>. Este <strong>transceptor coerente 100G ZR4<\/strong> \u00e9 um trabalho confi\u00e1vel para alcan\u00e7ar taxas de 100G em dist\u00e2ncias al\u00e9m de 80 km, ideal para redes de \u00e1rea metropolitana <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/knowledge-center\/what-is-a-metropolitan-area-network\/\"><strong>(MANs)<\/strong><\/a> e liga\u00e7\u00f5es regionais, oferecendo um excelente equil\u00edbrio entre desempenho e custo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao selecionar um m\u00f3dulo, as especifica\u00e7\u00f5es-chave a considerar incluem <strong>pot\u00eancia de sa\u00edda do transmissor, sensibilidade do receptor e toler\u00e2ncia \u00e0 dispers\u00e3o<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Compara\u00e7\u00e3o das Solu\u00e7\u00f5es Comuns de Transmiss\u00e3o de Longa Dist\u00e2ncia<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A tabela a seguir detalha as tecnologias comuns usadas para atingir diferentes objetivos de dist\u00e2ncia:<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p><strong>Tecnologia<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>Dist\u00e2ncia t\u00edpica<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>Principais caracter\u00edsticas<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>Melhor Para<\/strong><\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>\u00d3pticos 100GBASE-LR4 \/ ER4<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>10 km \/ 40 km<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Utiliza 4 <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/glossary\/what-is-lwdm-and-why-important-for-lans\/\"><strong>LAN WDM<\/strong><\/a> comprimentos de onda, popular para <strong>interconex\u00f5es de data centers de alta velocidade<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Redes Metropolitanas e Regionais<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Coerente 100G ZR\/ZR+<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>80 km \u2013 800 km<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Tecnologia coerente, integrada <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/glossary\/digital-signal-processor-functionality-in-optical-transceivers\/\"><strong>DSP<\/strong><\/a>, alta toler\u00e2ncia \u00e0 dispers\u00e3o<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Transmiss\u00e3o de Longa Dist\u00e2ncia e Interconex\u00e3o de Data Centers (DCI)<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>DWDM + EDFA<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>100 km \u2013 1000 km<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Amplifica m\u00faltiplos comprimentos de onda simultaneamente, com capacidade imensa<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Cabos Transoce\u00e2nicos, Redes Nucleares<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd O Futuro da Transmiss\u00e3o de Longa Dist\u00e2ncia<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A busca por mais capacidade e alcances ainda maiores nunca cessa. O futuro reside em:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Maior Integra\u00e7\u00e3o:<\/strong> \u00d3pticos coerentes plug\u00e1veis (como os padr\u00f5es 400ZR+ e 800ZR) est\u00e3o trazendo o desempenho de cabos submarinos para os data centers.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Multiplexa\u00e7\u00e3o por Divis\u00e3o Espacial (SDM):<\/strong> Uso de fibras com m\u00faltiplos n\u00facleos para criar, efetivamente, \u201cmais fibras\u201d dentro de um \u00fanico cabo.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Projetos Avan\u00e7ados de Fibra:<\/strong> Novos tipos de fibra com atenua\u00e7\u00e3o reduzida e maior resist\u00eancia a efeitos n\u00e3o lineares.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Conclus\u00e3o: Conectando o Mundo, Um Pulso de Luz de Cada Vez<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A transmiss\u00e3o \u00f3ptica de longa dist\u00e2ncia \u00e9 um campo fascinante onde f\u00edsica, engenharia e inova\u00e7\u00e3o convergem para alimentar nossas vidas digitais. Ao aproveitar tecnologias como DWDM, amplifica\u00e7\u00e3o \u00f3ptica e <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/knowledge-center\/coherent-transceivers-high-speed-data-transmission-explained\/\"><strong>transceptores \u00f3pticos coerentes de alto desempenho<\/strong><\/a> from industry leaders like <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/page\/aboutus.htm\"><strong>LINK-PP<\/strong><\/a>, continuamos a expandir os limites de velocidade e dist\u00e2ncia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pronto para projetar ou atualizar sua infraestrutura de rede de longa dist\u00e2ncia?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Garanta o sucesso do seu projeto com componentes confi\u00e1veis e de alto desempenho. <strong>Explore o portf\u00f3lio completo da LINK-PP de transceptores \u00f3pticos de longa dist\u00e2ncia<\/strong> para encontrar a solu\u00e7\u00e3o perfeita para seus requisitos espec\u00edficos de alcance e capacidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/support.htm\"><strong>Entre em contato com nossos especialistas hoje para uma consulta \u279e<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Perguntas frequentes (FAQ)<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >Qual \u00e9 a principal fun\u00e7\u00e3o da transmiss\u00e3o de longa dist\u00e2ncia?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A transmiss\u00e3o de longa dist\u00e2ncia transporta seus dados por dist\u00e2ncias muito grandes. Ela conecta cidades, pa\u00edses e at\u00e9 continentes. Voc\u00ea a utiliza todos os dias para navegar na internet, fazer chamadas telef\u00f4nicas e transmitir v\u00eddeos em fluxo cont\u00ednuo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Como os cabos de fibra \u00f3ptica enviam dados t\u00e3o rapidamente?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os cabos de fibra \u00f3ptica usam luz para transportar seus dados. A luz viaja muito rapidamente atrav\u00e9s dos filamentos de vidro no interior do cabo. Isso permite que voc\u00ea envie informa\u00e7\u00f5es para longe em apenas alguns segundos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Por que os sinais precisam de amplificadores e repetidores?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os sinais podem enfraquecer \u00e0 medida que viajam. Os amplificadores aumentam a intensidade do sinal. Os repetidores captam o sinal e o retransmitem adiante. Voc\u00ea obt\u00e9m dados claros e fortes, mesmo em longas dist\u00e2ncias.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >A transmiss\u00e3o de longa dist\u00e2ncia pode funcionar debaixo d\u2019\u00e1gua?<\/h3>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Sim! Cabos especiais de fibra \u00f3ptica percorrem o fundo do mar. Esses cabos conectam continentes. Voc\u00ea pode ligar ou enviar mensagens para pessoas em outros pa\u00edses gra\u00e7as a esses cabos submarinos.<\/p><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\" >A transmiss\u00e3o de longa dist\u00e2ncia \u00e9 importante para jogos online?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Absolutamente! As redes de longa dist\u00e2ncia mant\u00eam sua conex\u00e3o r\u00e1pida e est\u00e1vel. Voc\u00ea joga com amigos em outras cidades ou pa\u00edses sem atraso (lag). Isso torna sua experi\u00eancia de jogo suave e divertida.<\/p>","protected":false},"excerpt":{"rendered":"<p>A transmiss\u00e3o de longa dist\u00e2ncia utiliza cabos de fibra \u00f3ptica para enviar dados de forma r\u00e1pida e segura por grandes dist\u00e2ncias, conectando cidades e pa\u00edses para comunica\u00e7\u00e3o \u00e1gil.<\/p>","protected":false},"author":1,"featured_media":5270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[26],"class_list":["post-5271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowledge-center","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts\/5271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/comments?post=5271"}],"version-history":[{"count":4,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts\/5271\/revisions"}],"predecessor-version":[{"id":11201,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts\/5271\/revisions\/11201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/media\/5270"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/media?parent=5271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/categories?post=5271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/tags?post=5271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}