{"id":4783,"date":"2025-09-30T11:12:00","date_gmt":"2025-09-30T11:12:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/knowledge-center\/ieee-802-3at-power-over-ethernet-plus-standard\/"},"modified":"2026-06-22T09:03:33","modified_gmt":"2026-06-22T09:03:33","slug":"ieee-802-3at-power-over-ethernet-plus-standard","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/pt\/knowledge-center\/ieee-802-3at-power-over-ethernet-plus-standard","title":{"rendered":"Padr\u00e3o IEEE 802.3at (PoE+) Explicado: Pot\u00eancia, Aplica\u00e7\u00f5es e Benef\u00edcios"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/8cacf2fc454c422c8e974065ed88f18e.webp\" alt=\"What is IEEE 802.3at (PoE+)?\" class=\"wp-image-4780\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/8cacf2fc454c422c8e974065ed88f18e.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/8cacf2fc454c422c8e974065ed88f18e-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/8cacf2fc454c422c8e974065ed88f18e-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/8cacf2fc454c422c8e974065ed88f18e-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/8cacf2fc454c422c8e974065ed88f18e-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >\u27a1\ufe0f Introdu\u00e7\u00e3o: O que \u00e9 o IEEE 802.3at (PoE+)?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">The <strong>Padr\u00e3o IEEE 802.3at<\/strong>, amplamente conhecido como <strong>PoE+<\/strong>, \u00e9 a segunda gera\u00e7\u00e3o da tecnologia <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/glossary\/what-you-need-to-know-about-power-over-ethernet\/\">Alimenta\u00e7\u00e3o sobre Ethernet (PoE)<\/a> Ratificado em 2009, ele se baseia no padr\u00e3o original <strong>IEEE 802.3af PoE<\/strong>, quase dobrando a pot\u00eancia dispon\u00edvel. Com o PoE+, um \u00fanico cabo Ethernet pode fornecer tanto <strong>dados de alta velocidade quanto at\u00e9 30 watts de pot\u00eancia el\u00e9trica<\/strong>, permitindo a implanta\u00e7\u00e3o de dispositivos de rede mais exigentes em termos de energia, sem fontes de alimenta\u00e7\u00e3o ou adaptadores adicionais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\u27a1\ufe0f Entrega de energia: do PoE ao PoE+<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A principal vantagem do IEEE 802.3at reside em sua capacidade aumentada de fornecimento de energia:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>IEEE 802.3af (PoE):<\/strong><\/p><ul><li><p>Pot\u00eancia m\u00e1xima no PSE (Equipamento Fonte de Alimenta\u00e7\u00e3o): <strong>15,4 W<\/strong><\/p><\/li><li><p>Pot\u00eancia dispon\u00edvel no PD (Dispositivo Alimentado): <strong>12,95 W<\/strong><\/p><\/li><\/ul><\/li><li><p><strong>IEEE 802.3at (PoE+):<\/strong><\/p><ul><li><p>Pot\u00eancia m\u00e1xima no PSE: <strong>30 W<\/strong><\/p><\/li><li><p>Pot\u00eancia dispon\u00edvel no PD: <strong>25,5 W<\/strong><\/p><\/li><\/ul><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Esse aumento significativo torna o PoE+ adequado para equipamentos baseados em IP de nova gera\u00e7\u00e3o que exigem maior pot\u00eancia. Importante destacar que o 802.3at permanece <strong>compat\u00edveis com vers\u00f5es anteriores<\/strong> compat\u00edvel com o 802.3af, garantindo integra\u00e7\u00e3o perfeita nas infraestruturas existentes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\u27a1\ufe0f Principais aplica\u00e7\u00f5es do IEEE 802.3at (PoE+)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O PoE+ amplia a gama de dispositivos alimentados al\u00e9m do que o PoE padr\u00e3o poderia suportar. Aplica\u00e7\u00f5es comuns incluem:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/knowledge-center\/poe-lan-transformers-in-ip-cameras\/\"><strong>C\u00e2meras IP<br><\/strong><\/a><strong> C\u00e2meras com PTZ (Pan-Tilt-Zoom) e ilumina\u00e7\u00e3o IR<\/strong><\/p><\/li><li><p><strong>Pontos de acesso sem fio de alto desempenho (Wi-Fi 5\/6\/6E)<\/strong><\/p><\/li><li><p><strong>Telefones VoIP com telas coloridas e recursos avan\u00e7ados<\/strong><\/p><\/li><li><p><strong>Clientes leves e pequenos <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/knowledge-center\/what-is-a-network-switch\/\"><strong>Switches de rede<\/strong><\/a><\/p><\/li><li><p><strong>Dispositivos industriais e IoT<\/strong> que exigem pot\u00eancia confi\u00e1vel de n\u00edvel intermedi\u00e1rio<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ao consolidar energia e dados em um \u00fanico cabo, o PoE+ simplifica a implanta\u00e7\u00e3o, reduz os custos com cabeamento e melhora a escalabilidade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\u27a1\ufe0f Caracter\u00edsticas t\u00e9cnicas do IEEE 802.3at<\/h2>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p><strong>Compatibilidade Reversa:<\/strong> Suporta dispositivos PoE (802.3af) e PoE+ (802.3at).<\/p><\/li><li><p><strong>Detec\u00e7\u00e3o inteligente de energia:<\/strong> O PSE identifica automaticamente se um dispositivo conectado suporta PoE antes de fornecer energia, protegendo dispositivos n\u00e3o compat\u00edveis com PoE.<\/p><\/li><li><p><strong>Cabeamento flex\u00edvel:<\/strong> Opera sobre cabos Ethernet Cat5e ou superiores.<\/p><\/li><li><p><strong>Implanta\u00e7\u00e3o midspan ou endspan:<\/strong> O PoE+ pode ser integrado a switches (endspan) ou por meio de injetores midspan.<\/p><\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" >\u27a1\ufe0f IEEE 802.3at vs IEEE 802.3bt (PoE++)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Embora o 802.3at forne\u00e7a at\u00e9 <strong>30 W<\/strong>, o mais recente <strong>IEEE 802.3bt (PoE++)<br><\/strong> padr\u00e3o leva os limites ainda mais longe, fornecendo at\u00e9 <strong>60 W (Tipo 3)<\/strong> or <strong>100 W (Tipo 4)<\/strong>. Isso torna o PoE++ ideal para dispositivos de alta pot\u00eancia, como c\u00e2meras PTZ com aquecedores, pontos de acesso sem fio com m\u00faltiplos r\u00e1dios ou at\u00e9 mesmo laptops.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para engenheiros e integradores de rede, compreender as diferen\u00e7as entre PoE+ e PoE++ garante a sele\u00e7\u00e3o dos componentes de infraestrutura corretos para escalabilidade e desempenho.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\u27a1\ufe0f Solu\u00e7\u00f5es LINK-PP para PoE+<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/183580f84621465fad9ab762573857a3.webp\" alt=\"LINK-PP Solutions for PoE+\" class=\"wp-image-4781\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/183580f84621465fad9ab762573857a3.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/183580f84621465fad9ab762573857a3-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/183580f84621465fad9ab762573857a3-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/183580f84621465fad9ab762573857a3-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/183580f84621465fad9ab762573857a3-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para aproveitar plenamente os padr\u00f5es IEEE 802.3at e IEEE 802.3bt, magn\u00e9ticos Ethernet de alta qualidade s\u00e3o essenciais para transmiss\u00e3o est\u00e1vel de dados e entrega eficiente de energia. <strong>LINK-PP<\/strong>, fornecedor l\u00edder de magn\u00e9ticos para conectividade Ethernet, oferece solu\u00e7\u00f5es robustas projetadas especificamente para redes PoE:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>\ud83d\udd39 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/466212.htm\"><strong>Conector RJ45 com magn\u00e9ticos PoE+<\/strong><\/a>: Projetado para conformidade com o IEEE 802.3at, suportando entrega de at\u00e9 30 W de pot\u00eancia com excelente desempenho contra EMI.<\/p><\/li><li><p>\ud83d\udd39 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/452775.htm\"><strong>M\u00f3dulos transformadores magn\u00e9ticos PoE+<\/strong><\/a>: M\u00f3dulos transformadores de porta \u00fanica LP41223NL 10\/100 Base-T projetados para aplica\u00e7\u00e3o PoE+ IEEE 802.3at.<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Esses componentes garantem <strong>implanta\u00e7\u00e3o segura, eficiente e de alto desempenho de PoE<\/strong> em ambientes corporativos, industriais e IoT.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >Conclus\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">The <strong>Padr\u00e3o IEEE 802.3at (PoE+)<\/strong> tornou-se um pilar das redes modernas, permitindo implanta\u00e7\u00e3o econ\u00f4mica e escal\u00e1vel de dispositivos exigentes em energia por meio de uma \u00fanica conex\u00e3o Ethernet. Com maior capacidade de pot\u00eancia, compatibilidade reversa e grande potencial de aplica\u00e7\u00e3o, o PoE+ preenche a lacuna entre o PoE tradicional e o padr\u00e3o de pr\u00f3xima gera\u00e7\u00e3o PoE++.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para organiza\u00e7\u00f5es que desenvolvem <strong>redes prontas para o futuro<\/strong>, escolher magn\u00e9ticos PoE confi\u00e1veis \u00e9 fundamental. <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/buy-poe+.htm\"><strong>Solu\u00e7\u00f5es PoE+ da LINK-PP<\/strong> <\/a>oferecem o desempenho, a seguran\u00e7a e a escalabilidade necess\u00e1rios para aplica\u00e7\u00f5es corporativas e industriais.<\/p>","protected":false},"excerpt":{"rendered":"<p>Descubra o padr\u00e3o IEEE 802.3at (PoE+), sua entrega de pot\u00eancia de 30 W, principais aplica\u00e7\u00f5es e benef\u00edcios. Saiba como os magn\u00e9ticos RJ45 PoE+ LINK-PP suportam redes modernas.<\/p>","protected":false},"author":1,"featured_media":4782,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[22,23],"class_list":["post-4783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowledge-center","tag-integrated-rj45-connectors","tag-link-pp-lan-transformers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts\/4783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/comments?post=4783"}],"version-history":[{"count":4,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts\/4783\/revisions"}],"predecessor-version":[{"id":11361,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts\/4783\/revisions\/11361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/media\/4782"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/media?parent=4783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/categories?post=4783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/tags?post=4783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}