{"id":4170,"date":"2025-09-15T11:12:00","date_gmt":"2025-09-15T11:12:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/glossary\/what-is-ftth-fiber-to-the-home\/"},"modified":"2026-06-22T07:15:04","modified_gmt":"2026-06-22T07:15:04","slug":"what-is-ftth-fiber-to-the-home","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/pt\/glossary\/what-is-ftth-fiber-to-the-home","title":{"rendered":"Compreendendo FTTH (Fibra at\u00e9 a Casa): Um Guia Abrangente"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"477\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dd15766dfe004e4ea8bfe32624c4bbc5.webp\" alt=\"What Is FTTH?\" class=\"wp-image-4166\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dd15766dfe004e4ea8bfe32624c4bbc5.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dd15766dfe004e4ea8bfe32624c4bbc5-300x119.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dd15766dfe004e4ea8bfe32624c4bbc5-1024x407.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dd15766dfe004e4ea8bfe32624c4bbc5-768x305.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dd15766dfe004e4ea8bfe32624c4bbc5-18x7.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Introdu\u00e7\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FTTH (Fibra at\u00e9 a Resid\u00eancia)<\/strong> \u00e9 uma tecnologia de banda larga de ponta que fornece internet de alta velocidade diretamente \u00e0s resid\u00eancias usando cabos de fibra \u00f3ptica. Ao contr\u00e1rio das conex\u00f5es tradicionais baseadas em cobre, o FTTH oferece velocidade, confiabilidade e escalabilidade sem paralelo, tornando-o ideal para aplica\u00e7\u00f5es digitais modernas, como streaming, jogos online, telemedicina e sistemas de casa inteligente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 O que \u00e9 FTTH?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O FTTH envolve a instala\u00e7\u00e3o de cabos de fibra \u00f3ptica de um escrit\u00f3rio central (CO) diretamente at\u00e9 resid\u00eancias ou empresas individuais. Essa conex\u00e3o direta por fibra substitui tecnologias mais antigas, como DSL ou cabos coaxiais, proporcionando largura de banda significativamente maior e menor lat\u00eancia. O FTTH \u00e9 um subconjunto da fam\u00edlia mais ampla de <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/knowledge-center\/fttx-technical-guide-modern-fiber-access-architectures\/\"><strong>FTTx<\/strong><\/a> (Fibra at\u00e9 o X), que inclui:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>FTTB (Fibra at\u00e9 o Edif\u00edcio):<\/strong> A fibra alcan\u00e7a a entrada do edif\u00edcio, com as conex\u00f5es internas feitas por cabos de cobre ou coaxiais.<\/p><\/li><li><p><strong>FTTC (Fibra at\u00e9 a Cal\u00e7ada):<\/strong> A fibra se estende at\u00e9 um ponto de distribui\u00e7\u00e3o pr\u00f3ximo \u00e0s instala\u00e7\u00f5es, com a conex\u00e3o final realizada usando linhas de cobre.<\/p><\/li><li><p><strong>FTTN (Fibra at\u00e9 o N\u00f3):<\/strong> A fibra se estende at\u00e9 um n\u00f3 de bairro, com linhas de cobre completando a conex\u00e3o at\u00e9 as resid\u00eancias.<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">O FTTH \u00e9 considerado a op\u00e7\u00e3o mais avan\u00e7ada e preparada para o futuro, oferecendo o desempenho e a capacidade mais elevados.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"450\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/55111ab41ab44f4e94795a0ca269e081.webp\" alt=\"FTTH: Fiber to the home\" class=\"wp-image-4167\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/55111ab41ab44f4e94795a0ca269e081.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/55111ab41ab44f4e94795a0ca269e081-300x113.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/55111ab41ab44f4e94795a0ca269e081-1024x384.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/55111ab41ab44f4e94795a0ca269e081-768x288.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/55111ab41ab44f4e94795a0ca269e081-18x7.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Como o FTTH funciona<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A rede FTTH \u00e9 composta por diversos componentes essenciais:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>Terminal de Linha \u00d3ptica (OLT):<\/strong> Localizado no escrit\u00f3rio central do provedor de servi\u00e7os, o OLT gerencia o tr\u00e1fego de dados e os sinais destinados \u00e0s Unidades de Rede \u00d3ptica (ONUs) nas instala\u00e7\u00f5es do cliente.<\/p><\/li><li><p><strong>Divisores \u00d3pticos:<\/strong> Esses dispositivos passivos dividem o sinal \u00f3ptico proveniente do OLT em m\u00faltiplos caminhos, permitindo que uma \u00fanica fibra atenda v\u00e1rias resid\u00eancias.<\/p><\/li><li><p><strong>Terminal de Rede \u00d3ptica (ONT):<\/strong> Instalado nas instala\u00e7\u00f5es do usu\u00e1rio, o ONT converte sinais \u00f3pticos em sinais el\u00e9tricos para uso por dispositivos como computadores, roteadores e televis\u00f5es.<\/p><\/li><li><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/knowledge-center\/fiber-optic-cable-what-it-is-and-how-it-works-explained\/\"><strong>Cabos de Fibra \u00d3ptica<\/strong><\/a><strong>:<\/strong> Geralmente s\u00e3o utilizadas fibras monomodo para FTTH, fornecendo alta largura de banda em longas dist\u00e2ncias com perda m\u00ednima de sinal.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Vantagens do FTTH<\/h2>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p><strong>Internet de Alta Velocidade:<\/strong> O FTTH pode oferecer velocidades de at\u00e9 1 Gbps ou superiores, permitindo streaming em HD sem interrup\u00e7\u00f5es, downloads r\u00e1pidos e jogos online suaves.<\/p><\/li><li><p><strong>Baixa lat\u00eancia:<\/strong> A tecnologia oferece lat\u00eancia reduzida, o que \u00e9 crucial para aplica\u00e7\u00f5es em tempo real, como videoconfer\u00eancia e jogos online.<\/p><\/li><li><p><strong>Velocidades Sim\u00e9tricas:<\/strong> O FTTH frequentemente fornece velocidades iguais de upload e download, o que \u00e9 ben\u00e9fico para atividades como backups na nuvem e cria\u00e7\u00e3o de conte\u00fado.<\/p><\/li><li><p><strong>Confiabilidade:<\/strong> Os cabos de fibra \u00f3ptica s\u00e3o menos suscet\u00edveis a <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/glossary\/what-is-electromagnetic-interference\/\">interfer\u00eancia eletromagn\u00e9tica<\/a> e fatores ambientais, garantindo uma conex\u00e3o est\u00e1vel.<\/p><\/li><li><p><strong>Selecionar uma contagem alinhada com caminhos futuros de migra\u00e7\u00e3o protege seu investimento.<\/strong> A alta capacidade de largura de banda do FTTH suporta avan\u00e7os tecnol\u00f3gicos futuros e demandas crescentes de dados.<\/p><\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Aplica\u00e7\u00f5es do FTTH<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O FTTH est\u00e1 transformando diversos setores:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>Residencial:<\/strong> Fornece internet ultra-r\u00e1pida para resid\u00eancias, suportando m\u00faltiplos dispositivos e aplica\u00e7\u00f5es de casa inteligente.<\/p><\/li><li><p><strong>Empresarial:<\/strong> Melhora a produtividade com internet confi\u00e1vel e de alta velocidade, facilitando o trabalho remoto e os servi\u00e7os em nuvem.<\/p><\/li><li><p><strong>Sa\u00fade:<\/strong> Suporta telemedicina, monitoramento remoto de pacientes e acesso a registros eletr\u00f4nicos de sa\u00fade.<\/p><\/li><li><p><strong>Educa\u00e7\u00e3o:<\/strong> Permite aprendizagem online, salas de aula virtuais e acesso a recursos educacionais.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 M\u00f3dulos \u00d3pticos LINK-PP para FTTH<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1506a789f2154eb9bd332818d3bf2996.webp\" alt=\"FTTH Optical Transceivers\" class=\"wp-image-4168\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1506a789f2154eb9bd332818d3bf2996.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1506a789f2154eb9bd332818d3bf2996-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1506a789f2154eb9bd332818d3bf2996-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1506a789f2154eb9bd332818d3bf2996-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1506a789f2154eb9bd332818d3bf2996-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Na LINK-PP, oferecemos uma gama de m\u00f3dulos <strong>\u00f3pticos de alto desempenho<\/strong> e acess\u00f3rios projetados especificamente para implanta\u00e7\u00f5es FTTH. Abaixo est\u00e3o alguns dos transceptores \u00f3pticos FTTH da LINK-PP:<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"width: 184px;\"\/><col style=\"width: 80px;\"\/><col style=\"width: 131px;\"\/><col style=\"width: 104px;\"\/><col style=\"width: 173px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\" colwidth=\"184\"><p>Modelo do Produto<\/p><\/th><th colspan=\"1\" rowspan=\"1\" colwidth=\"80\"><p>Taxa de Dados<\/p><\/th><th colspan=\"1\" rowspan=\"1\" colwidth=\"131\"><p>Comprimento de onda <\/p><\/th><th colspan=\"1\" rowspan=\"1\" colwidth=\"104\"><p>Dist\u00e2ncia<\/p><\/th><th colspan=\"1\" rowspan=\"1\" colwidth=\"173\"><p>Aplica\u00e7\u00e3o em FTTH<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"184\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/478230.htm\"><strong>LS-MM851G-S5C<\/strong><\/a><\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"80\"><p>1,25 G<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"131\"><p>850nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"104\"><p>500 m (MMF)<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"173\"><p>Conex\u00f5es de curta dist\u00e2ncia em edif\u00edcios ou instala\u00e7\u00f5es do assinante<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"184\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/488475.htm\"><strong>LS-SM311G-02I<\/strong><\/a><\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"80\"><p>1,25 G<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"131\"><p>1310 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"104\"><p>2 km (SMF)<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"173\"><p>Transmiss\u00e3o downstream GPON do OLT at\u00e9 o divisor\/ONT<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"184\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/488431.htm\"><strong>LS-SM551G-60C<\/strong><\/a><\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"80\"><p>1,25 G<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"131\"><p>1550 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"104\"><p>60 km (SMF)<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"173\"><p>Caminho de retorno upstream do ONT ao OLT<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Conclus\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O FTTH representa o \u00e1pice da tecnologia de banda larga, oferecendo velocidade, confiabilidade e escalabilidade incompar\u00e1veis. Com as solu\u00e7\u00f5es <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-26155-1g-sfp.htm?ca=1453&amp;cv=8281\">de m\u00f3dulo SFP da LINK-PP,<\/a>, implantar uma rede FTTH robusta e preparada para o futuro est\u00e1 ao seu alcance. Adote o futuro da conectividade \u00e0 internet com FTTH e LINK-PP.<\/p>","protected":false},"excerpt":{"rendered":"<p>Discover FTTH technology\u2014how it works, its advantages, and how LINK-PP&#8217;s solutions can enhance your broadband experience.<\/p>","protected":false},"author":1,"featured_media":4169,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[27],"tags":[26],"class_list":["post-4170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-glossary","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts\/4170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/comments?post=4170"}],"version-history":[{"count":5,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts\/4170\/revisions"}],"predecessor-version":[{"id":11130,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts\/4170\/revisions\/11130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/media\/4169"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/media?parent=4170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/categories?post=4170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/tags?post=4170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}