{"id":3911,"date":"2025-11-14T00:00:00","date_gmt":"2025-11-14T00:00:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/glossary\/fiber-bragg-grating-precise-strain-temperature-sensing-monitoring\/"},"modified":"2026-06-22T05:05:29","modified_gmt":"2026-06-22T05:05:29","slug":"fiber-bragg-grating-precise-strain-temperature-sensing-monitoring","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/pt\/glossary\/fiber-bragg-grating-precise-strain-temperature-sensing-monitoring","title":{"rendered":"O que \u00e9 Grade de Bragg em Fibra \u00d3ptica? O Guia Definitivo para Sensores FBG"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/458beee1ca3b47c481fd710e7107a57a.webp\" alt=\"Fiber Bragg Grating (FBG)\" class=\"wp-image-3909\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/458beee1ca3b47c481fd710e7107a57a.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/458beee1ca3b47c481fd710e7107a57a-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/458beee1ca3b47c481fd710e7107a57a-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/458beee1ca3b47c481fd710e7107a57a-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/458beee1ca3b47c481fd710e7107a57a-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea j\u00e1 se perguntou como uma enorme p\u00e1 de turbina e\u00f3lica pode detectar tens\u00f5es estruturais ou como as temperaturas s\u00e3o monitoradas nas profundezas de uma usina el\u00e9trica? A resposta muitas vezes reside em uma tecnologia not\u00e1vel escondida dentro de uma fibra \u00f3ptica fina como um fio de cabelo: <strong>Fiber Bragg Grating (FBG)<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste guia abrangente, desmistificaremos a tecnologia FBG. Exploraremos seus princ\u00edpios fundamentais, como \u00e9 fabricada, suas amplas aplica\u00e7\u00f5es e por que \u00e9 uma escolha superior para sistemas modernos de detec\u00e7\u00e3o e comunica\u00e7\u00e3o. Tamb\u00e9m abordaremos seu papel em avan\u00e7ados <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\"><strong>transceptores \u00f3pticos<\/strong><\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83c\udf10 Principais Conclus\u00f5es<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>Sensores de grade de Bragg em fibra<\/strong> conseguem medir altera\u00e7\u00f5es de deforma\u00e7\u00e3o e temperatura com precis\u00e3o. Eles ajudam a verificar a seguran\u00e7a de pontes e m\u00e1quinas.<\/p><\/li><li><p>Esses sensores refletem apenas certas cores de luz. Isso permite que detectem at\u00e9 mesmo pequenas mudan\u00e7as ao seu redor.<\/p><\/li><li><p>Os sensores de grade de Bragg em fibra s\u00e3o confi\u00e1veis e n\u00e3o afetados por ru\u00eddo el\u00e9trico. Funcionam em ambientes dif\u00edceis onde outros sensores poderiam deixar de operar.<\/p><\/li><li><p>A multiplexa\u00e7\u00e3o permite que v\u00e1rios sensores sejam instalados em uma \u00fanica fibra. Isso torna mais f\u00e1cil e r\u00e1pido monitorar grandes \u00e1reas.<\/p><\/li><li><p>O uso de sensores de grade de Bragg em fibra ajuda a manter a seguran\u00e7a e o funcionamento adequado dos equipamentos. S\u00e3o utilizados em f\u00e1bricas e no monitoramento ambiental.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83c\udf10 O Princ\u00edpio Central: um \u201cespelho\u201d dentro de uma fibra<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Em sua ess\u00eancia, uma <strong>Grade de Bragg em Fibra<\/strong> \u00e9 uma perturba\u00e7\u00e3o microsc\u00f3pica <strong>peri\u00f3dica do \u00edndice de refra\u00e7\u00e3o<\/strong> no n\u00facleo de uma fibra \u00f3ptica. Pense nela como uma s\u00e9rie de min\u00fasculos espelhos paralelos gravados no vidro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando uma luz de espectro amplo \u00e9 enviada pela fibra, essa grade especial atua como um filtro seletivo. Ela reflete um comprimento de onda muito espec\u00edfico da luz, conhecido como <strong>Comprimento de Onda de Bragg (\u03bb\u2086)<\/strong>, transmitindo todos os demais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A equa\u00e7\u00e3o fundamental que rege esse fen\u00f4meno \u00e9:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><mark data-color=\"var(--qc-color2)\" style=\"background-color: var(--qc-color2); color: inherit;\">\u03bb\u2086 = 2n\u039b<\/mark><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Onde:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong><mark data-color=\"var(--qc-color2)\" style=\"background-color: var(--qc-color2); color: inherit;\">\u03bb\u2086<\/mark><\/strong> \u00e9 o comprimento de onda de Bragg (o comprimento de onda refletido).<\/p><\/li><li><p style=\"margin: 0px;\"><strong><mark data-color=\"var(--qc-color2)\" style=\"background-color: var(--qc-color2); color: inherit;\">n<\/mark><\/strong> \u00e9 o \u00edndice de refra\u00e7\u00e3o efetivo do n\u00facleo da fibra.<\/p><\/li><li><p style=\"margin: 0px;\"><strong><mark data-color=\"var(--qc-color2)\" style=\"background-color: var(--qc-color2); color: inherit;\">\u039b<\/mark><\/strong> (Lambda) \u00e9 o per\u00edodo da grade.<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Essa simples equa\u00e7\u00e3o \u00e9 a chave para o poder de detec\u00e7\u00e3o da FBG. Qualquer fator externo, como <strong>deforma\u00e7\u00e3o (alongamento ou compress\u00e3o), temperatura ou press\u00e3o<\/strong> que altere qualquer um dos dois par\u00e2metros <strong>\u2018<mark data-color=\"var(--qc-color2)\" style=\"background-color: var(--qc-color2); color: inherit;\">n<\/mark>\u2018<\/strong> or <strong>\u2018<mark data-color=\"var(--qc-color2)\" style=\"background-color: var(--qc-color2); color: inherit;\">\u039b<\/mark>\u2018<\/strong> causar\u00e1 um deslocamento direto e mensur\u00e1vel no comprimento de onda de Bragg. Ao medir com precis\u00e3o esse deslocamento, podemos determinar exatamente a magnitude da mudan\u00e7a f\u00edsica que afeta a grade. <\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"505\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/6b86bde3fb8b4944994cea4d98c34181.webp\" alt=\"Fiber Bragg Grating (FBG)\" class=\"wp-image-3910\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/6b86bde3fb8b4944994cea4d98c34181.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/6b86bde3fb8b4944994cea4d98c34181-300x126.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/6b86bde3fb8b4944994cea4d98c34181-1024x431.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/6b86bde3fb8b4944994cea4d98c34181-768x323.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/6b86bde3fb8b4944994cea4d98c34181-18x8.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83c\udf10 Como os sensores FBG s\u00e3o fabricados?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Criar esses espelhos internos intrincados exige precis\u00e3o. O m\u00e9todo mais comum \u00e9 a <strong>t\u00e9cnica da m\u00e1scara de fase<\/strong>.<\/p>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p style=\"margin: 0px;\"><strong>A Configura\u00e7\u00e3o:<\/strong> Uma m\u00e1scara de fase especial (uma grade fotolitogr\u00e1fica) \u00e9 posicionada \u00e0 frente de uma fibra \u00f3ptica fotosens\u00edvel.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>O Processo de \u201cGrava\u00e7\u00e3o\u201d:<\/strong> Um feixe intenso de laser ultravioleta (UV) \u00e9 direcionado atrav\u00e9s da m\u00e1scara.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Altera\u00e7\u00e3o Permanente:<\/strong> A luz UV interfere ao atravessar a m\u00e1scara, criando um padr\u00e3o peri\u00f3dico de regi\u00f5es de alta e baixa intensidade sobre o n\u00facleo da fibra. Essa exposi\u00e7\u00e3o aumenta permanentemente o \u00edndice de refra\u00e7\u00e3o nas regi\u00f5es iluminadas, \u201cgravando\u201d a grade na fibra.<\/p><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Esse processo permite a cria\u00e7\u00e3o de sensores FBG altamente consistentes e confi\u00e1veis, o que \u00e9 crucial para aplica\u00e7\u00f5es que exigem alta precis\u00e3o, como <strong>solu\u00e7\u00f5es de monitoramento da integridade estrutural<\/strong> and <strong>sistemas de detec\u00e7\u00e3o distribu\u00edda<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83c\udf10 Principais vantagens da tecnologia FBG: por que escolh\u00ea-la?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Os sensores FBG<\/strong> revolucionaram as medi\u00e7\u00f5es em ambientes severos e cr\u00edticos. Veja abaixo uma compara\u00e7\u00e3o que explica por que eles frequentemente superam os sensores eletr\u00f4nicos tradicionais:<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p>Recurso<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Sensores FBG<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Sensores Eletr\u00f4nicos Tradicionais<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Imunidade \u00e0 interfer\u00eancia eletromagn\u00e9tica (EMI)<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u2705 Excelente (baseada em luz)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u274c Suscet\u00edveis \u00e0 interfer\u00eancia<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Fator de Forma<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Pequenos, leves e flex\u00edveis<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Geralmente mais volumosos<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Multiplexa\u00e7\u00e3o<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u2705 Alta (v\u00e1rios sensores em uma \u00fanica fibra)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u274c Fia\u00e7\u00e3o complexa para cada sensor<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Resist\u00eancia \u00e0 corros\u00e3o<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u2705 Excelente (vidro)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u274c Podem sofrer corros\u00e3o em ambientes agressivos<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Longa dist\u00e2ncia<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u2705 Funciona por quil\u00f4metros<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u274c Alcance de sinal limitado<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Isso torna a tecnologia FBG ideal para <strong>monitoramento cont\u00ednuo de condi\u00e7\u00f5es<\/strong> em ambientes industriais com alto ru\u00eddo el\u00e9trico e para garantir a <strong>seguran\u00e7a aeron\u00e1utica e espacial<\/strong> por meio de detec\u00e7\u00e3o embutida em materiais compostos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83c\udf10 Aplica\u00e7\u00f5es pr\u00e1ticas da detec\u00e7\u00e3o FBG<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os benef\u00edcios exclusivos da FBG se traduzem em solu\u00e7\u00f5es poderosas em diversos setores:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Engenharia Civil e Infraestrutura:<\/strong> Monitoramento de pontes, t\u00faneis, barragens e edif\u00edcios hist\u00f3ricos quanto a tens\u00f5es, deforma\u00e7\u00f5es e estresse.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Energia:<\/strong> <strong>Monitoramento de temperatura em transformadores de pot\u00eancia<\/strong> e detec\u00e7\u00e3o de carga nas p\u00e1s de turbinas e\u00f3licas.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Aeroespacial:<\/strong> Incorpora\u00e7\u00e3o de sensores nas asas e fuselagens de aeronaves para monitorar a integridade estrutural.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Medicina:<\/strong> Desenvolvimento de agulhas e cateteres avan\u00e7ados com capacidade de detec\u00e7\u00e3o de forma para cirurgias minimamente invasivas.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Petr\u00f3leo e G\u00e1s:<\/strong> Detec\u00e7\u00e3o de press\u00e3o e temperatura em po\u00e7os profundos em ambientes extremos.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83c\udf10 A conex\u00e3o FBG: estabilidade de comprimento de onda em transceptores \u00f3pticos<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea talvez esteja se perguntando: qual \u00e9 a rela\u00e7\u00e3o entre FBG e comunica\u00e7\u00e3o de dados? A resposta est\u00e1 em uma de suas aplica\u00e7\u00f5es mais antigas e cr\u00edticas: estabiliza\u00e7\u00e3o de diodos laser em <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\"><strong>transceptores \u00f3pticos<\/strong><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os lasers em transceptores podem apresentar deriva de comprimento de onda devido \u00e0 temperatura e ao envelhecimento, causando degrada\u00e7\u00e3o do sinal. Uma FBG interna atua como um espelho de cavidade externa altamente est\u00e1vel <strong>, fixando a sa\u00edda do laser em um comprimento de onda espec\u00edfico e preciso definido pela pr\u00f3pria grade. Isso \u00e9 essencial para<\/strong>, sistemas <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/glossary\/what-is-dwdm-explaining-dense-wavelength-division-multiplexing\/\"><strong>Multiplexa\u00e7\u00e3o Densa por Divis\u00e3o de Comprimento de Onda (DWDM)<\/strong><\/a> , nos quais dezenas de canais devem permanecer perfeitamente alinhados para evitar <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/glossary\/crosstalk-definition-causes-types-effects\/\"><strong>diafonia<\/strong><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para engenheiros de rede que buscam componentes confi\u00e1veis e de alto desempenho, escolher transceptores com fontes laser est\u00e1veis \u00e9 imprescind\u00edvel. Por exemplo, o de alto desempenho <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-27045-100g-qsfp28-sfp-dd.htm\"><strong>LINK-PP 100G QSFP28<\/strong> <strong>transceptor<br><\/strong><\/a> utiliza tecnologia laser avan\u00e7ada para garantir integridade de sinal superior e baixo consumo de energia em aplica\u00e7\u00f5es exigentes de data centers e telecomunica\u00e7\u00f5es. Ao avaliar seus <strong>requisitos de transceptores \u00f3pticos de alta velocidade<\/strong>, considerar a tecnologia subjacente que garante estabilidade de comprimento de onda \u00e9 um passo fundamental.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83c\udf10 Conclus\u00e3o: O futuro est\u00e1 escrito na luz<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Grade de Bragg em Fibra<\/strong> \u00e9 uma tecnologia vers\u00e1til e poderosa que transforma uma simples fibra \u00f3ptica em uma ferramenta precisa de detec\u00e7\u00e3o e comunica\u00e7\u00e3o. Sua imunidade a interfer\u00eancias eletromagn\u00e9ticas (EMI), capacidade de multiplexa\u00e7\u00e3o e robustez tornam-na a solu\u00e7\u00e3o preferida para infraestruturas inteligentes, monitoramento industrial avan\u00e7ado e links de dados de alta velocidade confi\u00e1veis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 medida que a demanda por dados e monitoramento inteligente cresce, o papel da FBG s\u00f3 se tornar\u00e1 mais proeminente, abrindo caminho para estruturas mais seguras, ind\u00fastrias mais eficientes e redes mais r\u00e1pidas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83c\udf10 Perguntas frequentes (FAQ)<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >Qual \u00e9 a finalidade principal de um sensor de grade de Bragg em fibra?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea usa um sensor de grade de Bragg em fibra para medir deforma\u00e7\u00e3o (strain) e temperatura. O sensor ajuda voc\u00ea a identificar altera\u00e7\u00f5es em estruturas ou m\u00e1quinas. Ele fornece dados claros usando luz.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >O que diferencia os sensores de grade de Bragg em fibra dos sensores convencionais?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os sensores de grade de Bragg em fibra usam luz em vez de eletricidade. Voc\u00ea obt\u00e9m leituras precisas. Esses sensores n\u00e3o reagem a ru\u00eddos el\u00e9tricos. Voc\u00ea pode utiliz\u00e1-los em locais onde sensores convencionais poderiam falhar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Em quais tipos de ambientes voc\u00ea pode usar sensores de grade de Bragg em fibra?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode usar sensores de grade de Bragg em fibra em ambientes \u00famidos, quentes ou sujos. Os sensores funcionam bem em condi\u00e7\u00f5es adversas. Voc\u00ea pode confiar neles para monitoramento externo, industrial ou subterr\u00e2neo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >O que o comprimento de onda de Bragg indica?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O comprimento de onda de Bragg mostra se a fibra est\u00e1 sendo esticada ou aquecida. Voc\u00ea observa esse comprimento de onda para saber o que est\u00e1 acontecendo. Uma altera\u00e7\u00e3o significa que h\u00e1 deforma\u00e7\u00e3o (strain) ou mudan\u00e7a de temperatura.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Quais s\u00e3o alguns usos comuns dos sensores de grade de Bragg em fibra?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea encontra sensores de grade de Bragg em fibra em pontes, t\u00faneis, f\u00e1bricas e dutos. Esses sensores ajudam voc\u00ea a monitorar a seguran\u00e7a, identificar danos e detectar vazamentos. Voc\u00ea os utiliza para manter tudo funcionando adequadamente.<\/p>","protected":false},"excerpt":{"rendered":"<p>A grade de Bragg em fibra \u00f3ptica permite detec\u00e7\u00e3o precisa de deforma\u00e7\u00e3o e temperatura, oferecendo monitoramento confi\u00e1vel para estruturas, m\u00e1quinas e ambientes severos.<\/p>","protected":false},"author":1,"featured_media":3909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[27],"tags":[13,17,24,26],"class_list":["post-3911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-glossary","tag-100g-modules","tag-400g-optical-modules","tag-link-pp","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts\/3911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/comments?post=3911"}],"version-history":[{"count":5,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts\/3911\/revisions"}],"predecessor-version":[{"id":10882,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts\/3911\/revisions\/10882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/media\/3909"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/media?parent=3911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/categories?post=3911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/tags?post=3911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}