{"id":3818,"date":"2025-09-03T00:00:00","date_gmt":"2025-09-03T00:00:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/glossary\/mode-conditioning-patch-cables-how-they-work-in-networks\/"},"modified":"2026-06-22T07:47:30","modified_gmt":"2026-06-22T07:47:30","slug":"mode-conditioning-patch-cables-how-they-work-in-networks","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/pt\/glossary\/mode-conditioning-patch-cables-how-they-work-in-networks","title":{"rendered":"O Que S\u00e3o Cabos de Corre\u00e7\u00e3o de Modo e Como Funcionam"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e804416210894e9c9828e14e16210c3f.webp\" alt=\"What Are Mode Conditioning Patch Cables\" class=\"wp-image-3815\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e804416210894e9c9828e14e16210c3f.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e804416210894e9c9828e14e16210c3f-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e804416210894e9c9828e14e16210c3f-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e804416210894e9c9828e14e16210c3f-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e804416210894e9c9828e14e16210c3f-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 implantou um transceptor \u00f3ptico Gigabit LX ou 10G LR e foi atormentado por erros inesperados, perda elevada ou links inst\u00e1veis? O culpado pode n\u00e3o ser seu equipamento, mas uma incompatibilidade fundamental entre os tipos de cabos de fibra \u00f3ptica. \u00c9 aqui que entra em cena um pequeno, mas poderoso her\u00f3i: o <strong>Cabo de Corre\u00e7\u00e3o de Modo (MCP)<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste guia, desvendaremos <strong>o que \u00e9 um cabo de corre\u00e7\u00e3o de modo<\/strong>, por que ele \u00e9 essencial em cen\u00e1rios espec\u00edficos de rede e como pode salv\u00e1-lo de uma infinidade de dores de cabe\u00e7a na conectividade. Tamb\u00e9m exploraremos como ele interage com componentes de alto desempenho, como <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\"><strong>Transceptores \u00f3pticos LINK-PP<\/strong><\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 Principais Conclus\u00f5es<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>Cabos de corre\u00e7\u00e3o de modo<\/strong> permitem que dispositivos de modo \u00fanico utilizem fibra multimodo. Eles resolvem problemas de sinal, como atraso diferencial de modo.<\/p><\/li><li><p>Esses cabos melhoram o sinal e reduzem erros. Isso ajuda as redes a operarem mais rapidamente e com maior confiabilidade, especialmente para Ethernet Gigabit.<\/p><\/li><li><p>Os cabos possuem uma parte especial com um trecho de modo \u00fanico. Essa parte desloca o sinal luminoso para reduzir a distor\u00e7\u00e3o e facilitar a transmiss\u00e3o de dados.<\/p><\/li><li><p>Conecte sempre a extremidade de modo \u00fanico ao transceptor. Conecte a extremidade multimodo \u00e0 infraestrutura de fibra para evitar problemas na rede.<\/p><\/li><li><p>Limpe os conectores antes de us\u00e1-los. N\u00e3o dobre os cabos bruscamente. Teste a conex\u00e3o ap\u00f3s a instala\u00e7\u00e3o para manter a rede robusta.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 Por Que Precisamos de um \u201cCabo Especial\u201d? O Problema Multimodo vs. Modo \u00danico<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para compreender a solu\u00e7\u00e3o, devemos primeiro entender o problema. Os cabos de fibra \u00f3ptica existem principalmente em dois tipos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/knowledge-center\/om1-om2-om3-om4-om5-multimode-fiber-guide\/\"><strong>Fibra Multimodo (MMF)<\/strong><\/a><strong>:<\/strong> Possui um n\u00facleo maior, permitindo que m\u00faltiplos modos de luz (trajet\u00f3rias) se propaguem. Foi projetado para aplica\u00e7\u00f5es de curta dist\u00e2ncia e alta largura de banda dentro de edif\u00edcios ou campi. Tipos comuns s\u00e3o <strong>OM1, OM2, OM3 e OM4<\/strong>.<\/p><\/li><li><p style=\"margin: 0px;\"><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/knowledge-center\/what-is-single-mode-fiber-and-how-does-it-work\/\"><strong>Fibra monomodo (SMF)<\/strong><\/a><strong>:<\/strong> Possui um n\u00facleo muito menor, permitindo que apenas um modo de luz se propague em linha reta. Foi projetado para comunica\u00e7\u00e3o de longa dist\u00e2ncia, como entre cidades.<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">O problema surge ao tentar conectar um <strong>transceptor de alcance longo (LX\/LR)<\/strong> (projetado para fibra de modo \u00fanico \u2013 SMF) a uma <strong>Fibra Multimodo (MMF)<\/strong> infraestrutura de cabos multimodo (MMF). Isso \u00e9 comum em edif\u00edcios antigos com cabeamento MMF que precisam se conectar a um novo backbone de SMF.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A luz laser do transceptor LX\/LR \u00e9 injetada no grande n\u00facleo da fibra MMF. Isso pode causar um fen\u00f4meno chamado <strong>Atraso Diferencial de Modo (DMD)<\/strong>, em que pulsos luminosos se espalham e se distorcem durante a propaga\u00e7\u00e3o, gerando jitter, erros e falha total do link. Isso \u00e9 especialmente problem\u00e1tico com <strong>fibras OM3 e OM4<\/strong> and <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/475586.htm\"><strong>m\u00f3dulos 10G LR<\/strong><\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 Como Funciona um Cabo de Corre\u00e7\u00e3o de Modo?<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"318\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/4deb34a51d504b858a9c85430a080028.webp\" alt=\"Mode Conditioning Patch Cables\" class=\"wp-image-3816\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/4deb34a51d504b858a9c85430a080028.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/4deb34a51d504b858a9c85430a080028-300x80.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/4deb34a51d504b858a9c85430a080028-1024x271.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/4deb34a51d504b858a9c85430a080028-768x204.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/4deb34a51d504b858a9c85430a080028-18x5.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>Cabo de conex\u00e3o condicionador de modo<\/strong> \u00e9 um <strong>jumper duplex de fibra<\/strong> engenhosamente projetado para resolver essa incompatibilidade na camada f\u00edsica. \u00c0s vezes, \u00e9 chamado de <em>jumper de corre\u00e7\u00e3o de modo<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seu segredo est\u00e1 na sua constru\u00e7\u00e3o no lado de transmiss\u00e3o (Tx):<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\">Uma perna do cabo \u00e9 um conector padr\u00e3o de <strong>modo \u00fanico<\/strong> que se conecta ao seu transceptor.<\/p><\/li><li><p style=\"margin: 0px;\">A outra perna \u00e9 um <strong>conector multimodo<\/strong> com uma emenda de fus\u00e3o deslocada precisa, localizada a poucos metros da extremidade.<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Esse projeto for\u00e7a a luz laser a percorrer inicialmente uma curta dist\u00e2ncia em fibra de modo \u00fanico. Em seguida, ela \u00e9 injetada estrategicamente no <strong>centro do n\u00facleo da fibra multimodo<\/strong> no ponto de emenda. Quando o sinal entra na sua infraestrutura de cabos MMF legada, j\u00e1 est\u00e1 estabilizado, eliminando efetivamente o efeito DMD e permitindo uma transmiss\u00e3o de dados limpa e confi\u00e1vel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Principais Aplica\u00e7\u00f5es e Casos de Uso:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\">Conectando <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/476763.htm\"><strong>M\u00f3dulo SFP 1000BASE-LX<\/strong><\/a> to <strong>fibras multimodo OM1\/OM2\/OM3<\/strong> .<\/p><\/li><li><p style=\"margin: 0px;\">Conectando <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/475586.htm\"><strong>M\u00f3dulos SFP+ 10GBASE-LR<\/strong><\/a> to <strong>OM3\/OM4<\/strong> .<\/p><\/li><li><p style=\"margin: 0px;\">Amplia\u00e7\u00e3o do alcance dos transceptores LX\/LR em fibras MMF al\u00e9m da dist\u00e2ncia t\u00edpica limitada pelo DMD.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 Corre\u00e7\u00e3o de Modo vs. Cabo Padr\u00e3o: Uma Compara\u00e7\u00e3o R\u00e1pida<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p><strong>Recurso<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>Cabo Padr\u00e3o<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>Cabo de conex\u00e3o condicionador de modo<\/strong><\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Fun\u00e7\u00e3o Principal<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Conecta tipos iguais de fibra (SMF-SMF ou MMF-MMF)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Conecta tipos diferentes de fibra (transceptor SMF a cabo MMF)<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Projeto Interno<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Tipo de fibra consistente em todo o comprimento<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Apresenta uma <strong>emenda de fus\u00e3o deslocada precisa<\/strong><\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Caso de uso<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Conex\u00f5es padr\u00e3o, do tipo \u201cin\u201d<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p><strong>Atualiza\u00e7\u00f5es de redes legadas<\/strong>, requisitos espec\u00edficos de transceptores<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Previne DMD?<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>No<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p><strong>Yes<\/strong><\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Cost<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Lower<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Levemente superior<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 Integra\u00e7\u00e3o com Transceptores \u00d3pticos LINK-PP para Desempenho Ideal<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"719\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ab15e605dd5a45cc9008a6ae30a4e10f.jpg\" alt=\"optical transceivers\" class=\"wp-image-3817\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ab15e605dd5a45cc9008a6ae30a4e10f.jpg 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ab15e605dd5a45cc9008a6ae30a4e10f-300x180.jpg 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ab15e605dd5a45cc9008a6ae30a4e10f-1024x614.jpg 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ab15e605dd5a45cc9008a6ae30a4e10f-768x460.jpg 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ab15e605dd5a45cc9008a6ae30a4e10f-18x12.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ao construir uma rede confi\u00e1vel e de alto desempenho, cada componente deve funcionar em harmonia. Usar um cabo de corre\u00e7\u00e3o de modo de qualidade \u00e9 crucial para desbloquear todo o potencial de seus <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\"><strong>transceivers de fibra \u00f3ptica<\/strong><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por exemplo, se voc\u00ea estiver usando um <strong>LINK-PP <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/475586.htm\"><strong>SFP-10G-LR<\/strong><\/a> m\u00f3dulo para se conectar a um backbone multimodo OM3 existente, um cabo de corre\u00e7\u00e3o de modo \u00e9 n\u00e3o apenas recomendado; muitas vezes \u00e9 obrigat\u00f3rio para um link est\u00e1vel. O mesmo vale para um<strong> <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/476763.htm\"><strong>SFP-1G-LX<\/strong><\/a> m\u00f3dulo em cabos OM1 mais antigos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O sinal el\u00e9trico restaurado \u00e9 transmitido para o switch\/roteador receptor para processamento adicional.<\/strong> Verifique sempre a folha de dados de seus <strong>transceptores compat\u00edveis com LINK-PP<\/strong>. Ela especificar\u00e1 o tipo de fibra exigido e frequentemente mencionar\u00e1 explicitamente a necessidade de um cabo de corre\u00e7\u00e3o de modo ao se conectar a fibras MMF. A implanta\u00e7\u00e3o adequada dessa configura\u00e7\u00e3o \u00e9 uma pr\u00e1tica recomendada para <strong>confiabilidade da rede<\/strong> e minimiza\u00e7\u00e3o de <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/pt\/glossary\/understanding-what-is-bit-error-rate\/\"><strong>taxas de erro de bit (BER)<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 Voc\u00ea Precisa Dele? Principais Conclus\u00f5es<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Voc\u00ea precisa de um cabo de corre\u00e7\u00e3o de modo se:<\/strong> Estiver conectando um <strong>transceptor de alcance longo (LX, LR, ER)<\/strong> SFP, SFP+ ou GBIC a uma <strong>Fibra Multimodo (MMF)<\/strong> infraestrutura de cabos multimodo.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Voc\u00ea N\u00c3O precisa dele se:<\/strong> Estiver conectando um transceptor ao mesmo tipo de fibra para o qual foi projetado (por exemplo, LX a SMF, ou SX a MMF).<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Investir na infraestrutura de cabos correta garante que sua rede opere com efici\u00eancia, reduza tempo de inatividade e proteja seu investimento em hardware de qualidade, como <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\"><strong>M\u00f3dulos \u00f3pticos LINK-PP<\/strong><\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 FAQ<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >Qual \u00e9 a finalidade principal de um cabo de corre\u00e7\u00e3o de modo?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Um cabo de corre\u00e7\u00e3o de modo permite que transceptores de modo \u00fanico funcionem com fibra multimodo. Ele ajuda a reduzir problemas de sinal, como atraso diferencial de modo. Isso mant\u00e9m os dados fluindo suavemente em redes de fibras mistas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >\u00c9 poss\u00edvel usar um cabo de corre\u00e7\u00e3o de modo com qualquer sistema de fibra \u00f3ptica?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o, esses cabos funcionam melhor ao conectar dispositivos de modo \u00fanico \u00e0 fibra multimodo. Eles n\u00e3o ajudam em sistemas que utilizam apenas fibra monomodo ou apenas fibra multimodo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Como algu\u00e9m pode identificar qual extremidade do cabo \u00e9 de modo \u00fanico?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A maioria dos cabos possui uma prote\u00e7\u00e3o amarela ou uma etiqueta na extremidade de modo \u00fanico. Os usu\u00e1rios devem sempre verificar essas marca\u00e7\u00f5es antes de conectar o cabo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >O que acontece se o cabo for instalado invertido?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Se algu\u00e9m conectar o cabo invertido, a rede pode n\u00e3o funcionar. O sinal pode ficar fraco ou ser perdido. Conecte sempre a extremidade de modo \u00fanico ao transceptor.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Os cabos de corre\u00e7\u00e3o de modo suportam redes de alta velocidade?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sim, esses cabos suportam links de alta velocidade, como Gigabit Ethernet e 10 Gigabit Ethernet. Eles ajudam a manter os sinais claros e fortes em redes r\u00e1pidas.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Dica: Sempre teste a liga\u00e7\u00e3o ap\u00f3s instalar um cabo de corre\u00e7\u00e3o de modo para garantir que a conex\u00e3o funcione bem.<\/p><\/blockquote>","protected":false},"excerpt":{"rendered":"<p>Os cabos de corre\u00e7\u00e3o de modo permitem que dispositivos monomodo funcionem com fibra multimodo, reduzindo a distor\u00e7\u00e3o do sinal e o atraso diferencial de modo nas redes.<\/p>","protected":false},"author":1,"featured_media":3815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[27],"tags":[26],"class_list":["post-3818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-glossary","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts\/3818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/comments?post=3818"}],"version-history":[{"count":4,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts\/3818\/revisions"}],"predecessor-version":[{"id":11185,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/posts\/3818\/revisions\/11185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/media\/3815"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/media?parent=3818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/categories?post=3818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/pt\/wp-json\/wp\/v2\/tags?post=3818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}