{"id":5155,"date":"2025-09-09T00:00:00","date_gmt":"2025-09-09T00:00:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/knowledge-center\/what-is-multicore-fiber-in-high-speed-networks\/"},"modified":"2026-06-22T07:33:18","modified_gmt":"2026-06-22T07:33:18","slug":"what-is-multicore-fiber-in-high-speed-networks","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/it\/knowledge-center\/what-is-multicore-fiber-in-high-speed-networks","title":{"rendered":"Fibra a multicore (MCF): rivoluzionare la densit\u00e0 dei dati con la multiplexazione spaziale"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ca6df008f1e847629042eb4e978ea360.jpg\" alt=\"What Role Does Multicore Fiber Play in High-Speed Communication\" class=\"wp-image-5152\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ca6df008f1e847629042eb4e978ea360.jpg 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ca6df008f1e847629042eb4e978ea360-300x178.jpg 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ca6df008f1e847629042eb4e978ea360-1024x608.jpg 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ca6df008f1e847629042eb4e978ea360-768x456.jpg 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ca6df008f1e847629042eb4e978ea360-18x12.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019insaziabile appetito globale di dati sta spingendo le fibre ottiche convenzionali ai loro limiti fisici. Mentre tecnologie come<br> <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/it\/glossary\/wdm-optical-transceiver-module-applications\/\"><strong>la multiplazione a divisione di lunghezza d\u2019onda (WDM)<br><\/strong><\/a> sono state pilastri fondamentali, \u00e8 in corso un\u2019evoluzione pi\u00f9 radicale. Entra in scena<br> <strong>Fibra a multicore (MCF)<br><\/strong> \u2013 una tecnologia rivoluzionaria che non si limita a potenziare, ma moltiplica i percorsi stessi della luce.<br>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Non si tratta semplicemente di un aggiornamento incrementale; \u00e8 invece una vera e propria svolta paradigmatica. Approfondiamo quindi<br> <strong>cos\u2019\u00e8 la MCF<br><\/strong>, perch\u00e9 \u00e8 importante e come plasmer\u00e0 il futuro della connettivit\u00e0.<br>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Cos\u2019\u00e8 esattamente la fibra a multicore?<br><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In termini semplici, una<br> <strong>fibra a multicore<br><\/strong> \u00e8 un singolo filamento di fibra di vetro che contiene pi\u00f9 nuclei indipendenti per la<br> <strong>guida della luce<br><\/strong>, a differenza delle tradizionali<br> <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/it\/knowledge-center\/what-is-single-mode-fiber-and-how-does-it-work\/\"><strong>fibra monomodale (SMF)<\/strong><\/a> or <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/it\/knowledge-center\/om1-om2-om3-om4-om5-multimode-fiber-guide\/\"><strong>le fibre multimodali (MMF)<\/strong><\/a>, che ne possiedono uno solo.<br>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Immaginatela come un\u2019autostrada a pi\u00f9 corsie rispetto a una strada a corsia singola. Ciascun nucleo pu\u00f2 trasportare un canale dati separato in modo simultaneo, aumentando in maniera drastica la<br> <strong>capacit\u00e0 della fibra<\/strong> and <strong>densit\u00e0 spaziale<br><\/strong> senza incrementare le dimensioni fisiche del cavo.<br>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Perch\u00e9 la fibra a multicore rappresenta un vero e proprio cambio di gioco? I vantaggi chiave<br><\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/02d147f393544481952c70b097e8daa9.jpg\" alt=\"Multicore Fiber\" class=\"wp-image-5153\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/02d147f393544481952c70b097e8daa9.jpg 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/02d147f393544481952c70b097e8daa9-300x178.jpg 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/02d147f393544481952c70b097e8daa9-1024x608.jpg 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/02d147f393544481952c70b097e8daa9-768x456.jpg 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/02d147f393544481952c70b097e8daa9-18x12.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">I benefici derivanti dall\u2019impiego della<br> <strong>tecnologia MCF<br><\/strong> sono profondi, soprattutto in un\u2019epoca caratterizzata da<br> <strong>applicazioni affamate di larghezza di banda<br><\/strong> come il 5G, l\u2019intelligenza artificiale e l\u2019Internet delle cose (IoT).<br>.<\/p>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p style=\"margin: 0px;\"><strong>Incremento massiccio della capacit\u00e0:<br><\/strong> Questo \u00e8 il vantaggio pi\u00f9 significativo. Grazie alla presenza di pi\u00f9 nuclei (ad esempio 4, 7, 19 o addirittura 32), la MCF pu\u00f2 moltiplicare la capacit\u00e0 di trasmissione dati di una singola fibra di un fattore corrispondente. Ci\u00f2 affronta direttamente il problema dell\u2019<br> <strong>esaurimento delle fibre<br><\/strong> nei condotti congestionati.<br>.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Efficienza spaziale superiore:<br><\/strong> L\u2019installazione di un singolo cavo MCF pu\u00f2 sostituire un fascio di fibre tradizionali mononucleo. Ci\u00f2 consente di risparmiare spazio cruciale nei data center e riduce peso e ingombro nelle applicazioni aerospaziali e navali.<br>.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Ridotto consumo energetico:<\/strong> Trasmettere pi\u00f9 dati attraverso una singola fibra \u00e8 intrinsecamente pi\u00f9 efficiente dal punto di vista energetico rispetto all\u2019alimentazione di pi\u00f9 fibre separate e dei relativi dispositivi elettronici associati, contribuendo cos\u00ec a reti pi\u00f9 ecologiche.<br> <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/it\/knowledge-center\/data-center-interconnect-definition-benefits-and-role-of-optical-modules\/\"><strong>Interconnessione tra data center (DCI)<\/strong><\/a> .<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Preparazione futura delle reti:<br><\/strong> Investire nell\u2019infrastruttura MCF prepara le reti alle esigenze delle generazioni successive, rendendola un pilastro fondamentale per l\u2019<br> <strong>rete ad alta velocit\u00e0<\/strong> and <strong>comunicazione ottica<\/strong> evoluzione.<br>.<\/p><\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Comprendere la MCF nel suo contesto: una tabella comparativa<br><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 fondamentale comprendere che la MCF si differenzia dalle fibre tradizionali per la sua<br> <em>spaziale<\/em> architettura. La seguente tabella chiarisce le principali differenze:<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p>Caratteristica<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/it\/knowledge-center\/what-is-single-mode-fiber-and-how-does-it-work\/\"><strong>Fibra monomodale (SMF)<\/strong><\/a><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/it\/knowledge-center\/om1-om2-om3-om4-om5-multimode-fiber-guide\/\"><strong>Fibra multimodale (MMF)<\/strong><\/a><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>Fibra a multicore (MCF)<br><\/strong><\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Caratteristica definitoria<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Singolo percorso luminoso<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Multipli percorsi luminosi (modi)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p><strong>Multipli core fisici<\/strong><\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Core Count<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Uno<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Uno<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Multipli (ad esempio, 4, 7, 19)<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Vantaggio principale<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>A lunga distanza, con basse perdite<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>A breve distanza, economico<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p><strong>Densit\u00e0 spaziale e capacit\u00e0 estreme<\/strong><\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Tecnologia principale<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Multiplexing per divisione temporale\/longitudinale (TDM\/WDM)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p\/><\/td><td colspan=\"1\" rowspan=\"1\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/it\/glossary\/space-division-multiplexing-modern-fiber-network-capacity-boost\/\"><strong>Multiplexing per divisione spaziale (SDM)<\/strong><\/a><\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Ideale per<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Telecomunicazioni, collegamenti a lunga distanza<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Data center, LAN<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p><strong>Interconnessione tra data center (DCI), calcolo ad alte prestazioni (HPC), superamento dell\u2019esaurimento delle fibre<\/strong><\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Applicazioni pratiche della tecnologia MCF<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dove vedremo l\u2019impatto della MCF?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Interconnessioni tra data center <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/it\/knowledge-center\/data-center-interconnect-definition-benefits-and-role-of-optical-modules\/\"><strong>(DCI)<\/strong><\/a><strong>:<\/strong> Con la crescita dei data center, il <strong>cablaggio in fibra<\/strong> tra di essi diventa un collo di bottiglia. La MCF \u00e8 la soluzione definitiva per trasferire quantit\u00e0 colossali di dati tra strutture.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>High-Performance Computing <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/it\/glossary\/what-is-hpc-high-performance-computing\/\"><strong>(HPC)<\/strong><\/a><strong>:<\/strong> I supercomputer richiedono collegamenti tra nodi con latenza ultra-bassa e larghezza di banda elevata. La MCF fornisce il \u201csistema nervoso interno\u201d per il calcolo exascale.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Cavi sottomarini:<\/strong> Installare nuovi cavi transoceanici \u00e8 estremamente costoso. La MCF consente un potenziamento massivo della capacit\u00e0 all\u2019interno dei design esistenti di cavi.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Aerospaziale e aviazione:<\/strong> Il risparmio di peso e spazio \u00e8 fondamentale su aerei e satelliti, dove ogni grammo conta.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Sfruttare il potenziale: il ruolo cruciale dei transceiver ottici<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/f376ba9bffdf47ffbbacb31b1311bb6d.webp\" alt=\"optical transceivers\" class=\"wp-image-5154\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/f376ba9bffdf47ffbbacb31b1311bb6d.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/f376ba9bffdf47ffbbacb31b1311bb6d-300x169.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/f376ba9bffdf47ffbbacb31b1311bb6d-1024x576.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/f376ba9bffdf47ffbbacb31b1311bb6d-768x432.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/f376ba9bffdf47ffbbacb31b1311bb6d-18x10.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La fibra stessa rappresenta solo met\u00e0 del discorso. Per sfruttare la potenza della MCF, sono necessari avanzati <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\"><strong>trasceivers ottici<\/strong><\/a> progettato specificamente per <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/it\/glossary\/space-division-multiplexing-modern-fiber-network-capacity-boost\/\"><strong>multiplexing per divisione spaziale (SDM)<\/strong><\/a>. Questi transceiver devono lanciare efficientemente la luce in ciascun core individuale e riceverla da esso con perdite minime. <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/it\/glossary\/crosstalk-definition-causes-types-effects\/\"><strong>diafonia<\/strong><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 qui che entra in gioco l\u2019ingegneria di precisione. Marchi come <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/it\/glossary\/crosstalk-definition-causes-types-effects\/\"><strong>LINK-PP<\/strong><\/a> sono in prima linea nello sviluppo di transceiver che si interfacciano senza soluzione di continuit\u00e0 con l\u2019infrastruttura MCF. Ad esempio, il <strong>LINK-PP <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-26045-400g-qsfp-dd-osfp-qsfp112.htm\"><strong>QSFP-DD 400G<\/strong> <strong>trasceivers<\/strong><\/a> \u00e8 progettato per fornire velocit\u00e0 fino a 400 Gbps sfruttando una fibra MCF a 4 core, offrendo una soluzione compatta ed energeticamente efficiente per i <strong>data center 400G<\/strong> di nuova generazione. Quando si cerca il miglior <strong>transceiver ottico per fibra multicore<\/strong>, valutare un modello ad alte prestazioni come questo \u00e8 fondamentale per l\u2019integrit\u00e0 del sistema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per applicazioni specifiche che richiedono densit\u00e0 estrema, esplorare <strong>transceiver OSFP 800G per fibra multicore<\/strong> potrebbe essere il passo successivo, rendendo la propria rete pronta per le future esigenze ancora pi\u00f9 elevate.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Il futuro \u00e8 multicore<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span class=\"qc-p1-tag\" style=\"color: rgb(15, 17, 21);\">Sebbene le sfide come la standardizzazione<br> <\/span><span class=\"qc-p1-tag\"><strong>connettori<\/strong><\/span><span class=\"qc-p1-tag\" style=\"color: rgb(15, 17, 21);\"> e i costi rimangano, la traiettoria \u00e8 chiara.<br>. <\/span><span class=\"qc-p1-tag\"><strong>fibra a multicore<br><\/strong><\/span><span class=\"qc-p1-tag\" style=\"color: rgb(15, 17, 21);\"> non \u00e8 solo un esperimento di laboratorio; \u00e8 una tecnologia commercialmente valida che risponde alla richiesta di maggiore larghezza di banda, minor ingombro e maggiore efficienza. Mentre<br> <\/span><span class=\"qc-p1-tag\"><strong>SDM<\/strong><\/span><span class=\"qc-p1-tag\" style=\"color: rgb(15, 17, 21);\"> e le fibre a multicore (MCF) continuano a evolversi, formeranno indubbiamente la spina dorsale dell\u2019infrastruttura digitale futura del mondo.<br>.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd FAQ<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >Che cosa rende la fibra a multicore diversa dalla fibra normale?<br><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La fibra a multicore ha molti core in un unico cavo. Ogni core trasmette il proprio segnale. La fibra normale ne ha soltanto uno. La fibra a multicore consente il trasferimento simultaneo di una quantit\u00e0 maggiore di dati. Si ottengono velocit\u00e0 pi\u00f9 elevate e maggiore spazio per i dati.<br>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Quali vantaggi offre l\u2019uso della fibra a multicore?<br><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si ottiene una larghezza di banda maggiore e download pi\u00f9 veloci. Sono disponibili pi\u00f9 canali per i dati. La fibra a multicore riduce ingombro e costi. \u00c8 possibile collegare contemporaneamente un numero maggiore di dispositivi. Streaming e download sono pi\u00f9 fluidi.<br>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Quali settori utilizzano maggiormente la fibra a multicore?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La fibra multicore \u00e8 utilizzata nei cavi sottomarini e nei data center. Anche gli ospedali la utilizzano per trasferire dati velocemente. Questi luoghi necessitano di connessioni robuste e rapide. La fibra multicore consente di inviare pi\u00f9 informazioni senza attese.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Quali sfide si incontrano con la fibra multicore?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Potrebbe essere necessario acquistare nuovi dispositivi per la fibra multicore. Pu\u00f2 risultare difficile collegare le reti obsolete alla nuova fibra. Gli ingegneri stanno lavorando per risolvere questi problemi. Il loro obiettivo \u00e8 rendere la fibra multicore pi\u00f9 accessibile a tutti.<\/p>","protected":false},"excerpt":{"rendered":"<p>Discover how Multicore Fiber (MCF) and Space-Division Multiplexing (SDM) are solving the bandwidth crisis. Learn about MCF applications and how LINK-PP&#8217;s optical transceivers harness its power.<\/p>","protected":false},"author":1,"featured_media":5152,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[26],"class_list":["post-5155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowledge-center","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/it\/wp-json\/wp\/v2\/posts\/5155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/it\/wp-json\/wp\/v2\/comments?post=5155"}],"version-history":[{"count":4,"href":"https:\/\/resourceslp.szlogic.cn\/it\/wp-json\/wp\/v2\/posts\/5155\/revisions"}],"predecessor-version":[{"id":11161,"href":"https:\/\/resourceslp.szlogic.cn\/it\/wp-json\/wp\/v2\/posts\/5155\/revisions\/11161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/it\/wp-json\/wp\/v2\/media\/5152"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/it\/wp-json\/wp\/v2\/media?parent=5155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/it\/wp-json\/wp\/v2\/categories?post=5155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/it\/wp-json\/wp\/v2\/tags?post=5155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}