{"id":6607,"date":"2025-07-01T09:13:38","date_gmt":"2025-07-01T09:13:38","guid":{"rendered":"https:\/\/lp.szlogic.cn\/glossary\/through-hole-reflow-soldering-process\/"},"modified":"2026-06-22T09:22:38","modified_gmt":"2026-06-22T09:22:38","slug":"through-hole-reflow-soldering-process","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/fr\/glossary\/through-hole-reflow-soldering-process","title":{"rendered":"Qu\u2019est-ce que le soudage par reflow \u00e0 travers-trou et comment fonctionne-t-il ?"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/38595c55e1b241ab9884b65331c6903b.webp\" alt=\"What is Through\u2011Hole Reflow Soldering and How Does It Work\" class=\"wp-image-6604\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/38595c55e1b241ab9884b65331c6903b.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/38595c55e1b241ab9884b65331c6903b-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/38595c55e1b241ab9884b65331c6903b-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/38595c55e1b241ab9884b65331c6903b-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/38595c55e1b241ab9884b65331c6903b-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le soudage par reprise \u00e0 travers trou, \u00e9galement appel\u00e9 \u00ab pin-in-paste \u00bb ou soudage intrusif, permet de souder simultan\u00e9ment des composants \u00e0 montage traversant et des composants \u00e0 montage en surface dans un seul cycle de reprise. <strong>Soudage par reprise \u00e0 travers trou (THR)<\/strong> offre pr\u00e9cis\u00e9ment cela : un proc\u00e9d\u00e9 hybride qui allie la robustesse de <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/glossary\/what-is-tht-through-hole-technology\/\">la technologie \u00e0 montage traversant (THT)<\/a> \u00e0 la rapidit\u00e9 et \u00e0 l\u2019automatisation de <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/glossary\/what-does-smt-surface-mount-technology-mean\/\">la technologie \u00e0 montage en surface (SMT)<\/a>. Cette m\u00e9thode s\u2019int\u00e8gre parfaitement aux lignes d\u2019assemblage SMT. Selon les rapports du march\u00e9, le soudage par reprise, y compris pour les applications \u00e0 montage traversant, accro\u00eet l\u2019efficacit\u00e9 et conna\u00eet une utilisation croissante dans la fabrication \u00e9lectronique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >Contexte : Pourquoi le THR est important<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>La THT (technologie \u00e0 montage traversant)<\/strong> consiste \u00e0 ins\u00e9rer les broches des composants dans les trous de la carte de circuit imprim\u00e9 (PCI) et \u00e0 les souder depuis la face inf\u00e9rieure. Cette m\u00e9thode assure <strong>des interconnexions m\u00e9caniques solides<\/strong>, id\u00e9ales pour les connecteurs, les composants de puissance ou les environnements soumis \u00e0 de fortes contraintes m\u00e9caniques.<\/p><\/li><li><p><strong>La SMT (technologie \u00e0 montage en surface)<\/strong> place les composants sur la surface de la carte \u00e0 l\u2019aide de p\u00e2te \u00e0 souder, puis les fait fondre dans un four \u2014 une m\u00e9thode efficace, pr\u00e9cise et adapt\u00e9e \u00e0 la miniaturisation.<\/p><\/li><li><p><strong>Le THR<\/strong> combine les deux approches : les composants con\u00e7us selon la norme THT sont adapt\u00e9s au soudage par reprise, aux c\u00f4t\u00e9s des composants SMT, permettant ainsi un flux de production unique et simplifi\u00e9, sans recourir au soudage par vague.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >Aper\u00e7u du proc\u00e9d\u00e9 THR<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le soudage par reprise \u00e0 travers trou s\u2019int\u00e8gre parfaitement aux lignes de production SMT standard. Le flux de travail typique comprend les \u00e9tapes suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>\u00c9tape 1 :<\/strong> La carte de circuit imprim\u00e9 est fabriqu\u00e9e avec des<strong> trous m\u00e9tallis\u00e9s (PTH)<\/strong>, garantissant une m\u00e9tallisation ad\u00e9quate pour le soudage.<\/p><\/li><li><p><strong>\u00c9tape 2 :<\/strong> Sur la ligne SMT, la carte est positionn\u00e9e sous un pochoir \u00e0 p\u00e2te \u00e0 souder en pr\u00e9paration de l\u2019impression.<\/p><\/li><li><p><strong>\u00c9tapes 3\u20134 :<\/strong> Lors de l\u2019\u00e9tape d\u2019impression de la p\u00e2te \u00e0 souder, celle-ci est d\u00e9pos\u00e9e via le pochoir, recouvrant \u00e0 la fois les pastilles de montage en surface et p\u00e9n\u00e9trant partiellement dans les PTH.<\/p><\/li><li><p><strong>\u00c9tapes 5\u20136 :<\/strong> Les composants sont plac\u00e9s \u00e0 l\u2019aide d\u2019une machine automatis\u00e9e de pr\u00e9l\u00e8vement et de pose. <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/search\/?keyword=SMD\">Dispositifs \u00e0 montage en surface (SMD)<\/a> sont positionn\u00e9s en premier. Si la machine n\u2019est pas capable de placer les composants \u00e0 montage traversant, ceux-ci sont ins\u00e9r\u00e9s manuellement apr\u00e8s les composants CMS. Les broches traversent les trous remplis de p\u00e2te \u00e0 souder, o\u00f9 une partie de la p\u00e2te adh\u00e8re aux broches, tandis que la majeure partie reste \u00e0 l\u2019int\u00e9rieur des trous.<\/p><\/li><li><p><strong>\u00c9tapes 7\u20138 :<\/strong> La carte entre ensuite dans le four de refusion. \u00c0 mesure que la temp\u00e9rature augmente, la p\u00e2te \u00e0 souder fond et s\u2019\u00e9coule autour des broches des composants et dans les parois des trous m\u00e9tallis\u00e9s. Une liaison solder fiable se forme gr\u00e2ce \u00e0 la cr\u00e9ation d\u2019un compos\u00e9 interm\u00e9tallique (CIM) entre la broche du composant, la soudure et le placage cuivre \u00e0 l\u2019int\u00e9rieur du trou.<\/p><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"667\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/b65b80309a1442debbe84f9a526ffbc2.webp\" alt=\"THR Process\" class=\"wp-image-6605\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/b65b80309a1442debbe84f9a526ffbc2.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/b65b80309a1442debbe84f9a526ffbc2-300x167.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/b65b80309a1442debbe84f9a526ffbc2-1024x569.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/b65b80309a1442debbe84f9a526ffbc2-768x427.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/b65b80309a1442debbe84f9a526ffbc2-18x10.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ce processus rationalis\u00e9 permet de souder simultan\u00e9ment les composants CMS et \u00e0 montage traversant lors d\u2019un seul cycle de refusion, r\u00e9duisant ainsi les \u00e9tapes de fabrication tout en garantissant des liaisons m\u00e9caniques et \u00e9lectriques robustes \u2014 particuli\u00e8rement importantes pour les composants \u00e0 haute fiabilit\u00e9, tels que les connecteurs RJ45 compatibles THR de LINK-PP.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >Avantages du THR<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>Int\u00e9grit\u00e9 m\u00e9canique<\/strong><br\/>Les broches \u00e0 montage traversant s\u2019ancrent dans la carte, fixant fermement les composants plus volumineux ou soumis \u00e0 de fortes contraintes \u2014 comme les connecteurs RJ45 \u2014 contre les vibrations et les manipulations.<\/p><\/li><li><p><strong>Assemblage en une seule \u00e9tape<\/strong><br\/>Le THR \u00e9limine la soudure par vague, permettant de traiter conjointement les composants CMS et THR sur la ligne de refusion \u2014 ce qui permet de gagner du temps, de r\u00e9duire la main-d\u2019\u0153uvre et de diminuer les co\u00fbts.<\/p><\/li><li><p><strong>\u00c9volutivit\u00e9<\/strong><br\/>En tirant parti des lignes automatis\u00e9es CMS, le THR convient aussi bien aux petites qu\u2019aux grandes s\u00e9ries de production \u2014 id\u00e9al pour les prestataires EMS et les fabricants OEM \u00e0 volumes mixtes.<\/p><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\" >Consid\u00e9rations de conception et bonnes pratiques<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La r\u00e9ussite du THR d\u00e9pend d\u2019une conception r\u00e9fl\u00e9chie de la carte de circuit imprim\u00e9 et des composants :<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" >Exigences relatives aux composants<\/h4>\n\n\n\n<h4 class=\"wp-block-heading\" >Les mat\u00e9riaux doivent r\u00e9sister aux temp\u00e9ratures de refusion (g\u00e9n\u00e9ralement jusqu\u2019\u00e0 260\u202f\u00b0C). Les connecteurs RJ45 PoE+ <strong>LPJG0926HENLS4R de LINK\u2011PP<\/strong> utilisent des thermoplastiques \u00e0 haute temp\u00e9rature et des broches optimis\u00e9es pour le THR.<\/h4>\n\n\n\n<h4 class=\"wp-block-heading\" >Conception de l\u2019espace libre et des broches<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Un espace libre par rapport \u00e0 la carte permet \u00e0 la p\u00e2te de remonter par capillarit\u00e9 et am\u00e9liore la circulation de l\u2019air. La longueur des broches doit \u00eatre soigneusement calibr\u00e9e : trop longue, elle provoque des d\u00e9fauts dus \u00e0 l\u2019extrusion de p\u00e2te ; trop courte, les liaisons ne r\u00e9pondent pas aux crit\u00e8res IPC\u2011610.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" >Conception du pochoir \u00e0 p\u00e2te<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Assurez-vous que la p\u00e2te remplit correctement les trous : une p\u00e2te \u00e0 haute viscosit\u00e9 permet de remplir les trous et d\u2019\u00e9viter les vides, comme recommand\u00e9 dans<br> <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/\">LIEN\u2011PP<\/a>\u2019la documentation technique de soutien THR de <em>&#8217;s<\/em>.<br> .<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" >Profil de refusion<br><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Utilisez une courbe contr\u00f4l\u00e9e de mont\u00e9e en temp\u00e9rature\u2013palier\u2013pic\u2013refroidissement. Assurez-vous que la p\u00e2te atteint la temp\u00e9rature liquidus, ce qui active le flux et \u00e9vite tout choc thermique aux composants.<br>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" >Inspection et normes<br><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Finalisez le contr\u00f4le qualit\u00e9 \u00e0 l\u2019aide de l\u2019inspection optique automatis\u00e9e (AOI), de la radiographie X et des crit\u00e8res IPC-610. Les joints THR doivent pr\u00e9senter une couverture de soudure \u2265 75\u202f% avec &lt; 30\u202f% de vides.<br>.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\" >\ud83d\udce6 Connecteurs LINK-PP pr\u00eats pour THR<br><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">LINK-PP con\u00e7oit plusieurs connecteurs RJ45 compatibles avec la technologie THR, notamment le<br> <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/478673.htm\"><strong>LPJG0926HENLS4R<br><\/strong><\/a><strong> RJ45 PoE+<br><\/strong>dot\u00e9s de :<br><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>un bo\u00eetier r\u00e9sistant aux hautes temp\u00e9ratures (PA46 + 30\u202f% de verre)<br><\/strong> capable de supporter une refusion \u00e0 260\u202f\u00b0C pendant 10\u202fs.<br>.<\/p><\/li><li><p><strong>une hauteur de support de 1,25\u202fmm<br><\/strong> permettant une circulation d\u2019air optimale et un \u00e9coulement ad\u00e9quat de la p\u00e2te.<br>.<\/p><\/li><li><p><strong>une longueur de broche de 2,40\u202fmm<br><\/strong> adapt\u00e9e aux cartes PCB standard de 1,6\u202fmm.<br>.<\/p><\/li><li><p><strong>Une compatibilit\u00e9 avec les p\u00e2tes \u00e0 haute viscosit\u00e9<br><\/strong>, r\u00e9duisant les vides et am\u00e9liorant la fiabilit\u00e9 des joints.<br>.<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ces caract\u00e9ristiques garantissent que les connecteurs THR de LINK-PP r\u00e9pondent aux exigences de la norme IPC-610, offrant une grande durabilit\u00e9 et de solides performances \u00e9lectriques dans des environnements s\u00e9v\u00e8res.<br>.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h2 class=\"wp-block-heading\" > Applications typiques<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>R\u00e9seaux et t\u00e9l\u00e9communications<\/strong>: Les ports RJ45 haute densit\u00e9 profitent de la stabilit\u00e9 m\u00e9canique offerte par la technologie THR ainsi que de la rapidit\u00e9 des lignes de montage SMT.<br>.<\/p><\/li><li><p><strong>Industrie et automobile<br><\/strong>: La r\u00e9sistance aux vibrations et la tol\u00e9rance aux fortes intensit\u00e9s de courant sont parfaitement compatibles avec les avantages de la technologie THR.<br>.<\/p><\/li><li><p><strong>Services de fabrication \u00e9lectronique (EMS) et production \u00e0 grande \u00e9chelle<br><\/strong>: Un seul passage en four \u00e0 reflow augmente le d\u00e9bit de production et r\u00e9duit les d\u00e9penses en capital.<br>.<\/p><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h2 class=\"wp-block-heading\" >Comparaison synth\u00e9tique : THR vs. THT vs. SMT<br><\/h2>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"width: 180px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p>Technologie<\/p><\/th><th colspan=\"1\" rowspan=\"1\" colwidth=\"180\"><p>Assembly Method<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Strengths<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Limitations<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>THT<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"180\"><p>Plombages + soudage par vague<br><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Joints m\u00e9caniques extr\u00eamement robustes<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Main-d\u2019\u0153uvre manuelle, pas d\u2019int\u00e9gration SMT<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>SMT<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"180\"><p>P\u00e2te + reflow<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Compact, rapide et automatis\u00e9<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Moins de r\u00e9sistance m\u00e9canique<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Le THR<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"180\"><p>P\u00e2te + reflow (trou)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Efficacit\u00e9 m\u00e9canique et automatis\u00e9e<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>N\u00e9cessite des composants homologu\u00e9s THR et des ajustements du proc\u00e9d\u00e9<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" >Pourquoi choisir le THR ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le THR \u00e9tablit un \u00e9quilibre convaincant : il conserve la r\u00e9silience m\u00e9canique des montages \u00e0 travers-trou tout en tirant parti du proc\u00e9d\u00e9 de reflow rapide et automatis\u00e9 de la technologie SMT. Pour les cartes de circuits imprim\u00e9s comportant plusieurs composants \u2014 notamment celles int\u00e9grant des connecteurs lourds tels que <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-17492-integrated-rj45-connector.htm\">RJ45<\/a>\u2014 le THR constitue le choix strat\u00e9gique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous utilisez <strong>la s\u00e9rie RJ45 optimis\u00e9e pour le THR de LINK\u2011PP<\/strong>, vous garantissez un brasage fiable, une qualit\u00e9 constante et des flux de production rationalis\u00e9s \u2014 le tout soutenu par une conception rigoureuse et des normes certifi\u00e9es par l\u2019industrie.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\" >\ud83c\udfc1 Conclusion<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Soudage par reprise \u00e0 travers trou (THR)<\/strong> est une technologie de soudure hybride tourn\u00e9e vers l\u2019avenir qui offre le meilleur des deux mondes : <strong>des joints m\u00e9caniques durables et un assemblage SMT \u00e0 haute efficacit\u00e9<\/strong>. En concevant sp\u00e9cifiquement pour le THR \u2014 au niveau des composants, des cartes de circuits imprim\u00e9s, des p\u00e2tes et des proc\u00e9d\u00e9s \u2014 les fabricants peuvent r\u00e9duire leurs co\u00fbts, am\u00e9liorer leurs rendements et offrir une fiabilit\u00e9 accrue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chez LINK\u2011PP, les composants compatibles THR incarnent cette philosophie. Du choix des mat\u00e9riaux \u00e0 la g\u00e9om\u00e9trie des entretoises et \u00e0 la compatibilit\u00e9 avec les p\u00e2tes, chaque d\u00e9tail favorise un proc\u00e9d\u00e9 de reflow plus fluide et des produits finaux plus solides. D\u00e9couvrez les solutions THR de LINK\u2011PP \u2014 con\u00e7ues pour la performance, pens\u00e9es pour l\u2019industrialisation et pr\u00eates pour les environnements exigeants de demain.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >FAQ<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >Quel est l\u2019avantage principal du brasage \u00e0 travers-trou par reflow ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez souder simultan\u00e9ment des composants \u00e0 travers-trou et des composants mont\u00e9s en surface dans un seul et m\u00eame proc\u00e9d\u00e9. Cette m\u00e9thode permet de gagner du temps et d\u2019accro\u00eetre l\u2019efficacit\u00e9 de votre cha\u00eene de montage.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Quels types de composants conviennent le mieux au brasage \u00e0 travers-trou par reflow ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous devez utiliser des composants capables de supporter des temp\u00e9ratures \u00e9lev\u00e9es. La plupart des connecteurs, interrupteurs et condensateurs de grande capacit\u00e9 fonctionnent bien avec ce proc\u00e9d\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Que se passe-t-il si vous appliquez trop peu de p\u00e2te \u00e0 souder ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous risquez d\u2019obtenir des joints faibles ou un remplissage incomplet des trous. V\u00e9rifiez toujours le volume de p\u00e2te afin d\u2019assurer des liaisons soud\u00e9es solides et fiables.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >Voir aussi<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/glossary\/what-is-tht-through-hole-technology\/\">Guide complet sur la technologie \u00e0 travers-trou expliqu\u00e9e<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/glossary\/understanding-surface-mount-device-smd\/\">Exploration des dispositifs mont\u00e9s en surface et de leur r\u00f4le dans l\u2019\u00e9lectronique<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/glossary\/what-does-smt-surface-mount-technology-mean\/\">D\u00e9cryptage de la signification et de l\u2019importance de la technologie SMT<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Le soudage par reflow \u00e0 travers-trou permet la soudure simultan\u00e9e des composants \u00e0 montage traversant et des composants \u00e0 montage en surface dans un seul processus de reflow efficace.<\/p>","protected":false},"author":1,"featured_media":6606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[27],"tags":[22],"class_list":["post-6607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-glossary","tag-integrated-rj45-connectors"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/6607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/comments?post=6607"}],"version-history":[{"count":7,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/6607\/revisions"}],"predecessor-version":[{"id":11440,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/6607\/revisions\/11440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/media\/6606"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/media?parent=6607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/categories?post=6607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/tags?post=6607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}