{"id":5357,"date":"2025-08-22T00:00:00","date_gmt":"2025-08-22T00:00:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/knowledge-center\/media-converters-what-they-are-and-how-media-converters-work\/"},"modified":"2026-06-22T08:13:48","modified_gmt":"2026-06-22T08:13:48","slug":"media-converters-what-they-are-and-how-media-converters-work","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/media-converters-what-they-are-and-how-media-converters-work","title":{"rendered":"Convertisseurs de support fibre : Le guide ultime"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/00e0eaeac2cc4e04a2baddf11cca269d.webp\" alt=\"What Are Media Converters\" class=\"wp-image-5355\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/00e0eaeac2cc4e04a2baddf11cca269d.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/00e0eaeac2cc4e04a2baddf11cca269d-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/00e0eaeac2cc4e04a2baddf11cca269d-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/00e0eaeac2cc4e04a2baddf11cca269d-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/00e0eaeac2cc4e04a2baddf11cca269d-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Convertisseurs de support<\/strong> vous permettent de relier diff\u00e9rents c\u00e2bles dans un r\u00e9seau. Vous utilisez un convertisseur de support pour commuter les signaux du cuivre vers la fibre ou entre c\u00e2bles en fibre. Un aper\u00e7u des convertisseurs de support montre que ces dispositifs maintiennent votre r\u00e9seau solide et stable. Les convertisseurs de support fonctionnent avec des connexions en fibre et en fibre dans de nombreux endroits. Vous pouvez trouver diff\u00e9rents types de convertisseurs de support pour <strong>cuivre vers fibre<\/strong> and <strong>liaisons fibre vers fibre<\/strong>. Les convertisseurs de support aident votre r\u00e9seau \u00e0 rester flexible et \u00e0 fonctionner efficacement.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Les convertisseurs de support fonctionnent avec des connexions en fibre et en fibre, ce qui vous permet d\u2019\u00e9tendre facilement votre r\u00e9seau.<\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udca1 Qu\u2019est-ce qu\u2019un convertisseur de support ?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>Convertisseur de support en fibre<\/strong> est un dispositif r\u00e9seau polyvalent qui relie de mani\u00e8re transparente deux types de support diff\u00e9rents \u2014 g\u00e9n\u00e9ralement <strong>c\u00e2ble en cuivre \u00e0 paires torsad\u00e9es<\/strong> (comme Cat6\/Cat7 transportant Ethernet) avec <strong>c\u00e2ble en fibre optique<\/strong>. Il agit comme un traducteur, garantissant une transmission fluide des donn\u00e9es entre une infrastructure en cuivre <strong>r\u00e9seau local (LAN)<\/strong> et le r\u00e9seau principal haute vitesse et haut d\u00e9bit en fibre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sans convertisseurs de support, les organisations seraient confront\u00e9es \u00e0 des d\u00e9fis et \u00e0 des co\u00fbts importants pour mettre \u00e0 niveau enti\u00e8rement leurs r\u00e9seaux vers la fibre optique d\u2019un seul coup. Ce sont la solution id\u00e9ale <strong>solution \u00e9conomique<\/strong> pour la migration et l\u2019extension du r\u00e9seau.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udca1 Pourquoi utiliser un convertisseur de support ? Les avantages cl\u00e9s<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Distance \u00e9tendue :<\/strong> L\u2019Ethernet sur cuivre (comme 10\/100\/1000BASE-T) est limit\u00e9 \u00e0 100 m\u00e8tres. La fibre optique peut transmettre des donn\u00e9es sur des <strong>kilom\u00e8tres<\/strong> sans d\u00e9gradation du signal. Les convertisseurs de support comblent cet \u00e9cart.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Immunit\u00e9 renforc\u00e9e :<\/strong> La fibre est insensible aux <strong>Interf\u00e9rences \u00e9lectromagn\u00e9tiques<\/strong> <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/glossary\/what-is-electromagnetic-interference\/\"><strong>(EMI)<\/strong><\/a> and <strong>interf\u00e9rences \u00e9lectromagn\u00e9tiques (RFI) <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/glossary\/rfi-radio-frequency-interference-causes-effects-solutions\/\"><strong>(IRF)<\/strong><\/a>, ce qui le rend id\u00e9al pour les environnements industriels s\u00e9v\u00e8res.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Bande passante accrue et \u00e9volutivit\u00e9 :<\/strong> Ils vous permettent de tirer parti de la haute bande passante de la fibre pour prendre en charge des applications exigeantes telles que le streaming vid\u00e9o HD et les transferts massifs de donn\u00e9es.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>\u00c9conomies de co\u00fbts :<\/strong> Prot\u00e9gez votre investissement dans les \u00e9quipements existants bas\u00e9s sur le cuivre tout en adoptant progressivement la technologie fibre.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udca1 Types de convertisseurs de support : choisir le bon mod\u00e8le<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/60547928026a4932befdeafadb306159.webp\" alt=\"fiber media converter\" class=\"wp-image-5356\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/60547928026a4932befdeafadb306159.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/60547928026a4932befdeafadb306159-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/60547928026a4932befdeafadb306159-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/60547928026a4932befdeafadb306159-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/60547928026a4932befdeafadb306159-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Les convertisseurs de support existent sous diverses formes adapt\u00e9es \u00e0 des besoins vari\u00e9s. Voici un aper\u00e7u rapide :<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p><strong>Fonctionnalit\u00e9<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>Convertisseur autonome \/ de bureau<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>Ch\u00e2ssis \/ convertisseur g\u00e9r\u00e9<\/strong><\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Id\u00e9al pour<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Petites entreprises, liaisons point \u00e0 point<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Centres de donn\u00e9es, grandes entreprises<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Densit\u00e9 de ports<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Faible (1 \u00e0 2 conversions)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u00c9lev\u00e9e (modulaire, 4 \u00e0 16+ emplacements)<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Gestion<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Non g\u00e9r\u00e9 \/ interface web simple<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Enti\u00e8rement g\u00e9r\u00e9 (SNMP, VLAN, QoS)<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>\u00c9volutivit\u00e9<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Faible<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>High<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Cas d\u2019utilisation<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Connexion entre deux b\u00e2timents<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Agr\u00e9gation centralis\u00e9e du r\u00e9seau<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">D\u2019autres types importants incluent les <strong>convertisseurs de support PoE<\/strong> (qui transmettent \u00e0 la fois des donn\u00e9es et de l\u2019\u00e9nergie \u00e0 des dispositifs tels que des cam\u00e9ras IP via la fibre) et les mod\u00e8les prenant en charge diff\u00e9rents <strong>modes de fibre <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/difference-between-fibers-single-mode-vs-multimode-guide\/\"><strong>(monomode vs multimode)<\/strong><\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udca1 Comment choisir le meilleur convertisseur de support en fibre adapt\u00e9 \u00e0 vos besoins<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le choix du convertisseur appropri\u00e9 d\u00e9pend de plusieurs facteurs. Posez-vous ces questions :<\/p>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p style=\"margin: 0px;\"><strong>Quel d\u00e9bit ai-je besoin ?<\/strong> (Fast Ethernet 100 Mbps, Gigabit 1 Gbps, 10 Gigabit ?)<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Quel type de fibre j\u2019utilise ?<\/strong> (monomode <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/what-is-single-mode-fiber-and-how-does-it-work\/\"><strong>(SMF)<\/strong><\/a> pour de longues distances ou multimode <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/om1-om2-om3-om4-om5-multimode-fiber-guide\/\"><strong>(MMF)<\/strong><\/a> pour de courtes distances ?)<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Quel type de connecteur est pr\u00e9sent sur ma fibre ?<\/strong> (SFP, SFP+, SFP28 ou port fixe ?)<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Ai-je besoin de fonctionnalit\u00e9s de gestion ?<\/strong> (Pour surveiller et configurer le r\u00e9seau \u00e0 distance)<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Quel est l\u2019environnement d\u2019exploitation ?<\/strong> (Bureau standard ou environnement industriel robuste ?)<\/p><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Pour des performances optimales et une compatibilit\u00e9 parfaite, assurez-vous toujours que votre convertisseur est associ\u00e9 \u00e0 des <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\"><strong>\u00e9metteurs-r\u00e9cepteurs optiques<\/strong><\/a>. C\u2019est ici qu\u2019une marque fiable comme <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.link-pp.com\/\"><strong>LIEN-PP<\/strong><\/a> excelle, en proposant des convertisseurs parfaitement appari\u00e9s et des <strong>modules SFP compatibles<\/strong> pour une exp\u00e9rience sans tracas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par exemple, une solution populaire pour une liaison Gigabit sur de longues distances est un convertisseur de support autonome coupl\u00e9 \u00e0 un <strong>LIEN-PP <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/476763.htm\"><strong>SFP-1G-LX<\/strong><\/a> module \u00e9metteur-r\u00e9cepteur pour fibre monomode.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udca1 LINK-PP : Votre partenaire en connectivit\u00e9 r\u00e9seau<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">At <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/page\/aboutus.htm\"><strong>LIEN-PP<\/strong><\/a>, nous comprenons le r\u00f4le critique d\u2019une connectivit\u00e9 fiable. Notre gamme de <strong>convertisseurs de support industriels<\/strong> and <strong>haute performance compatibles <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\"><strong>\u00e9metteurs-r\u00e9cepteurs optiques<\/strong><\/a> est con\u00e7ue pour la durabilit\u00e9 et l\u2019int\u00e9gration transparente. Que vous recherchiez un <strong>convertisseur de support g\u00e9r\u00e9<\/strong> pour un contr\u00f4le pr\u00e9cis ou un simple <strong>convertisseur Ethernet non g\u00e9r\u00e9 vers fibre<\/strong> pour une liaison basique, nous avons la solution adapt\u00e9e.<\/p>\n\n\n\n<div class=\"alignnone qc-cover-wrapper has-custom-content-position is-position-center\" elementtype=\"div\" useimagebackground=\"false\" imgbg=\"\" imgbgpositionleft=\"50\" imgbgpositiontop=\"50\" overlay=\"#165DFF\" overlayopacity=\"0.8\" contentposition=\"center\" alt=\"\" parallax=\"false\" style=\"border-radius: 12px; padding-left: var(--qc-preset--spacing--60); padding-right: var(--qc-preset--spacing--60); padding-top: var(--qc-preset--spacing--40); padding-bottom: var(--qc-preset--spacing--40); background-color: rgb(245, 245, 245); height: auto;\"><div class=\"qc-cover-wrapper__inner-container\"><div style=\"flex-wrap: wrap; justify-content: center; display: flex;\"><div colmd=\"10\" class=\"col col-md-10\"><p style=\"text-align: center;\"><span class=\"qc-h1-tag\" style=\"color: var(--qc-color5);\">LIEN-PP<\/span><\/p><p style=\"text-align: center;\"><span class=\"qc-p1-tag\" style=\"color: var(--qc-color5);\">se sp\u00e9cialise dans la fourniture de solutions \u00e9conomiques en fibre optique<\/span><\/p><div class=\"qc-buttons-wrapper\"><div justification=\"center\" class=\"qc-buttons-container is-horizontal is-content-justification-center\" style=\"margin-top: var(--qc-preset--spacing--0); margin-bottom: var(--qc-preset--spacing--0); gap: var(--qc-preset--spacing--40);\"><div link=\"https:\/\/www.l-p.com\/\" opennewtab=\"true\" width=\"\" outline=\"false\" class=\"qc-button-wrapper\" style=\"background-color: rgb(248, 249, 250);\"><a class=\"qc-button-container\" href=\"https:\/\/www.l-p.com\/\" target=\"_blank\"><span style=\"color: rgb(85, 75, 223);\"><strong>En savoir plus  <\/strong><\/span><span style=\"color: rgb(85, 75, 223);\"><strong>\u27a1\ufe0f<\/strong><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udca1 FAQ<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >\u00c0 quoi sert un convertisseur de support ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un convertisseur de support permet \u00e0 diff\u00e9rents c\u00e2bles de communiquer entre eux. Vous pouvez l\u2019utiliser pour relier des c\u00e2bles en cuivre \u00e0 des c\u00e2bles en fibre. Il permet \u00e9galement de relier diff\u00e9rents c\u00e2bles en fibre entre eux. Cela aide votre r\u00e9seau \u00e0 connecter de nombreux types de dispositifs.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Quels types de convertisseurs de support pouvez-vous trouver ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il existe des convertisseurs de support cuivre vers fibre, fibre vers fibre, PoE, g\u00e9r\u00e9s, non g\u00e9r\u00e9s et industriels. Chacun convient \u00e0 certaines t\u00e2ches ou \u00e0 des emplacements sp\u00e9cifiques dans un r\u00e9seau.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Quels dispositifs pouvez-vous connecter \u00e0 l\u2019aide d\u2019un convertisseur de support ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez relier des ordinateurs, des commutateurs, des cam\u00e9ras, des t\u00e9l\u00e9phones et des capteurs. Les convertisseurs de support permettent aux anciens dispositifs Ethernet de fonctionner avec les nouveaux \u00e9quipements en fibre.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Pourquoi la fibre est-elle meilleure sur de longues distances ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les c\u00e2bles en fibre utilisent la lumi\u00e8re pour transmettre des donn\u00e9es. Ils conservent les signaux puissants et rapides sur de longues distances. Les c\u00e2bles en cuivre perdent rapidement leur signal, tandis que les c\u00e2bles en fibre fonctionnent efficacement m\u00eame \u00e0 grande distance.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Que devez-vous v\u00e9rifier avant d\u2019acheter un convertisseur de support ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Examinez vos types de c\u00e2bles, vos styles de connecteurs, la vitesse de votre r\u00e9seau et l\u2019emplacement d\u2019installation. Assurez-vous que le convertisseur de support est compatible avec vos dispositifs et qu\u2019il fonctionne dans votre environnement.<\/p>\n\n\n\n<script>const link1 = document.createElement('link');link1.rel = 'stylesheet';link1.type = 'text\/css';link1.href = 'https:\/\/statics.quickcreator.io\/static\/theme\/css\/qcb-theme-additional.css';const link2 = document.createElement('link');link2.rel = 'stylesheet';link2.type = 'text\/css';link2.href = 'https:\/\/statics.quickcreator.io\/static\/aaapycm22qmuab44\/theme\/css\/qcb-main-theme.css';document.head.appendChild(link1);document.head.appendChild(link2);<\/script>","protected":false},"excerpt":{"rendered":"<p>Les convertisseurs de support relient les c\u00e2bles en cuivre et en fibre, en convertissant les signaux pour \u00e9tendre la port\u00e9e du r\u00e9seau et prendre en charge les \u00e9quipements anciens.<\/p>","protected":false},"author":1,"featured_media":5355,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[26],"class_list":["post-5357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowledge-center","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/5357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/comments?post=5357"}],"version-history":[{"count":4,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/5357\/revisions"}],"predecessor-version":[{"id":11231,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/5357\/revisions\/11231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/media\/5355"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/media?parent=5357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/categories?post=5357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/tags?post=5357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}