{"id":5172,"date":"2025-09-08T00:00:00","date_gmt":"2025-09-08T00:00:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/glossary\/tdm-time-division-multiplexing-basics-uses-benefits-guide\/"},"modified":"2026-06-22T07:36:15","modified_gmt":"2026-06-22T07:36:15","slug":"tdm-time-division-multiplexing-basics-uses-benefits-guide","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/fr\/glossary\/tdm-time-division-multiplexing-basics-uses-benefits-guide","title":{"rendered":"Ce que vous devez savoir sur la TDM (multiplexion par r\u00e9partition temporelle)"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5872ba83d31e454f991f1d0e726cfe66.webp\" alt=\"What You Need to Know About TDM Time Division Multiplexing\" class=\"wp-image-5169\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5872ba83d31e454f991f1d0e726cfe66.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5872ba83d31e454f991f1d0e726cfe66-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5872ba83d31e454f991f1d0e726cfe66-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5872ba83d31e454f991f1d0e726cfe66-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5872ba83d31e454f991f1d0e726cfe66-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le vaste monde des t\u00e9l\u00e9communications, d\u00e9placer efficacement d\u2019\u00e9normes quantit\u00e9s de donn\u00e9es est l\u2019objectif ultime. Imaginez une seule route devant accueillir des flux infinis de voitures sans embouteillage. Tel est le d\u00e9fi fondamental du r\u00e9seau. L\u2019une des solutions les plus r\u00e9volutionnaires \u00e0 ce probl\u00e8me est <strong>Multiplexage par r\u00e9partition dans le temps (TDM)<\/strong>. M\u00eame \u00e0 l\u2019\u00e8re du commutateur de paquets, comprendre la multiplexion par r\u00e9partition dans le temps (TDM) est essentiel pour saisir les fondements de la communication num\u00e9rique moderne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce guide d\u00e9mystifiera la TDM, en expliquant son fonctionnement, ses domaines d\u2019application et son r\u00f4le \u00e9volutif aux c\u00f4t\u00e9s des technologies actuelles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Qu\u2019est-ce que la multiplexion par r\u00e9partition dans le temps (TDM) ? Le concept fondamental<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Multiplexage par r\u00e9partition dans le temps (TDM)<\/strong> est une m\u00e9thode permettant de transmettre plusieurs signaux num\u00e9riques ou flux de donn\u00e9es sur un seul canal de communication, en divisant le temps de ce canal en intervalles temporels distincts et r\u00e9p\u00e9titifs. \u00c0 chaque signal d\u2019entr\u00e9e est attribu\u00e9 un intervalle temporel sp\u00e9cifique, et durant cet intervalle, un fragment de ce signal est transmis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pensez-y comme \u00e0 un professeur tr\u00e8s occup\u00e9 qui re\u00e7oit ses \u00e9tudiants pendant ses heures de permanence. Plut\u00f4t que d\u2019avoir des conversations s\u00e9par\u00e9es dans diff\u00e9rentes salles (plusieurs canaux), chaque \u00e9tudiant se voit allouer un cr\u00e9neau r\u00e9p\u00e9titif de 5 minutes. Le professeur (le canal) consacre toute son attention \u00e0 un seul \u00e9tudiant \u00e0 la fois, passant de l\u2019un \u00e0 l\u2019autre de fa\u00e7on fluide.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Comment fonctionne la TDM ? Une analyse \u00e9tape par \u00e9tape<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"521\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/3219d05b8b9a45caadf64000c71f4e18.webp\" alt=\"Time Division Multiplexing\" class=\"wp-image-5170\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/3219d05b8b9a45caadf64000c71f4e18.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/3219d05b8b9a45caadf64000c71f4e18-300x130.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/3219d05b8b9a45caadf64000c71f4e18-1024x445.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/3219d05b8b9a45caadf64000c71f4e18-768x333.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/3219d05b8b9a45caadf64000c71f4e18-18x8.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le processus implique un <strong>multiplexeur (MUX)<\/strong> \u00e0 l\u2019extr\u00e9mit\u00e9 d\u2019\u00e9mission et un <strong>d\u00e9multiplexeur (DEMUX)<\/strong> \u00e0 l\u2019extr\u00e9mit\u00e9 de r\u00e9ception.<\/p>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p style=\"margin: 0px;\"><strong>Signaux d\u2019entr\u00e9e multiples :<\/strong> Plusieurs flux de donn\u00e9es \u00e0 faible d\u00e9bit (par exemple, appels vocaux provenant d\u2019utilisateurs diff\u00e9rents) sont inject\u00e9s dans le multiplexeur.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Attribution des intervalles temporels :<\/strong> Le multiplexeur (MUX) attribue \u00e0 chaque flux d\u2019entr\u00e9e un intervalle temporel fixe et r\u00e9p\u00e9titif. Cette attribution est r\u00e9gul\u00e9e par un signal d\u2019horloge pr\u00e9cis.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Transmission :<\/strong> Le MUX commute rapidement entre ces entr\u00e9es, pr\u00e9levant successivement un petit \u00e9chantillon ou un \u201c octet \u201d de donn\u00e9es de chaque flux et les combinant en un seul flux de <strong>transmission num\u00e9rique<\/strong> \u00e0 haut d\u00e9bit.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>R\u00e9ception :<\/strong> Le signal combin\u00e9 circule sur le support (par exemple, un <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/fiber-optic-cable-what-it-is-and-how-it-works-explained\/\">c\u00e2ble en fibre optique<\/a>).<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Synchronisation et d\u00e9multiplexage :<\/strong> Le d\u00e9multiplexeur (DEMUX), parfaitement synchronis\u00e9 avec le MUX, re\u00e7oit le signal composite. Il lit la trame, identifie les intervalles temporels et achemine les donn\u00e9es de chaque intervalle vers le canal de sortie appropri\u00e9.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Reconstruction :<\/strong> Les signaux \u00e0 faible d\u00e9bit d\u2019origine sont reconstruits et achemin\u00e9s vers leurs destinations finales.<\/p><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Ce processus entier s\u2019ex\u00e9cute des millions de fois par seconde, ce qui le rend extr\u00eamement efficace.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd TDM contre FDM : quelle est la diff\u00e9rence ?<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"905\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/b2025c333df748a5b4d2f956a06bf442.webp\" alt=\"TDM vs FDM\" class=\"wp-image-5171\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/b2025c333df748a5b4d2f956a06bf442.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/b2025c333df748a5b4d2f956a06bf442-300x226.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/b2025c333df748a5b4d2f956a06bf442-1024x772.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/b2025c333df748a5b4d2f956a06bf442-768x579.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/b2025c333df748a5b4d2f956a06bf442-16x12.webp 16w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TDM<\/strong> est souvent compar\u00e9e \u00e0 <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/glossary\/frequency-division-multiplexing-importance-and-how-it-works\/\"><strong>Multiplexage par r\u00e9partition en fr\u00e9quence (FDM)<\/strong><\/a>. Bien que les deux techniques combinent des signaux, elles le font de mani\u00e8re fondamentalement diff\u00e9rente. Ce tableau pr\u00e9sente les diff\u00e9rences cl\u00e9s :<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p>Fonctionnalit\u00e9<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>Multiplexage par r\u00e9partition dans le temps (TDM)<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>Multiplexage par r\u00e9partition en fr\u00e9quence (FDM)<\/strong><\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Principe fondamental<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Partage d\u2019un canal unique en allouant des <strong>cr\u00e9neaux temporels<\/strong>.<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Partage d\u2019un canal unique en allouant des <strong>bandes de fr\u00e9quence<\/strong>.<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Nature des signaux<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Num\u00e9rique<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Analogique<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Synchronisation<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>N\u00e9cessite une synchronisation pr\u00e9cise par horloge.<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Ne n\u00e9cessite pas de synchronisation.<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Efficacit\u00e9<br><\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Tr\u00e8s efficace ; aucune bande de garde n\u2019est requise.<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Moins efficace en raison des bandes de garde obligatoires entre les fr\u00e9quences.<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Cas d\u2019utilisation principal<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>T\u00e9l\u00e9phonie num\u00e9rique (lignes T1\/E1), SONET\/SDH.<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Radiodiffusion, t\u00e9l\u00e9vision analogique, premiers r\u00e9seaux cellulaires.<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Applications et normes courantes de la TDM<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TDM<\/strong> constitue depuis des d\u00e9cennies l\u2019\u00e9pine dorsale des r\u00e9seaux num\u00e9riques. Parmi ses applications et normes cl\u00e9s figurent :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>R\u00e9seaux t\u00e9l\u00e9phoniques :<\/strong> L\u2019exemple classique. Une <strong>ligne T1<\/strong> (1,544 Mbps) combine 24 canaux vocaux num\u00e9riques \u00e0 l\u2019aide de la TDM. Une <strong>ligne E1<\/strong> (2,048 Mbps) est la norme europ\u00e9enne, transportant 32 canaux.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>SONET\/SDH :<\/strong> The <strong>R\u00e9seau optique synchrone (SONET)<\/strong> and <strong>Hi\u00e9rarchie num\u00e9rique synchrone (SDH)<\/strong> sont les protocoles dominants pour la <strong>transmission optique \u00e0 haut d\u00e9bit<\/strong> sur de longues distances. Ils utilisent les principes de la TDM pour agr\u00e9ger des milliers de canaux vocaux et de donn\u00e9es.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Commutation de circuits num\u00e9riques :<\/strong> La TDM est par nature une technologie de commutation de circuits, ce qui la rend id\u00e9ale pour les applications exigeant des connexions constantes et \u00e0 faible latence, comme les appels vocaux traditionnels.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd La TDM \u00e0 l\u2019\u00e8re moderne : est-elle encore pertinente ?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Avec l\u2019essor d\u2019internet et d\u2019Ethernet, les technologies de commutation par paquets (telles que l\u2019IP) sont devenues dominantes pour le trafic de donn\u00e9es, gr\u00e2ce \u00e0 leur flexibilit\u00e9 sup\u00e9rieure et \u00e0 leur efficacit\u00e9 face aux donn\u00e9es \u00e0 caract\u00e8re \u00e9clat\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toutefois, la TDM <strong>n\u2019est nullement obsol\u00e8te<\/strong>. Ses atouts en mati\u00e8re de latence pr\u00e9visible et de fiabilit\u00e9 la rendent irrempla\u00e7able pour :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Raccordement mobile (backhaul) :<\/strong> Connexion des antennes-relais au r\u00e9seau c\u0153ur.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Connectivit\u00e9 entreprise :<\/strong> Lignes lou\u00e9es d\u00e9di\u00e9es pour les entreprises.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Support des syst\u00e8mes h\u00e9rit\u00e9s :<\/strong> De nombreux syst\u00e8mes critiques reposent encore sur l\u2019infrastructure TDM.<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Par ailleurs, les technologies modernes utilisent souvent des mod\u00e8les hybrides. Par exemple, <strong>LIEN-PP<\/strong>\u2018la gamme compl\u00e8te de <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-27047-10g-cwdm-dwdm-sfp.htm\"><strong>les \u00e9metteurs-r\u00e9cepteurs optiques 10G CWDM et DWDM<\/strong><\/a> sont con\u00e7us pour transporter simultan\u00e9ment, sur la m\u00eame fibre, du trafic TDM natif (comme SONET\/SDH) et du trafic IP bas\u00e9 sur des paquets, optimisant ainsi l\u2019investissement infrastructurel. Pour un <strong>d\u00e9ploiement optique fiable et performant<\/strong> prenant en charge des types de trafic mixtes, le <strong>LIEN-PP <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-27047-10g-cwdm-dwdm-sfp.htm?ca=1592,1595,1591&amp;cv=8852,8873,8847\"><strong>module SFP+ 10G-ER DWDM<\/strong><\/a> constitue un choix de r\u00e9f\u00e9rence dans le secteur.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Conclusion : l\u2019h\u00e9ritage durable de la TDM<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span class=\"qc-p1-tag\" style=\"color: rgb(15, 17, 21);\"><strong>La multiplexion par r\u00e9partition dans le temps<\/strong> est une technologie fondatrice qui a r\u00e9volutionn\u00e9 les t\u00e9l\u00e9communications en permettant une <\/span><span class=\"qc-p1-tag\"><strong>transmission num\u00e9rique<\/strong><\/span><span class=\"qc-p1-tag\" style=\"color: rgb(15, 17, 21);\">. transmission efficace et \u00e0 haute capacit\u00e9.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span class=\"qc-p1-tag\"><strong>Pr\u00eat \u00e0 construire une infrastructure r\u00e9seau fiable et \u00e0 haute capacit\u00e9 ?<\/strong><\/span><span class=\"qc-p1-tag\" style=\"color: rgb(15, 17, 21);\"> <\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span class=\"qc-p1-tag\" style=\"color: rgb(15, 17, 21);\">Que vous int\u00e9griez des syst\u00e8mes TDM h\u00e9rit\u00e9s ou que vous d\u00e9ployiez un r\u00e9seau hybride de nouvelle g\u00e9n\u00e9ration, le choix du mat\u00e9riel adapt\u00e9 est essentiel. <\/span><span class=\"qc-p1-tag\"><strong>D\u00e9couvrez toute la gamme LINK-PP de transceivers optiques haute performance et compatibles<\/strong><\/span><span class=\"qc-p1-tag\" style=\"color: rgb(15, 17, 21);\"> con\u00e7us pour r\u00e9pondre aux exigences des infrastructures modernes <\/span><span class=\"qc-p1-tag\"><strong>Ils se tiennent \u00e0 la pointe de cette technologie, con\u00e7ant et fabriquant des composants de haute performance essentiels pour<\/strong><\/span><span class=\"qc-p1-tag\" style=\"color: rgb(15, 17, 21);\">. <\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u25b6 <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\"><strong>Visitez notre page produit<\/strong><\/a><strong> d\u00e8s aujourd\u2019hui pour trouver le module SFP, SFP+ ou QSFP parfait pour votre application !<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>Que faire si votre commutateur ne s\u2019allume pas ?<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >Quel est l\u2019objectif principal de la TDM ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous utilisez la TDM pour envoyer plusieurs signaux sur un seul canal. Cette m\u00e9thode vous aide \u00e0 organiser les donn\u00e9es afin que chaque signal dispose de sa propre plage temporelle. Vous \u00e9conomisez de l\u2019espace et acc\u00e9l\u00e9rez les communications.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Quels types de signaux la TDM peut-elle traiter ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La TDM fonctionne aussi bien avec des signaux num\u00e9riques qu\u2019analogiques. On la retrouve fr\u00e9quemment dans les applications vocales, vid\u00e9o et de donn\u00e9es. Cette souplesse rend la TDM utile dans de nombreux syst\u00e8mes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Quel \u00e9quipement est n\u00e9cessaire pour la TDM ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous avez besoin d\u2019un multiplexeur c\u00f4t\u00e9 \u00e9metteur et d\u2019un d\u00e9multiplexeur c\u00f4t\u00e9 r\u00e9cepteur. Ces dispositifs vous permettent de combiner et de s\u00e9parer les signaux \u00e0 l\u2019aide de plages temporelles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Que se passe-t-il si un signal n\u2019a rien \u00e0 transmettre pendant sa plage temporelle ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si un signal ne comporte aucune donn\u00e9e, sa plage temporelle reste vide dans la TDM synchrone. Dans la TDM asynchrone, le syst\u00e8me ignore les plages vides et alloue le temps aux signaux actifs.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >En quoi la TDM se distingue-t-elle des autres m\u00e9thodes de multiplexage ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La TDM utilise des plages temporelles pour s\u00e9parer les signaux. D\u2019autres m\u00e9thodes, comme la FDM, utilisent des bandes de fr\u00e9quence. Vous choisissez la TDM lorsque vous souhaitez transmettre des signaux num\u00e9riques tour \u00e0 tour.<\/p>","protected":false},"excerpt":{"rendered":"<p>La TDM (multiplexion par r\u00e9partition temporelle) permet \u00e0 plusieurs signaux de partager un canal en leur attribuant des cr\u00e9neaux temporels, am\u00e9liorant ainsi l\u2019efficacit\u00e9 dans les t\u00e9l\u00e9communications, la diffusion et les r\u00e9seaux.<\/p>","protected":false},"author":1,"featured_media":5169,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[27],"tags":[26],"class_list":["post-5172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-glossary","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/5172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/comments?post=5172"}],"version-history":[{"count":5,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/5172\/revisions"}],"predecessor-version":[{"id":11165,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/5172\/revisions\/11165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/media\/5169"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/media?parent=5172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/categories?post=5172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/tags?post=5172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}