{"id":4936,"date":"2025-09-23T11:12:00","date_gmt":"2025-09-23T11:12:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/knowledge-center\/what-is-ethernet-wired-networking-technology-explained\/"},"modified":"2026-06-22T06:46:59","modified_gmt":"2026-06-22T06:46:59","slug":"what-is-ethernet-wired-networking-technology-explained","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/what-is-ethernet-wired-networking-technology-explained","title":{"rendered":"Qu\u2019est-ce qu\u2019Ethernet ? Le fondement filaire de votre r\u00e9seau expliqu\u00e9"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e94aea4de5ea4ca8a83eb9aeb28c3dee.webp\" alt=\"What Is Ethernet and Why Does It Matter?\" class=\"wp-image-4934\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e94aea4de5ea4ca8a83eb9aeb28c3dee.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e94aea4de5ea4ca8a83eb9aeb28c3dee-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e94aea4de5ea4ca8a83eb9aeb28c3dee-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e94aea4de5ea4ca8a83eb9aeb28c3dee-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e94aea4de5ea4ca8a83eb9aeb28c3dee-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pourriez vous demander, <strong>qu\u2019est-ce que l\u2019Ethernet ?<\/strong> L\u2019Ethernet relie votre ordinateur, votre console de jeu ou votre t\u00e9l\u00e9viseur intelligent \u00e0 Internet au moyen d\u2019un c\u00e2ble. Vous utilisez l\u2019Ethernet \u00e0 la maison ou au travail lorsque vous souhaitez une connexion Internet rapide et stable. De nombreuses personnes appr\u00e9cient l\u2019Ethernet car il est plus rapide et plus fiable que la connexion sans fil. Vos donn\u00e9es circulent en toute s\u00e9curit\u00e9 via <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/cat5e-vs-cat6-vs-cat7-ethernet-cable\/\"><strong>les c\u00e2bles Ethernet<\/strong><\/a>, ce qui rend vos activit\u00e9s en ligne plus s\u00e9curis\u00e9es. Si vous avez besoin d\u2019une connexion robuste pour le streaming, les cours en ligne ou les appels vid\u00e9o, l\u2019Ethernet vous offre les meilleurs r\u00e9sultats.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Astuce : Essayez l\u2019Ethernet si votre Wi-Fi est lent ou se d\u00e9connecte r\u00e9guli\u00e8rement. Cela r\u00e9sout souvent le probl\u00e8me !<\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcc4 Qu\u2019est-ce que l\u2019Ethernet ? Bien plus qu\u2019un simple c\u00e2ble<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dans notre monde connect\u00e9 sans fil, vous pourriez penser que les c\u00e2bles appartiennent au pass\u00e9. Or, lorsqu\u2019il s\u2019agit d\u2019une connectivit\u00e9 Internet stable, haute vitesse et s\u00e9curis\u00e9e, rien ne vaut une bonne vieille connexion filaire. Au c\u0153ur de cette magie filaire se trouve une technologie appel\u00e9e <strong>Ethernet<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En termes simples, <strong>l\u2019Ethernet est une technologie traditionnelle qui relie des appareils au sein d\u2019un <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/local-area-network-lan-modern-networking-fast-secure-connections\/\"><strong>R\u00e9seau local (LAN)<\/strong><\/a><strong> or <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/what-is-a-wide-area-network\/\"><strong>R\u00e9seau \u00e9tendu (WAN)<\/strong><\/a><strong>.<\/strong> Il utilise des c\u00e2bles physiques \u2014 comme ce c\u00e2ble bleu familier qui serpente depuis votre routeur jusqu\u2019\u00e0 votre ordinateur \u2014 pour transmettre des donn\u00e9es. C\u2019est la norme fondamentale qui d\u00e9finit comment les donn\u00e9es sont format\u00e9es et envoy\u00e9es via ces c\u00e2bles, garantissant ainsi une communication transparente entre des appareils provenant de diff\u00e9rents fabricants.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si le Wi-Fi nous offre libert\u00e9, l\u2019Ethernet fournit fiabilit\u00e9. Que vous soyez un joueur passionn\u00e9, un amateur de streaming ou que vous exploitiez un serveur professionnel, comprendre l\u2019Ethernet est essentiel pour optimiser votre r\u00e9seau.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcc4 Comment fonctionne l\u2019Ethernet ? Les rouages du syst\u00e8me<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019Ethernet repose sur un principe appel\u00e9 <strong>Acc\u00e8s multiple avec d\u00e9tection de porteuse et de collisions (CSMA\/CD)<\/strong>. Imaginez cela comme une conversation polie dans une pi\u00e8ce :<\/p>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p style=\"margin: 0px;\"><strong>\u00c9coutez d\u2019abord :<\/strong> Un appareil \u201c \u00e9coute \u201d le c\u00e2ble r\u00e9seau pour v\u00e9rifier s\u2019il est libre avant d\u2019envoyer des donn\u00e9es.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Envoyez les donn\u00e9es :<\/strong> Si la ligne est libre, il transmet le paquet de donn\u00e9es.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>D\u00e9tection des collisions :<\/strong> Si deux appareils envoient des donn\u00e9es exactement au m\u00eame moment, une \u201c collision \u201d se produit. Les deux appareils la d\u00e9tectent, attendent un court instant al\u00e9atoire, puis r\u00e9essaient.<\/p><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Ce syst\u00e8me, r\u00e9gi par la <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/ieee-802-3-ethernet-standard-explained\/\"><strong>La norme IEEE 802.3<\/strong><\/a>, cr\u00e9e un flux ordonn\u00e9 d\u2019informations. Chaque appareil poss\u00e8de une adresse physique unique appel\u00e9e <strong>adresse MAC (Media Access Control Address)<\/strong>, qui agit comme une adresse postale pour votre carte r\u00e9seau, garantissant ainsi que les donn\u00e9es parviennent \u00e0 la destination correcte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcc4 C\u00e2bles Ethernet et d\u00e9bits : choisir le bon c\u00e2ble<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tous les c\u00e2bles Ethernet ne se valent pas. Ils sont class\u00e9s selon des num\u00e9ros \u201c Cat \u201d, qui indiquent leurs performances. Voici un guide rapide des types les plus courants :<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p>Cat\u00e9gorie de c\u00e2ble<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>D\u00e9bit maximal pris en charge<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Bande passante (fr\u00e9quence)<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Cas d\u2019utilisation courant<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Cat&nbsp;5<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>100 Mbit\/s<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>100MHz<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Obsol\u00e8te, non recommand\u00e9 pour de nouvelles installations.<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Cat 5e<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>1 Gbit\/s (1000 Mbit\/s)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>100MHz<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Standard pour la plupart des r\u00e9seaux domestiques et professionnels.<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Cat 6<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>1 Gbit\/s (jusqu\u2019\u00e0 10 Gbit\/s sur de courtes distances)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>250MHz<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Id\u00e9al pour le jeu en ligne, le streaming 4K et les grandes habitations.<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Cat 6a<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>10 Gbps<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>500MHz<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Utilisation professionnelle, centres de donn\u00e9es, r\u00e9seaux haute performance.<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Cat\u00e9gorie 7\/8<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>10\/40 Gbit\/s<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>600\/2000 MHz<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Applications sp\u00e9cialis\u00e9es haute fr\u00e9quence, centres de donn\u00e9es.<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><span class=\"qc-p1-tag\" style=\"color: rgb(15, 17, 21);\">Pour la plupart des utilisateurs, un c\u00e2ble <\/span><span class=\"qc-p1-tag\"><strong>Cat 5e ou Cat 6<\/strong><\/span><span class=\"qc-p1-tag\" style=\"color: rgb(15, 17, 21);\"> est parfaitement suffisant. Si vous disposez d\u2019un forfait Internet multi-gigabit ou transf\u00e9rez fr\u00e9quemment de gros fichiers en interne, envisagez <\/span><span class=\"qc-p1-tag\"><strong>Cat 6a<\/strong><\/span><span class=\"qc-p1-tag\" style=\"color: rgb(15, 17, 21);\"> ou davantage.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcc4 Ethernet contre Wi-Fi : pourquoi opter pour la connexion filaire ?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pourquoi utiliser un c\u00e2ble alors que le Wi-Fi est si pratique ? Voici les principaux avantages de l\u2019Ethernet :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Latence plus faible (ping) :<\/strong> Crucial pour le jeu en ligne et les visioconf\u00e9rences. Les connexions filaires pr\u00e9sentent un d\u00e9lai minimal.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Fiabilit\u00e9 accrue :<\/strong> Non sensible aux obstacles physiques, aux interf\u00e9rences radio provenant des voisins ou aux pertes de signal.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>S\u00e9curit\u00e9 renforc\u00e9e :<\/strong> Une connexion physique est bien plus difficile \u00e0 intercepter qu\u2019une diffusion sans fil.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>D\u00e9bits plus \u00e9lev\u00e9s :<\/strong> M\u00eame le meilleur Wi-Fi ne parvient pas toujours \u00e0 \u00e9galer le d\u00e9bit constant et maximal offert par une liaison directe par c\u00e2ble.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcc4 L\u2019avenir est rapide : l\u2019Ethernet et le r\u00f4le des modules optiques<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"719\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d7f423b51d5e4e90bdc34eb332e1dc30.jpg\" alt=\"optical transceiver\" class=\"wp-image-4935\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d7f423b51d5e4e90bdc34eb332e1dc30.jpg 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d7f423b51d5e4e90bdc34eb332e1dc30-300x180.jpg 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d7f423b51d5e4e90bdc34eb332e1dc30-1024x614.jpg 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d7f423b51d5e4e90bdc34eb332e1dc30-768x460.jpg 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d7f423b51d5e4e90bdc34eb332e1dc30-18x12.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 mesure que les besoins en donn\u00e9es explosent, les c\u00e2bles en cuivre traditionnels (comme le Cat 6 ci-dessus) pr\u00e9sentent des limites, notamment sur de longues distances. C\u2019est ici que les fibres optiques et les <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\"><strong>des modules optiques<\/strong><\/a> prennent le relais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans les r\u00e9seaux modernes haute vitesse, tels que les centres de donn\u00e9es et les infrastructures d\u2019entreprise, <strong>Ethernet<\/strong> les trames sont transmises sous forme de faisceaux lumineux \u00e0 travers des c\u00e2bles en fibre optique. Le dispositif qui convertit les signaux \u00e9lectriques provenant des \u00e9quipements r\u00e9seau en signaux lumineux (et vice versa) s\u2019appelle un <strong>amovible<\/strong>, couramment d\u00e9sign\u00e9 sous le nom de <strong>module optique<\/strong> or <strong>SFP<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces petits modules ins\u00e9rables \u00e0 chaud sont essentiels pour atteindre des d\u00e9bits de 10 G, 40 G, 100 G et plus. Lors du choix d\u2019un module optique, compatibilit\u00e9 et qualit\u00e9 sont primordiales. Par exemple, une solution haute performance et fiable pour une connexion 10 Gigabit serait un module <strong>LIEN-PP <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/475415.htm\"><strong>SFP-10G-SR<\/strong><\/a> Ce mod\u00e8le sp\u00e9cifique de <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.link-pp.com\/\"><strong>LIEN-PP<\/strong><\/a> est con\u00e7u pour des connexions en fibre multimode \u00e0 courte port\u00e9e, offrant un \u00e9quilibre parfait entre performances et rapport qualit\u00e9-prix pour les r\u00e9seaux professionnels en pleine croissance. Comprendre le r\u00f4le de ces <strong>modules SFP+ compatibles<\/strong> est essentiel pour toute personne g\u00e9rant une infrastructure r\u00e9seau \u00e0 forte capacit\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcc4 Conclusion : l\u2019Ethernet est l\u00e0 pour rester<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ethernet<\/strong> s\u2019est av\u00e9r\u00e9 \u00eatre l\u2019une des technologies les plus r\u00e9silientes et critiques de l\u2019histoire de l\u2019informatique. Il constitue la colonne vert\u00e9brale fiable et haute vitesse dont d\u00e9pend notre monde sans fil. Que ce soit pour connecter votre t\u00e9l\u00e9viseur intelligent afin de diffuser du contenu 4K ou pour former le c\u0153ur de l\u2019infrastructure Internet mondiale, son importance ne saurait \u00eatre surestim\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pr\u00eat \u00e0 am\u00e9liorer la fiabilit\u00e9 et la vitesse de votre r\u00e9seau ?<\/strong> Commencez par v\u00e9rifier la pr\u00e9sence de ports Ethernet disponibles sur votre routeur et vos appareils. Pour des besoins exigeants en mati\u00e8re de performances, notamment dans un environnement professionnel, envisagez les avantages de la fibre optique et des composants de haute qualit\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcc4 FAQ<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >Quels appareils peuvent utiliser Ethernet ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez utiliser Ethernet avec des ordinateurs et des consoles de jeu. Les t\u00e9l\u00e9viseurs intelligents, les imprimantes et les commutateurs r\u00e9seau utilisent \u00e9galement Ethernet. La plupart des nouveaux appareils sont \u00e9quip\u00e9s de ports Ethernet. Si votre appareil n\u2019en poss\u00e8de pas, vous pouvez utiliser un adaptateur Ethernet.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Quels c\u00e2bles Ethernet avez-vous besoin ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous avez besoin de c\u00e2bles Ethernet tels que Cat5e, Cat6 ou Cat7. Ces c\u00e2bles relient votre appareil \u00e0 un routeur ou \u00e0 un commutateur. Chaque type de c\u00e2ble convient \u00e0 des vitesses et des distances diff\u00e9rentes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Pourquoi Ethernet est-il plus s\u00e9curis\u00e9 que le Wi-Fi ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ethernet utilise des c\u00e2bles physiques pour connecter les appareils. Seuls les appareils branch\u00e9s peuvent rejoindre le r\u00e9seau. Cela rend plus difficile pour des personnes ext\u00e9rieures d\u2019acc\u00e9der \u00e0 vos donn\u00e9es qu\u2019avec une connexion sans fil.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Que faire si votre connexion Ethernet ne fonctionne pas ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">V\u00e9rifiez si le c\u00e2ble est endommag\u00e9. Assurez-vous que les deux extr\u00e9mit\u00e9s sont bien ins\u00e9r\u00e9es. Red\u00e9marrez votre appareil et votre routeur. Si le probl\u00e8me persiste, essayez un autre c\u00e2ble ou un autre port.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Quelle est la diff\u00e9rence entre Fast Ethernet et Gigabit Ethernet ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Fast Ethernet atteint jusqu\u2019\u00e0 100 Mbps. Gigabit Ethernet atteint jusqu\u2019\u00e0 1 000 Mbps. Gigabit Ethernet est nettement plus rapide pour r\u00e9pondre aux besoins actuels.<\/p>","protected":false},"excerpt":{"rendered":"<p>Qu\u2019est-ce qu\u2019Ethernet ? Ethernet est une technologie de r\u00e9seau filaire offrant des connexions rapides, stables et s\u00e9curis\u00e9es pour les foyers, les bureaux et les entreprises.<\/p>","protected":false},"author":1,"featured_media":4934,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[26],"class_list":["post-4936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowledge-center","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/4936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/comments?post=4936"}],"version-history":[{"count":4,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/4936\/revisions"}],"predecessor-version":[{"id":11083,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/4936\/revisions\/11083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/media\/4934"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/media?parent=4936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/categories?post=4936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/tags?post=4936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}