{"id":4396,"date":"2026-05-13T03:17:52","date_gmt":"2026-05-13T03:17:52","guid":{"rendered":"https:\/\/lp.szlogic.cn\/products\/40g-swdm4-module-high-speed-network-upgrade-benefits\/"},"modified":"2026-06-22T03:26:29","modified_gmt":"2026-06-22T03:26:29","slug":"40g-swdm4-module-high-speed-network-upgrade-benefits","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/fr\/products\/40g-swdm4-module-high-speed-network-upgrade-benefits","title":{"rendered":"Pourquoi choisir le module QSFP+ LQ\u2011SW40\u2011SR4C 40G pour les r\u00e9seaux haute vitesse"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e9b86abc8c68400bb128ed36da363bc3.webp\" alt=\"LQ\u2011SW40\u2011SR4C 40G QSFP+ Module\" class=\"wp-image-4393\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e9b86abc8c68400bb128ed36da363bc3.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e9b86abc8c68400bb128ed36da363bc3-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e9b86abc8c68400bb128ed36da363bc3-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e9b86abc8c68400bb128ed36da363bc3-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e9b86abc8c68400bb128ed36da363bc3-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Introduction<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dans l\u2019environnement r\u00e9seau \u00e0 haute vitesse d\u2019aujourd\u2019hui, les centres de donn\u00e9es et les r\u00e9seaux d\u2019entreprise exigent des solutions plus rapides, plus fiables et plus rentables. Le LINK-PP<br> <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/491483.htm\"><strong>Module LQ-SW40-SR4C 40GBASE-SR SWDM4<br><\/strong><\/a> est con\u00e7u pour r\u00e9pondre \u00e0 ces besoins, offrant un d\u00e9bit de 40 Gb\/s sur fibre multimode duplex tout en optimisant la consommation d\u2019\u00e9nergie, le co\u00fbt et les performances.<br>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Points cl\u00e9s \u00e0 retenir<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>The <strong>LQ-SW40-SR4C<\/strong> adopte<br> <strong>la technologie SWDM4<br><\/strong>, permettant une transmission \u00e0 40 Gb\/s sur fibre multimode (MMF) duplex standard sans n\u00e9cessiter de refonte de l\u2019infrastructure.<br>.<\/p><\/li><li><p>Compatible avec <strong>Fibre multimode OM3\/OM4<br><\/strong>, offrant des distances de liaison allant jusqu\u2019\u00e0<br> <strong>350 m<br><\/strong>.<\/p><\/li><li><p>Caract\u00e9ristiques<br> <strong>faible consommation d\u2019\u00e9nergie (&lt; 3,5 W)<br><\/strong> pour des op\u00e9rations \u00e9co\u00e9nerg\u00e9tiques dans les centres de donn\u00e9es.<br>.<\/p><\/li><li><p>Enti\u00e8rement conforme aux normes <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/what-is-ieee-802-3ba-standard\/\"><strong>IEEE 802.3ba<\/strong><\/a><strong>, <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/qsfp-plus-msa-explained-40g-qsfp-plus-modules\/\"><strong>QSFP+ MSA<\/strong><\/a><strong>, et le standard SWDM MSA<br><\/strong> pour une interop\u00e9rabilit\u00e9 \u00e9tendue.<br>.<\/p><\/li><li><p>Fournit une <strong>chemin de mise \u00e0 niveau rentable et \u00e9volutif<br><\/strong> des r\u00e9seaux 10G vers les r\u00e9seaux 40G.<br>.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Caract\u00e9ristiques principales<br><\/h2>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p><strong>D\u00e9bit de donn\u00e9es de 40 Gb\/s<br><\/strong>: Prend en charge des liaisons QSFP+ \u00e0 haute vitesse pour des applications r\u00e9seau exigeantes. (<br><a target=\"_new\" rel=\"noopener\" class=\"decorated-link\" href=\"https:\/\/www.l-p.com\/file\/datasheet\/lq-sw40-sr4c.pdf?utm_source=chatgpt.com\">l-p.com<\/a>)<\/p><\/li><li><p><strong>Technologie SWDM4<br><\/strong>: Quatre longueurs d\u2019onde (850 nm \/ 880 nm \/ 910 nm \/ 940 nm), chacune \u00e0 10 Gb\/s, pour une utilisation efficace de la fibre.<br>.<\/p><\/li><li><p><strong>Connecteurs duplex LC\/UPC<br><\/strong>: Compatible avec l\u2019infrastructure standard en fibre multimode (MMF).<br>.<\/p><\/li><li><p><strong>Port\u00e9e \u00e9tendue<\/strong>: Jusqu\u2019\u00e0 240 m sur fibre OM3 et 350 m sur fibre OM4, pour des configurations flexibles dans les centres de donn\u00e9es.<br>.<\/p><\/li><li><p><strong>Faible consommation d\u2019\u00e9nergie<\/strong>: Consommation typique &lt; 3,5 W afin de r\u00e9duire la charge thermique et les co\u00fbts op\u00e9rationnels.<br>.<\/p><\/li><li><p><strong>Conformit\u00e9 aux normes<\/strong>: Enti\u00e8rement conforme aux normes QSFP+ MSA, SWDM MSA, IEEE 802.3ba,<br>, <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/sff-8636-standard-qsfp-qsfp28-management-interface-guide\/\">SFF-8636<\/a>.<\/p><\/li><li><p><strong>Compatibilit\u00e9 des fournisseurs<\/strong>: Compatible avec les principales marques (Cisco, Arista, Dell, HPE\/Aruba, Juniper, Mellanox) pour un d\u00e9ploiement flexible.<br>.<\/p><\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Sp\u00e9cifications techniques<br><\/h2>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"width: 285px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\" colwidth=\"285\"><p>Param\u00e8tre<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Sp\u00e9cification<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"285\"><p>Facteur de forme<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>QSFP+<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"285\"><p>D\u00e9bit de donn\u00e9es<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>40 Gb\/s<br><\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"285\"><p>Technologie de transmission<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>SWDM4 (4 voies)<br><\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"285\"><p>Canaux de longueur d\u2019onde<br><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>850 nm \/ 880 nm \/ 910 nm \/ 940 nm<br><\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"285\"><p>Type de fibre<br><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Fibre multimode (OM3 \/ OM4)<br><\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"285\"><p>Type de connecteur<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>connecteurs duplex LC\/UPC<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"285\"><p>Distance maximale de liaison<br><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>OM3 : 240 m, OM4 : 350 m<br><\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"285\"><p>Consommation d\u2019\u00e9nergie<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>&lt; 3,5 W<br><\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"285\"><p>Temp\u00e9rature de fonctionnement du bo\u00eetier<br><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>0 \u00b0C \u00e0 70 \u00b0C (standard)<br><\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"285\"><p>Conformit\u00e9 aux normes<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>QSFP+ MSA, SWDM MSA, IEEE 802.3ba, SFF-8636<br><\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"285\"><p>Interface de connecteur<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Interface \u00e9lectrique XLPPI<br><\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup\/><tbody><tr\/><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"850\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/883b54889ce24d31804bba2557acc9e6.webp\" alt=\"40GBASE\u2011SR for High-Speed Networks\" class=\"wp-image-4394\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/883b54889ce24d31804bba2557acc9e6.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/883b54889ce24d31804bba2557acc9e6-300x213.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/883b54889ce24d31804bba2557acc9e6-1024x725.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/883b54889ce24d31804bba2557acc9e6-768x544.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/883b54889ce24d31804bba2557acc9e6-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Avantages pour les r\u00e9seaux \u00e0 haute vitesse<br><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >Grande bande passante dans un format compact<br><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Avec un d\u00e9bit de 40 Gb\/s dans le format compact QSFP+, le module LQ-SW40-SR4C permet des mises \u00e0 niveau de ports \u00e0 haute densit\u00e9 sans sacrifier de l\u2019espace dans les baies.<br>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Utilisation \u00e9conomique de la fibre<br><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019utilisation de la technologie SWDM4 permet de r\u00e9utiliser l\u2019infrastructure existante en fibre multimode duplex, \u00e9vitant ainsi des op\u00e9rations co\u00fbteuses de rec\u00e2blage.<br>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Faible consommation d\u2019\u00e9nergie et empreinte thermique<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Avec une consommation \u00e9lectrique typique inf\u00e9rieure \u00e0 3,5 W, ce module contribue \u00e0 minimiser les besoins en refroidissement et \u00e0 r\u00e9duire le co\u00fbt op\u00e9rationnel total.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Interop\u00e9rabilit\u00e9 et conformit\u00e9 aux normes<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La conformit\u00e9 compl\u00e8te aux principales normes industrielles et la compatibilit\u00e9 \u00e9tendue avec les fournisseurs garantissent une int\u00e9gration transparente dans des r\u00e9seaux h\u00e9t\u00e9rog\u00e8nes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Infrastructure fibre optique pr\u00e9par\u00e9e pour l\u2019avenir<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La prise en charge des fibres OM3\/OM4 avec une port\u00e9e g\u00e9n\u00e9reuse fait de ce module un choix \u00e9volutif \u00e0 mesure que les exigences r\u00e9seau augmentent.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Applications id\u00e9ales<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>Liaisons montantes entre commutateurs spine et leaf dans les centres de donn\u00e9es<\/p><\/li><li><p>Interconnexions de grappes informatiques haute performance (HPC) et d\u2019intelligence artificielle\/apprentissage automatique (IA\/ML)<\/p><\/li><li><p>Mise \u00e0 niveau des r\u00e9seaux d\u2019entreprise passant de 10 G \u00e0 40 G<\/p><\/li><li><p>Cycles de renouvellement et d\u2019optimisation des infrastructures fibre<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Pourquoi choisir LINK-PP<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>Un programme rigoureux d\u2019assurance qualit\u00e9 et de tests garantit la fiabilit\u00e9.<\/p><\/li><li><p>Une compatibilit\u00e9 \u00e9tendue avec les principaux fournisseurs de commutateurs r\u00e9duit le risque de d\u00e9pendance vis-\u00e0-vis d\u2019un fournisseur unique.<\/p><\/li><li><p>Une conception \u00e9conomique offrant faible consommation \u00e9nerg\u00e9tique, hautes performances et port\u00e9e \u00e9tendue.<\/p><\/li><li><p>Facteur de forme QSFP+ \u00e0 insertion \u00e0 chaud permettant un d\u00e9ploiement rapide et une maintenance ais\u00e9e.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Conclusion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mettez \u00e0 niveau votre r\u00e9seau en toute confiance avec LINK-PP <strong>Module LQ-SW40-SR4C 40GBASE-SR SWDM4<br><\/strong>. Il offre des performances haut d\u00e9bit, fiables, \u00e0 faible consommation \u00e9nerg\u00e9tique et ind\u00e9pendantes du fournisseur, ce qui en fait une solution id\u00e9ale pour les centres de donn\u00e9es, les r\u00e9seaux d\u2019entreprise et les grappes de serveurs. Pr\u00e9parez votre connectivit\u00e9 pour l\u2019avenir avec des modifications minimales de l\u2019infrastructure et des performances maximales.<\/p>\n\n\n\n<div class=\"alignnone qc-cover-wrapper has-custom-content-position is-position-center\" elementtype=\"div\" useimagebackground=\"false\" imgbg=\"\" imgbgpositionleft=\"50\" imgbgpositiontop=\"50\" overlay=\"#165DFF\" overlayopacity=\"0.8\" contentposition=\"center\" alt=\"\" parallax=\"false\" style=\"border-radius: 12px; padding-left: var(--qc-preset--spacing--60); padding-right: var(--qc-preset--spacing--60); padding-top: var(--qc-preset--spacing--60); padding-bottom: var(--qc-preset--spacing--60); background-color: rgb(242, 243, 245); height: auto;\"><div class=\"qc-cover-wrapper__inner-container\"><div style=\"flex-wrap: wrap; justify-content: center; display: flex;\"><div colmd=\"10\" class=\"col col-md-10\"><p style=\"text-align: center;\"><span class=\"qc-h1-tag\" style=\"color: rgb(0, 0, 0);\">D\u00e9couvrez le LQ-SW40-SR4C<\/span><\/p><p style=\"text-align: center;\"><span class=\"qc-p1-tag\" style=\"color: rgb(0, 0, 0);\">Explorez les fonctionnalit\u00e9s et les avantages du module 40G QSFP+ LQ-SW40-SR4C pour r\u00e9pondre \u00e0 vos besoins r\u00e9seau.<\/span><\/p><div class=\"qc-buttons-wrapper\"><div justification=\"center\" class=\"qc-buttons-container is-horizontal is-content-justification-center\" style=\"margin-top: var(--qc-preset--spacing--0); margin-bottom: var(--qc-preset--spacing--0); gap: var(--qc-preset--spacing--40);\"><div link=\"https:\/\/www.l-p.com\/products\/491483.htm\" opennewtab=\"false\" width=\"\" outline=\"false\" class=\"qc-button-wrapper\" style=\"\"><a class=\"qc-button-container\" href=\"https:\/\/www.l-p.com\/products\/491483.htm\" target=\"_self\"><span style=\"color: rgb(255, 255, 255);\"><strong>En savoir plus<\/strong><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 FAQ<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >Q1 : Le LQ-SW40-SR4C est-il compatible avec mes commutateurs ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">R : Oui, il est ind\u00e9pendant du fournisseur et a \u00e9t\u00e9 test\u00e9 pour fonctionner avec les marques leaders, notamment Cisco, Arista, Dell, HPE\/Aruba, Juniper, Mellanox, et bien d\u2019autres.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Q2 : Quel type de fibre ce module prend-il en charge ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">R : Il prend en charge les types standard de fibre multimode (MMF) OM3 et OM4, avec des connecteurs duplex LC\/UPC.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Q3 : Qu\u2019est-ce que la technologie SWDM4 ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">R : SWDM4 (multiplexage en longueur d\u2019onde courte) transmet quatre signaux de 10\u202fGb\/s sur une fibre multimode duplex \u00e0 l\u2019aide de quatre longueurs d\u2019onde (850\u202fnm \/ 880\u202fnm \/ 910\u202fnm \/ 940\u202fnm), atteignant ainsi efficacement un d\u00e9bit global de 40\u202fGb\/s.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Q4&nbsp;: Puis-je utiliser ce module pour mettre \u00e0 niveau des liaisons 10 G existantes&nbsp;?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">R&nbsp;: Absolument. Le module LQ-SW40-SR4C est id\u00e9al pour des mises \u00e0 niveau rentables de 10 G vers 40 G, sans avoir \u00e0 remplacer le c\u00e2blage en fibre optique.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Q5&nbsp;: Puis-je acheter en gros pour des d\u00e9ploiements \u00e0 grande \u00e9chelle&nbsp;?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">R&nbsp;: Oui, LINK-PP propose des tarifs d\u00e9gressifs pour les installations \u00e0 grande \u00e9chelle dans les centres de donn\u00e9es ou les entreprises.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Voir aussi<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/products\/link-pp-100g-transceivers-connectivity\/\">Les avantages des transceivers 100 G LINK-PP pour des connexions rapides<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/products\/link-pp-ls-dw2810-40i-dwdm-transceiver\/\">Aper\u00e7u du module DWDM SFP+ 10 G LINK-PP LS-DW2810-40I<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/products\/qsfp-dd-lr4-transceiver-400g-10km-solution\/\">Exploration de la solution optique QSFP-DD 400 G LINK-PP LQD-CW400-LR4C<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/why-choose-link-pp-fiber-optical-modules\/\">Pourquoi choisir les modules transceivers optiques fibre LINK-PP<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/the-benefits-of-100g-sfp-dd-lr-optical-transceiver\/\">Avantages de l\u2019utilisation du transceiver optique 100 G SFP-DD LR<\/a><\/p>\n\n\n\n<script>const link1 = document.createElement('link');link1.rel = 'stylesheet';link1.type = 'text\/css';link1.href = 'https:\/\/statics.quickcreator.io\/static\/theme\/css\/qcb-theme-additional.css';const link2 = document.createElement('link');link2.rel = 'stylesheet';link2.type = 'text\/css';link2.href = 'https:\/\/statics.quickcreator.io\/static\/aaapycm22qmuab44\/theme\/css\/qcb-main-theme.css';document.head.appendChild(link1);document.head.appendChild(link2);<\/script>","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez le module 40GBASE\u2011SR LQ\u2011SW40\u2011SR4C : optique QSFP+ haute vitesse et faible consommation pour r\u00e9seaux en fibre multimode. Id\u00e9al pour les centres de donn\u00e9es et les mises \u00e0 niveau r\u00e9seau.<\/p>","protected":false},"author":1,"featured_media":4395,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[28],"tags":[18,24,26],"class_list":["post-4396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-products","tag-40g-qsfp-transceivers","tag-link-pp","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/4396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/comments?post=4396"}],"version-history":[{"count":4,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/4396\/revisions"}],"predecessor-version":[{"id":10689,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/4396\/revisions\/10689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/media\/4395"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/media?parent=4396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/categories?post=4396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/tags?post=4396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}