{"id":4170,"date":"2025-09-15T11:12:00","date_gmt":"2025-09-15T11:12:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/glossary\/what-is-ftth-fiber-to-the-home\/"},"modified":"2026-06-22T07:15:04","modified_gmt":"2026-06-22T07:15:04","slug":"what-is-ftth-fiber-to-the-home","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/fr\/glossary\/what-is-ftth-fiber-to-the-home","title":{"rendered":"Comprendre la FTTH (Fibre jusqu\u2019\u00e0 l\u2019abonn\u00e9) : guide complet"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"477\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dd15766dfe004e4ea8bfe32624c4bbc5.webp\" alt=\"What Is FTTH?\" class=\"wp-image-4166\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dd15766dfe004e4ea8bfe32624c4bbc5.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dd15766dfe004e4ea8bfe32624c4bbc5-300x119.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dd15766dfe004e4ea8bfe32624c4bbc5-1024x407.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dd15766dfe004e4ea8bfe32624c4bbc5-768x305.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dd15766dfe004e4ea8bfe32624c4bbc5-18x7.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Introduction<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FTTH (fibre jusqu\u2019\u00e0 l\u2019habitation)<\/strong> est une technologie de large bande de pointe qui fournit un acc\u00e8s Internet haut d\u00e9bit directement aux r\u00e9sidences \u00e0 l\u2019aide de c\u00e2bles en fibre optique. Contrairement aux connexions traditionnelles bas\u00e9es sur le cuivre, la FTTH offre une vitesse, une fiabilit\u00e9 et une \u00e9volutivit\u00e9 sans \u00e9gales, ce qui la rend id\u00e9ale pour les applications num\u00e9riques modernes telles que le streaming, les jeux en ligne, la t\u00e9l\u00e9m\u00e9decine et les syst\u00e8mes domotiques.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Qu\u2019est-ce que la FTTH ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La FTTH implique l\u2019installation de c\u00e2bles en fibre optique depuis un central t\u00e9l\u00e9phonique (CO) directement jusqu\u2019aux habitations ou entreprises individuelles. Cette connexion directe par fibre remplace les technologies plus anciennes, telles que l\u2019ADSL ou les c\u00e2bles coaxiaux, offrant une bande passante nettement sup\u00e9rieure et une latence r\u00e9duite. La FTTH constitue un sous-ensemble de la famille plus large des <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/fttx-technical-guide-modern-fiber-access-architectures\/\"><strong>, marge m\u00e9tropolitaine, campus h\u00e9rit\u00e9), les \u00e9conomies issues de l'\u00e9vitement d'une nouvelle installation de fibre surpassent souvent l\u00e9g\u00e8rement le co\u00fbt plus \u00e9lev\u00e9 des optiques.<\/strong><\/a> (Fibre jusqu\u2019au x), qui comprend :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>FTTB (Fibre jusqu\u2019\u00e0 l\u2019immeuble) :<\/strong> La fibre atteint l\u2019entr\u00e9e de l\u2019immeuble, les liaisons internes \u00e9tant assur\u00e9es par des c\u00e2bles en cuivre ou coaxiaux.<\/p><\/li><li><p><strong>FTTC (Fibre jusqu\u2019au trottoir) :<\/strong> La fibre s\u2019\u00e9tend jusqu\u2019\u00e0 un point de distribution situ\u00e9 \u00e0 proximit\u00e9 des locaux, la liaison finale \u00e9tant r\u00e9alis\u00e9e \u00e0 l\u2019aide de lignes en cuivre.<\/p><\/li><li><p><strong>FTTN (Fibre jusqu\u2019au n\u0153ud) :<\/strong> La fibre s\u2019\u00e9tend jusqu\u2019\u00e0 un n\u0153ud de quartier, les lignes en cuivre assurant la liaison finale avec les habitations.<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La FTTH est consid\u00e9r\u00e9e comme l\u2019option la plus avanc\u00e9e et la plus p\u00e9renne, offrant les performances et la capacit\u00e9 les plus \u00e9lev\u00e9es.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"450\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/55111ab41ab44f4e94795a0ca269e081.webp\" alt=\"FTTH: Fiber to the home\" class=\"wp-image-4167\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/55111ab41ab44f4e94795a0ca269e081.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/55111ab41ab44f4e94795a0ca269e081-300x113.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/55111ab41ab44f4e94795a0ca269e081-1024x384.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/55111ab41ab44f4e94795a0ca269e081-768x288.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/55111ab41ab44f4e94795a0ca269e081-18x7.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Comment fonctionne la FTTH ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le r\u00e9seau FTTH se compose de plusieurs \u00e9l\u00e9ments cl\u00e9s :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>Terminal de ligne optique (OLT) :<\/strong> Situ\u00e9 au central t\u00e9l\u00e9phonique de l\u2019op\u00e9rateur, l\u2019OLT g\u00e8re le trafic de donn\u00e9es et les signaux destin\u00e9s aux unit\u00e9s de r\u00e9seau optique (ONU) install\u00e9es chez les clients.<\/p><\/li><li><p><strong>R\u00e9partiteurs optiques :<\/strong> Ces dispositifs passifs divisent le signal optique provenant de l\u2019OLT en plusieurs trajets, permettant \u00e0 une seule fibre de desservir plusieurs habitations.<\/p><\/li><li><p><strong>Terminal de r\u00e9seau optique (ONT) :<\/strong> Install\u00e9 sur les lieux de l\u2019utilisateur, l\u2019ONT convertit les signaux optiques en signaux \u00e9lectriques utilisables par des appareils tels que les ordinateurs, les routeurs et les t\u00e9l\u00e9viseurs.<\/p><\/li><li><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/knowledge-center\/fiber-optic-cable-what-it-is-and-how-it-works-explained\/\"><strong>C\u00e2bles en fibre optique<\/strong><\/a><strong>:<\/strong> Les fibres monomodes sont g\u00e9n\u00e9ralement utilis\u00e9es pour la FTTH, offrant une bande passante \u00e9lev\u00e9e sur de longues distances avec une perte de signal minimale.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Avantages de la FTTH<\/h2>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p><strong>Acc\u00e8s Internet haut d\u00e9bit :<\/strong> La FTTH peut fournir des d\u00e9bits allant jusqu\u2019\u00e0 1 Gbps ou plus, permettant un streaming HD fluide, des t\u00e9l\u00e9chargements rapides et des jeux en ligne sans interruption.<\/p><\/li><li><p><strong>Faible latence :<\/strong> Cette technologie offre une latence r\u00e9duite, essentielle pour les applications en temps r\u00e9el telles que les visioconf\u00e9rences et les jeux en ligne.<\/p><\/li><li><p><strong>D\u00e9bits sym\u00e9triques :<\/strong> La FTTH fournit souvent des d\u00e9bits identiques pour l\u2019envoi et la r\u00e9ception, ce qui est particuli\u00e8rement avantageux pour des activit\u00e9s telles que les sauvegardes dans le cloud et la cr\u00e9ation de contenus.<\/p><\/li><li><p><strong>Fiabilit\u00e9 :<\/strong> Les c\u00e2bles en fibre optique sont moins sensibles aux <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/fr\/glossary\/what-is-electromagnetic-interference\/\">interf\u00e9rence \u00e9lectromagn\u00e9tique<\/a> et aux facteurs environnementaux, garantissant une connexion stable.<\/p><\/li><li><p><strong>Compatible avec les technologies \u00e9mergentes telles<\/strong> La grande capacit\u00e9 de bande passante de la FTTH soutient les progr\u00e8s technologiques futurs et l\u2019augmentation continue des besoins en donn\u00e9es.<\/p><\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Applications de la FTTH<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La FTTH transforme divers secteurs :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>R\u00e9sidentiel :<\/strong> Fournit un acc\u00e8s Internet ultra-rapide aux foyers, prenant en charge plusieurs appareils et les applications domotiques.<\/p><\/li><li><p><strong>Entreprise :<\/strong> Am\u00e9liore la productivit\u00e9 gr\u00e2ce \u00e0 un acc\u00e8s Internet fiable et haut d\u00e9bit, facilitant le t\u00e9l\u00e9travail et les services cloud.<\/p><\/li><li><p><strong>Sant\u00e9 :<\/strong> Soutient la t\u00e9l\u00e9m\u00e9decine, la surveillance \u00e0 distance des patients et l\u2019acc\u00e8s aux dossiers m\u00e9dicaux \u00e9lectroniques.<\/p><\/li><li><p><strong>\u00c9ducation :<\/strong> Permet l\u2019apprentissage en ligne, les salles de classe virtuelles et l\u2019acc\u00e8s aux ressources p\u00e9dagogiques.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Modules optiques LINK-PP pour FTTH<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1506a789f2154eb9bd332818d3bf2996.webp\" alt=\"FTTH Optical Transceivers\" class=\"wp-image-4168\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1506a789f2154eb9bd332818d3bf2996.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1506a789f2154eb9bd332818d3bf2996-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1506a789f2154eb9bd332818d3bf2996-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1506a789f2154eb9bd332818d3bf2996-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1506a789f2154eb9bd332818d3bf2996-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Chez LINK-PP, nous proposons une gamme de modules <strong>les modules<\/strong> et d\u2019accessoires haute performance con\u00e7us sp\u00e9cifiquement pour les d\u00e9ploiements FTTH. Voici quelques transceivers optiques FTTH LINK-PP :<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"width: 184px;\"\/><col style=\"width: 80px;\"\/><col style=\"width: 131px;\"\/><col style=\"width: 104px;\"\/><col style=\"width: 173px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\" colwidth=\"184\"><p>Mod\u00e8le du produit<\/p><\/th><th colspan=\"1\" rowspan=\"1\" colwidth=\"80\"><p>D\u00e9bit de donn\u00e9es<\/p><\/th><th colspan=\"1\" rowspan=\"1\" colwidth=\"131\"><p>Longueur d\u2019onde <\/p><\/th><th colspan=\"1\" rowspan=\"1\" colwidth=\"104\"><p>Distance<\/p><\/th><th colspan=\"1\" rowspan=\"1\" colwidth=\"173\"><p>Application dans la FTTH<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"184\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/478230.htm\"><strong>LS-MM851G-S5C<\/strong><\/a><\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"80\"><p>1,25 G<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"131\"><p>850nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"104\"><p>500 m (MMF)<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"173\"><p>Connexions \u00e0 courte port\u00e9e dans les b\u00e2timents ou les locaux des abonn\u00e9s<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"184\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/488475.htm\"><strong>LS-SM311G-02I<\/strong><\/a><\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"80\"><p>1,25 G<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"131\"><p>1310 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"104\"><p>2 km (SMF)<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"173\"><p>Transmission GPON descendante depuis l\u2019OLT vers le r\u00e9partiteur\/ONT<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"184\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/488431.htm\"><strong>LS-SM551G-60C<\/strong><\/a><\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"80\"><p>1,25 G<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"131\"><p>Requiert un c\u00e2blage standard OS1 ou OS2 de fil \u00e0 vide simple.<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"104\"><p>60 km (SMF)<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"173\"><p>Liaison de retour montante depuis l\u2019ONT vers l\u2019OLT<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >\u25b6 Conclusion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La FTTH repr\u00e9sente l\u2019apog\u00e9e de la technologie de large bande, offrant une vitesse, une fiabilit\u00e9 et une \u00e9volutivit\u00e9 in\u00e9gal\u00e9es. Gr\u00e2ce aux solutions <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-26155-1g-sfp.htm?ca=1453&amp;cv=8281\">de modules SFP LINK-PP,<\/a>, le d\u00e9ploiement d\u2019un r\u00e9seau FTTH robuste et pr\u00eat pour l\u2019avenir devient accessible. Adoptez l\u2019avenir de la connectivit\u00e9 Internet avec la FTTH et LINK-PP.<\/p>","protected":false},"excerpt":{"rendered":"<p>Discover FTTH technology\u2014how it works, its advantages, and how LINK-PP&#8217;s solutions can enhance your broadband experience.<\/p>","protected":false},"author":1,"featured_media":4169,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[27],"tags":[26],"class_list":["post-4170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-glossary","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/4170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/comments?post=4170"}],"version-history":[{"count":5,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/4170\/revisions"}],"predecessor-version":[{"id":11130,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/posts\/4170\/revisions\/11130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/media\/4169"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/media?parent=4170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/categories?post=4170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/fr\/wp-json\/wp\/v2\/tags?post=4170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}