{"id":3870,"date":"2025-11-05T11:12:00","date_gmt":"2025-11-05T11:12:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/glossary\/what-is-mcu-microcontroller-unit-explained\/"},"modified":"2026-06-22T05:32:47","modified_gmt":"2026-06-22T05:32:47","slug":"what-is-mcu-microcontroller-unit-explained","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/es\/glossary\/what-is-mcu-microcontroller-unit-explained","title":{"rendered":"\u00bfQu\u00e9 es una MCU? Unidad de microcontrolador explicada para el dise\u00f1o embebido"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/44447870208046b68e99d7012ee7ee59.webp\" alt=\"MCU (microcontroller unit) \" class=\"wp-image-3866\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/44447870208046b68e99d7012ee7ee59.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/44447870208046b68e99d7012ee7ee59-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/44447870208046b68e99d7012ee7ee59-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/44447870208046b68e99d7012ee7ee59-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/44447870208046b68e99d7012ee7ee59-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\uded1 \u00bfQu\u00e9 es una UCM (Unidad de Microcontrolador)?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">An <strong>MCU (unidad de microcontrolador)<\/strong> es un sistema inform\u00e1tico compacto en un solo chip que integra una <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/es\/glossary\/what-is-cpu-central-processing-unit\/\">CPU<\/a>, memoria de programa no vol\u00e1til (Flash), memoria vol\u00e1til (<a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/es\/glossary\/ram-random-access-memory-explained\/\">RAM<\/a>) y una amplia gama de perif\u00e9ricos, incluidos GPIO, ADC, temporizadores, PWM, UART, I\u00b2C y SPI.<br\/>Las UCM est\u00e1n optimizadas para <strong>tareas de control deterministas y de bajo consumo<\/strong> y act\u00faan como el \u201ccerebro\u201d de millones de dispositivos embebidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde dispositivos port\u00e1tiles inteligentes hasta controladores industriales, las UCM permiten el procesamiento en tiempo real de se\u00f1ales, la interfaz con sensores y la toma de decisiones determinista con un consumo y costo m\u00ednimos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\uded1 Arquitectura de la UCM \u2014 Componentes principales<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >N\u00facleo de CPU y tuber\u00eda de instrucciones<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Las UCM modernas suelen utilizar n\u00facleos altamente eficientes y de bajo consumo, como ARM Cortex-M, RISC-V o n\u00facleos propietarios de 8 o 16 bits. Estos n\u00facleos ofrecen una ejecuci\u00f3n determinista de instrucciones, ideal para tareas embebidas en tiempo real.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Sistema de memoria<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Una UCM integra todos los elementos clave de memoria en el chip:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>Flash\/ROM<\/strong> \u2014 almacena el firmware<\/p><\/li><li><p><strong>SRAM<\/strong> \u2014 contiene variables en tiempo de ejecuci\u00f3n, pilas y b\u00faferes<\/p><\/li><li><p><strong>Opcional <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/es\/glossary\/eeprom-electrically-erasable-programmable-read-only-memory\/\"><strong>EEPROM<\/strong><\/a> \u2014 retiene datos de configuraci\u00f3n<\/p><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" >Perif\u00e9ricos e interfaces integrados<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Las UCM incluyen interfaces esenciales para controlar directamente el hardware:<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"width: 178px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\" colwidth=\"178\"><p>Perif\u00e9rico<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Funci\u00f3n<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"178\"><p>GPIO<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Interruptores, LEDs, sensores, entradas de interrupci\u00f3n<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"178\"><p>ADC<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Convierte se\u00f1ales anal\u00f3gicas de sensores en valores digitales<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"178\"><p>Temporizadores \/ PWM<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Control de temporizaci\u00f3n, accionadores de motores e iluminaci\u00f3n<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"178\"><p>UART \/ SPI \/ I\u00b2C<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Comunicaci\u00f3n con m\u00f3dulos y sensores<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"178\"><p>DMA<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Descarga del movimiento de datos desde la CPU<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"178\"><p>Vigilante (Watchdog)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Mecanismo de fiabilidad y recuperaci\u00f3n segura<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\uded1 Por qu\u00e9 los ingenieros eligen UCM<\/h2>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"width: 215px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\" colwidth=\"215\"><p>Ventaja<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Descripci\u00f3n<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"215\"><p>Bajo consumo<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Modos de suspensi\u00f3n, activaci\u00f3n r\u00e1pida y compatibilidad con bater\u00edas<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"215\"><p>Bajo costo<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>La arquitectura de un solo chip reduce la lista de materiales (BOM)<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"215\"><p>Control en tiempo real<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Respuesta determinista a interrupciones para una temporizaci\u00f3n precisa<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"215\"><p>Peque\u00f1o tama\u00f1o f\u00edsico<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Ideal para dise\u00f1os de productos compactos<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"215\"><p>Ecosistema amplio<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Cadena de herramientas madura, bibliotecas y soporte para sistemas operativos en tiempo real (RTOS)<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Las UCM sobresalen en <strong>aplicaciones de bajo consumo, sensibles al costo y con temporizaci\u00f3n fiable<\/strong> .<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\uded1 UCM frente a UPM frente a SoC<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/853322e7e7f74f7183eac1ce741ecd5a.webp\" alt=\"MCU vs MPU vs SoC\" class=\"wp-image-3867\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/853322e7e7f74f7183eac1ce741ecd5a.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/853322e7e7f74f7183eac1ce741ecd5a-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/853322e7e7f74f7183eac1ce741ecd5a-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/853322e7e7f74f7183eac1ce741ecd5a-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/853322e7e7f74f7183eac1ce741ecd5a-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"width: 135px;\"\/><col style=\"width: 184px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\" colwidth=\"135\"><p>Caracter\u00edstica<\/p><\/th><th colspan=\"1\" rowspan=\"1\" colwidth=\"184\"><p>UCM<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>UPM<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>SoC<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"135\"><p>Uso principal<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"184\"><p>Control en tiempo real<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Sistema operativo de alto rendimiento<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Funciones convergentes<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"135\"><p>Memoria<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"184\"><p>En el chip<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Requiere DRAM externa<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>N\u00facleos mixtos + IP complejo<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"135\"><p>Sistema operativo<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"184\"><p>C\u00f3digo nativo \/ RTOS<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Linux \/ Android<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Puede ejecutar Linux<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"135\"><p>Casos de uso<\/p><\/td><td colspan=\"1\" rowspan=\"1\" colwidth=\"184\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/es\/knowledge-center\/iot-internet-of-things-definition-and-real-world-examples\/\">IoT<\/a>, control, industrial<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Interfaz de usuario, redes, pasarelas inteligentes<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Computaci\u00f3n m\u00f3vil, perimetral y automotriz<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Regla simplificada:<\/strong><br\/>Elija <strong>UCM<\/strong> for <strong>control en tiempo real y de bajo consumo<\/strong>; elegir <strong>MPU\/SoC<\/strong> for <strong>sistema operativo avanzado y computaci\u00f3n intensiva<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\uded1 Aplicaciones comunes de MCU<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >Consumo e IoT<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>Enchufes inteligentes, electrodom\u00e9sticos<\/p><\/li><li><p>Dispositivos port\u00e1tiles y de salud<\/p><\/li><li><p>Sensores inal\u00e1mbricos de bajo consumo<\/p><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" >Automoci\u00f3n y movilidad<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>M\u00f3dulos de control de carrocer\u00eda<\/p><\/li><li><p>Nodos de fusi\u00f3n de sensores<\/p><\/li><li><p>Controladores de bater\u00edas para veh\u00edculos el\u00e9ctricos<\/p><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" >Control industrial y perimetral<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/es\/glossary\/plc-programmable-logic-controller-for-industrial-automation-guide\/\">PLC<\/a>funciones de control tipo<\/p><\/li><li><p>Sensores y actuadores de automatizaci\u00f3n<\/p><\/li><li><p>Medidores de energ\u00eda y pasarelas IIoT<\/p><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" >Dispositivos de red y conectividad<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Muchos dispositivos basados en MCU integran <strong>redes Ethernet, PoE y serie<\/strong>, a menudo combinados con <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-17492-integrated-rj45-connector.htm\"><strong>MagJacks<\/strong><\/a> para una se\u00f1alizaci\u00f3n fiable entre PHY y RJ45.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\uded1 Consideraciones de dise\u00f1o para dispositivos Ethernet basados en MCU<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >Planificaci\u00f3n de perif\u00e9ricos e interfaces<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Seleccione MCUs con perif\u00e9ricos de hardware que soporten:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>MAC Ethernet<\/p><\/li><li><p>DMA para un manejo eficiente de paquetes<\/p><\/li><li><p>Interfaz con PHY externo<\/p><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" >Requisito de PHY y magn\u00e9ticos LAN<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los dise\u00f1os Ethernet con MCU requieren:<\/p>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p>MAC (integrada en el MCU)<\/p><\/li><li><p>PHY externo<\/p><\/li><li><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-17548-lan-transformer.htm\"><strong>Magn\u00e9ticos LAN<\/strong><\/a> (transformador y filtro EMI)<\/p><\/li><li><p>conector RJ45<\/p><\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\" >Por qu\u00e9 los conectores RJ45 integrados son \u00fatiles<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-17492-integrated-rj45-connector.htm\">Conectores RJ45 con magn\u00e9ticos<\/a> simplifican:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>la integraci\u00f3n de magn\u00e9ticos Ethernet<\/p><\/li><li><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/es\/knowledge-center\/emc-ems-emi-electromagnetic-compatibility-susceptibility-interference\/\">EMI\/CEM<\/a> la conformidad normativa<\/p><\/li><li><p>el trazado en la placa y la huella<\/p><\/li><li><p>la implementaci\u00f3n de PoE<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\uded1 Lista de verificaci\u00f3n para la selecci\u00f3n de MCU<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>Rendimiento del n\u00facleo (MIPS, frecuencia de reloj, profundidad de pipeline)<\/p><\/li><li><p>Capacidad de memoria Flash y RAM<\/p><\/li><li><p>Resoluci\u00f3n y n\u00famero de canales del ADC<\/p><\/li><li><p>Disponibilidad de UART \/ SPI \/ I\u00b2C<\/p><\/li><li><p>Modos de bajo consumo y latencia de activaci\u00f3n<\/p><\/li><li><p>Caracter\u00edsticas de seguridad (arranque seguro, motores criptogr\u00e1ficos)<\/p><\/li><li><p>Compatibilidad con RTOS y madurez del ecosistema<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Familias populares de MCU incluyen <strong>STM32<\/strong>, <strong>NXP LPC<\/strong>, <strong>PIC \/ AVR<\/strong>, <strong>TI MSP430<\/strong>, and <strong>Espressif ESP32 \/ ESP32-C3<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dda8e7c457f140949814857bdb63801b.webp\" alt=\"What Is an MCU? \" class=\"wp-image-3868\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dda8e7c457f140949814857bdb63801b.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dda8e7c457f140949814857bdb63801b-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dda8e7c457f140949814857bdb63801b-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dda8e7c457f140949814857bdb63801b-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/dda8e7c457f140949814857bdb63801b-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\uded1 Buenas pr\u00e1cticas en el flujo de desarrollo<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>Escriba el firmware en <strong>C o C++<\/strong> con an\u00e1lisis est\u00e1tico y verificaciones estilo MISRA<\/p><\/li><li><p>Use <strong>Depuraci\u00f3n SWD\/JTAG<\/strong> y seguimiento en tiempo real<\/p><\/li><li><p>Implemente temporizadores watchdog y detecci\u00f3n de ca\u00edda de tensi\u00f3n<\/p><\/li><li><p>Planifique actualizaciones seguras de firmware \/ OTA cuando sea necesario<\/p><\/li><li><p>Validar <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/es\/knowledge-center\/emc-ems-emi-electromagnetic-compatibility-susceptibility-interference\/\">Conformidad EMC<\/a> desde las primeras etapas del dise\u00f1o<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\uded1 Conclusi\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Las MCU<\/strong> son la base del control embebido moderno: compactas, eficientes y vers\u00e1tiles.<br\/>En sistemas conectados, combinar una MCU con un PHY y un <strong>conector RJ45 MagJack integrado<\/strong> mejora la integridad de la se\u00f1al, reduce la complejidad de la lista de materiales (BOM) y acelera la certificaci\u00f3n del producto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para hardware Ethernet robusto en dispositivos embebidos, explore <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-17492-integrated-rj45-connector.htm\"><strong>Cartera industrial de MagJack de LINK-PP<\/strong><\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Aprenda qu\u00e9 es una MCU (unidad de microcontrolador), su arquitectura, perif\u00e9ricos comunes y c\u00f3mo las MCU alimentan los sistemas embebidos \u2014 adem\u00e1s de enlaces pr\u00e1cticos a soluciones RJ45 MagJack.<\/p>","protected":false},"author":1,"featured_media":3869,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[27],"tags":[22,23],"class_list":["post-3870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-glossary","tag-integrated-rj45-connectors","tag-link-pp-lan-transformers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/posts\/3870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/comments?post=3870"}],"version-history":[{"count":5,"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/posts\/3870\/revisions"}],"predecessor-version":[{"id":10932,"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/posts\/3870\/revisions\/10932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/media\/3869"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/media?parent=3870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/categories?post=3870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/tags?post=3870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}