{"id":3339,"date":"2025-12-08T00:00:00","date_gmt":"2025-12-08T00:00:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/glossary\/what-is-direct-memory-access-dma-explained\/"},"modified":"2026-06-09T09:45:33","modified_gmt":"2026-06-09T09:45:33","slug":"what-is-direct-memory-access-dma-explained","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/es\/glossary\/what-is-direct-memory-access-dma-explained","title":{"rendered":"\u00bfQu\u00e9 es el acceso directo a la memoria? Explicaci\u00f3n de DMA"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1408\" height=\"768\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/296a5f4af1ba4c899c76c6ac9b8d0a08.jpg\" alt=\"What Is Direct Memory Access (DMA)?\" class=\"wp-image-3336\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/296a5f4af1ba4c899c76c6ac9b8d0a08.jpg 1408w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/296a5f4af1ba4c899c76c6ac9b8d0a08-300x164.jpg 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/296a5f4af1ba4c899c76c6ac9b8d0a08-1024x559.jpg 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/296a5f4af1ba4c899c76c6ac9b8d0a08-768x419.jpg 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/296a5f4af1ba4c899c76c6ac9b8d0a08-18x10.jpg 18w\" sizes=\"(max-width: 1408px) 100vw, 1408px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En el mundo de la inform\u00e1tica, la velocidad lo es todo. Ya sea que est\u00e9 jugando, transmitiendo video en 4K o procesando conjuntos masivos de datos en un centro de datos, el movimiento eficiente de los datos es fundamental. En el coraz\u00f3n de esta transferencia de datos a alta velocidad se encuentra una tecnolog\u00eda crucial, aunque a menudo pasada por alto: <strong>Acceso directo a la memoria (DMA)<\/strong>. Esta publicaci\u00f3n desmitificar\u00e1 el DMA, explicando c\u00f3mo funciona, por qu\u00e9 es indispensable para el rendimiento moderno y su papel en hardware de vanguardia como el de alta velocidad <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\"><strong>transceptores \u00f3pticos<\/strong><\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u2705 Conclusiones clave<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>Acceso directo a la memoria (DMA)<\/strong> permite que los dispositivos muevan datos directamente a la memoria. La CPU no tiene que ayudar. Esto hace que su computadora funcione m\u00e1s r\u00e1pido y mejor.<\/p><\/li><li><p>Existen distintos tipos de DMA. El modo r\u00e1faga y el robo de ciclos son ejemplos. Cada tipo ayuda con distintas necesidades de transferencia de datos. Esto le ayuda a elegir el m\u00e1s adecuado para sus dispositivos.<\/p><\/li><li><p>El DMA reduce la carga de trabajo de la CPU. Esto permite que su computadora realice m\u00faltiples tareas simult\u00e1neamente de forma m\u00e1s fluida. Tambi\u00e9n mejora el rendimiento en juegos, transmisi\u00f3n de video y edici\u00f3n de audio.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u2705 El concepto central: evitar el cuello de botella de la CPU<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Imagine un gran env\u00edo de libros (datos) que llega a una biblioteca (su computadora). Sin DMA, el bibliotecario jefe (la CPU) debe recibir personalmente cada caja, desempacarla y colocar cada libro en el estante correcto (RAM). Esto es extremadamente ineficiente y ocupa al bibliotecario con tareas rutinarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acceso directo a la memoria<\/strong> es como contratar un equipo especializado de log\u00edstica. El bibliotecario simplemente proporciona la direcci\u00f3n de entrega y las instrucciones. El equipo luego gestiona toda la transferencia de forma aut\u00f3noma, liberando al bibliotecario para gestionar tareas m\u00e1s cr\u00edticas, como ejecutar aplicaciones complejas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">T\u00e9cnicamente, <strong>DMA<\/strong> es una caracter\u00edstica que permite que ciertos subsistemas de hardware (como unidades de almacenamiento, tarjetas de red o tarjetas gr\u00e1ficas) accedan a la memoria principal del sistema (RAM) de forma independiente, sin requerir intervenci\u00f3n constante de la <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/es\/glossary\/what-is-cpu-central-processing-unit\/\"><strong>Unidad central de procesamiento (CPU)<\/strong><\/a>. Esto descarga a la CPU de la tarea agotadora de copiar cada byte de datos, mejorando dr\u00e1sticamente la eficiencia y el rendimiento general del sistema.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u2705 \u00bfC\u00f3mo funciona el DMA? Desglose paso a paso<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/349a78afb11b4e61b2a2302ccb13c0cc.webp\" alt=\"Direct Memory Access\" class=\"wp-image-3337\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/349a78afb11b4e61b2a2302ccb13c0cc.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/349a78afb11b4e61b2a2302ccb13c0cc-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/349a78afb11b4e61b2a2302ccb13c0cc-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/349a78afb11b4e61b2a2302ccb13c0cc-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/349a78afb11b4e61b2a2302ccb13c0cc-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El proceso de DMA lo gestiona un <strong>Controlador de DMA (DMAC)<\/strong>, a menudo integrado en los conjuntos de chips modernos o directamente en los propios dispositivos de entrada\/salida. A continuaci\u00f3n se presenta una secuencia simplificada:<\/p>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p style=\"margin: 0px;\"><strong>Configuraci\u00f3n por la CPU:<\/strong> La CPU programa el DMAC. Le proporciona la <strong>direcci\u00f3n de origen<\/strong> (por ejemplo, ubicaci\u00f3n en una SSD), la <strong>direcci\u00f3n de destino<\/strong> (un bloque en RAM) y la <strong>cantidad de datos<\/strong> que se va a transferir.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Solicitud de transferencia:<\/strong> El dispositivo perif\u00e9rico (por ejemplo, un <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/470377.htm\"><strong>transceptor \u00f3ptico LINK-PP 400G QSFP-DD DR4<\/strong><\/a> que recibe datos de red) indica que est\u00e1 listo para transferir datos.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>El DMA asume el control:<\/strong> El DMAC solicita el control del bus del sistema a la CPU (un proceso denominado <em>arbitraje de bus<\/em>). Una vez concedido, la CPU se desconecta temporalmente del bus.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Movimiento directo de datos:<\/strong> El DMAC gestiona la transferencia de datos directamente entre el dispositivo y la RAM. Durante este tiempo, la CPU puede continuar con otros c\u00e1lculos.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Finalizaci\u00f3n e interrupci\u00f3n:<\/strong> Una vez completada la transferencia, el DMAC libera el bus y env\u00eda una <strong>se\u00f1al de interrupci\u00f3n<\/strong> a la CPU. La CPU entonces sabe que los datos est\u00e1n listos para su procesamiento.<\/p><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Dos modos principales rigen c\u00f3mo interact\u00faa el DMAC con el bus:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Robo de ciclos:<\/strong> El DMAC \u201croba\u201d ciclos de bus a la CPU cuando esta no los est\u00e1 utilizando. Esto es eficiente, pero puede ralentizar ligeramente a la CPU.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Modo r\u00e1faga:<\/strong> El DMAC toma el control total del bus durante toda la transferencia. Esto es extremadamente r\u00e1pido para grandes bloques de datos, pero puede hacer que la CPU espere (<strong>espera de la CPU<\/strong>).<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La siguiente tabla resume las diferencias clave:<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p>Caracter\u00edstica<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Sin DMA<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Con DMA<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Participaci\u00f3n de la CPU<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Alta. La CPU copia cada byte.<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Baja. La CPU solo configura la transferencia y recibe una notificaci\u00f3n.<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Eficiencia<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Baja. La CPU no queda sobrecargada.<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Muy alta. La CPU y las operaciones de E\/S trabajan en paralelo.<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Velocidad para transferencias grandes<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Lenta. Limitada por el ancho de banda de la CPU.<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Muy r\u00e1pida. Usa un controlador dedicado.<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Capacidad de respuesta del sistema<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Puede degradarse bajo una carga intensa de E\/S.<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Se mantiene, ya que la CPU queda libre para tareas cr\u00edticas.<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Mejor para<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Transferencias peque\u00f1as y espor\u00e1dicas de datos.<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p><strong>Transferencias de datos de alto rendimiento<\/strong> como carga de archivos, captura de video o procesamiento de paquetes de red.<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u2705 \u00bfPor qu\u00e9 es cr\u00edtico el DMA hoy en d\u00eda? Aplicaciones modernas<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El DMA no es una tecnolog\u00eda nueva, pero su importancia ha crecido exponencialmente debido a las exigencias de la inform\u00e1tica moderna:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Computaci\u00f3n de alto rendimiento (HPC) e IA:<\/strong> Mover enormes conjuntos de datos de entrenamiento entre almacenamiento, memoria de GPU y memoria del sistema depende de avanzadas <strong>transferencias PCIe DMA<\/strong>.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Centros de datos y redes:<\/strong> Unidades SSD NVMe ultrarr\u00e1pidas y tarjetas de red Ethernet de <strong>100\/400 gigabits por segundo<\/strong> and <strong>utilizan DMA para alcanzar sus velocidades nominales, garantizando baja latencia y alto rendimiento. Tecnolog\u00edas como<\/strong> llevan esto un paso m\u00e1s all\u00e1, permitiendo el acceso directo a la memoria entre servidores a trav\u00e9s de una red. <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/es\/glossary\/remote-direct-memory-access-rdma-data-transfer-speed-latency\/\"><strong>RDMA (Acceso directo remoto a memoria)<\/strong><\/a> Multimedia y juegos:.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>La captura de video en tiempo real, el procesamiento de audio y la transmisi\u00f3n de texturas a una GPU dependen todas del DMA para evitar entrecortes y retrasos.<\/strong> Dispositivos de consumo:.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Incluso su tel\u00e9fono inteligente utiliza DMA para tareas como guardar fotos, cargar aplicaciones y transferir datos celulares.<\/strong> \u2705 DMA en acci\u00f3n: el v\u00ednculo cr\u00edtico con los m\u00f3dulos \u00f3pticos.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>Esto nos lleva a un componente clave en centros de datos modernos y redes de alta velocidad: el<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/7275ef2f350641cd9c439251ce38ba4a.webp\" alt=\"optical transceivers\" class=\"wp-image-3338\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/7275ef2f350641cd9c439251ce38ba4a.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/7275ef2f350641cd9c439251ce38ba4a-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/7275ef2f350641cd9c439251ce38ba4a-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/7275ef2f350641cd9c439251ce38ba4a-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/7275ef2f350641cd9c439251ce38ba4a-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">m\u00f3dulo \u00f3ptico <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\"><strong>m\u00f3dulo transceptor \u00f3ptico<\/strong><\/a>. Estos m\u00f3dulos, como el <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/470377.htm\"><strong>transceptor \u00f3ptico LINK-PP 400G QSFP-DD DR4<\/strong><\/a>, son los motores que convierten se\u00f1ales el\u00e9ctricas en luz y viceversa, permitiendo la transmisi\u00f3n de datos a trav\u00e9s de <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/es\/knowledge-center\/fiber-optic-cable-what-it-is-and-how-it-works-explained\/\"><strong>. Necesitan ser cuidadosamente grabados sobre una se\u00f1al portadora para viajar grandes distancias. Este proceso se llama<\/strong><\/a> a velocidades asombrosas de 400 gigabits por segundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces, \u00bfc\u00f3mo se relaciona la DMA con un m\u00f3dulo \u00f3ptico? El m\u00f3dulo en s\u00ed se ubica en una <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/es\/glossary\/what-is-nic-network-interface-card\/\"><strong>tarjeta de interfaz de red (NIC)<\/strong><\/a> o en un puerto de conmutaci\u00f3n. Este es el trabajo colaborativo sin interrupciones:<\/p>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p style=\"margin: 0px;\">The <strong>LINK-PP 400G<\/strong> El m\u00f3dulo \u00f3ptico recibe un flujo de datos \u00f3pticos y lo convierte en se\u00f1ales el\u00e9ctricas.<\/p><\/li><li><p style=\"margin: 0px;\">Estas se\u00f1ales el\u00e9ctricas (ahora paquetes de datos) son procesadas por el procesador especializado de la NIC.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Aqu\u00ed es donde brilla la DMA.<\/strong> La NIC utiliza la DMA para colocar de forma instant\u00e1nea y eficiente esos paquetes entrantes directamente en la memoria principal del servidor (RAM). Por otro lado, cuando el servidor env\u00eda datos, la NIC utiliza la DMA para extraer paquetes de la RAM destinados a la transmisi\u00f3n por el <strong>LINK-PP<\/strong> m\u00f3dulo.<\/p><\/li><li><p style=\"margin: 0px;\">Todo este proceso ocurre con una sobrecarga m\u00ednima de la CPU, lo que permite un procesamiento real <strong>a velocidad de l\u00ednea<\/strong> a 400 G. Sin la DMA, la CPU quedar\u00eda abrumada al intentar gestionar cada paquete individual, generando un cuello de botella masivo y haciendo poco pr\u00e1cticas tales soluciones <strong>de redes \u00f3pticas de alta velocidad.<\/strong> Para los ingenieros que dise\u00f1an sistemas que requieren un rendimiento m\u00e1ximo, seleccionar componentes con s\u00f3lidas.<\/p><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">capacidades de DMA <strong>es indispensable. Asociarse con un proveedor como<\/strong> , que garantiza que sus <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.link-pp.com\/\"><strong>LINK-PP<\/strong><\/a>, m\u00f3dulos \u00f3pticos de alta densidad QSFP-DD <strong>est\u00e1n dise\u00f1ados para una integraci\u00f3n perfecta con motores avanzados de DMA de las NIC, constituye un paso clave para construir una infraestructura de baja latencia y alto rendimiento.<\/strong> and <strong>OSFP<\/strong> \u2705 Conclusi\u00f3n: El h\u00e9roe silencioso de la velocidad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>La DMA es un pilar fundamental del rendimiento inform\u00e1tico moderno. Al permitir que componentes de hardware se comuniquen directamente con la memoria, libera a la CPU, reduce la latencia y desbloquea todo el potencial de dispositivos de alta velocidad, desde unidades NVMe hasta<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acceso directo a la memoria (DMA)<\/strong> transceptores \u00f3pticos de 400 G. <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-26045-400g-qsfp-dd-osfp-qsfp112.htm\"><strong>A medida que los vol\u00famenes de datos y los requisitos de velocidad siguen creciendo sin pausa, los principios de la DMA seguir\u00e1n siendo centrales. Tecnolog\u00edas de pr\u00f3xima generaci\u00f3n como<\/strong><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CXL (Compute Express Link) <strong>y una mayor adopci\u00f3n de<\/strong> RDMA sobre Ethernet convergente (RoCE) <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/es\/knowledge-center\/rdma-over-converged-ethernet-fast-low-latency-data-transfer\/\"><strong>son pasos evolutivos basados en este concepto esencial. Comprender la DMA es clave para entender c\u00f3mo nuestro mundo digital logra mover informaci\u00f3n a las velocidades impresionantes de las que dependemos actualmente.<\/strong><\/a> \u00bfQu\u00e9 significa DMA?.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u2705 FAQ<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >DMA significa Acceso Directo a Memoria. Lo usas cuando los dispositivos transfieren datos directamente a la memoria sin intervenir a la CPU.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 dispositivos utilizan DMA en tu computadora?.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Encuentras DMA en discos duros, tarjetas de red, tarjetas de sonido e impresoras. Estos dispositivos usan DMA para transferir datos r\u00e1pidamente.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 ocurre si no se usa DMA?.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Sin DMA, la CPU debe gestionar cada transferencia de datos. Esto ralentiza la computadora y la hace menos eficiente.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sin DMA, su CPU debe gestionar cada transferencia de datos. Esto ralentiza su ordenador y lo hace menos eficiente.<\/p>","protected":false},"excerpt":{"rendered":"<p>El acceso directo a memoria (DMA) permite que los dispositivos de hardware transfieran datos hacia o desde la memoria sin la intervenci\u00f3n de la CPU, lo que aumenta la velocidad y la eficiencia del sistema.<\/p>","protected":false},"author":1,"featured_media":3336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[27],"tags":[24,26],"class_list":["post-3339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-glossary","tag-link-pp","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/posts\/3339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/comments?post=3339"}],"version-history":[{"count":2,"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/posts\/3339\/revisions"}],"predecessor-version":[{"id":9146,"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/posts\/3339\/revisions\/9146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/media\/3336"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/media?parent=3339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/categories?post=3339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/es\/wp-json\/wp\/v2\/tags?post=3339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}