{"id":5938,"date":"2025-06-16T00:00:00","date_gmt":"2025-06-16T00:00:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/knowledge-center\/cwdm-vs-dwdm-differences-channel-capacity-distance-cost\/"},"modified":"2026-06-22T09:27:35","modified_gmt":"2026-06-22T09:27:35","slug":"cwdm-vs-dwdm-differences-channel-capacity-distance-cost","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/cwdm-vs-dwdm-differences-channel-capacity-distance-cost","title":{"rendered":"\u00bfCu\u00e1l es la diferencia entre CWDM y DWDM?"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ec7c0b712c0d41d28bc4498741296e64.webp\" alt=\"CWDM vs. DWDM\" class=\"wp-image-5936\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ec7c0b712c0d41d28bc4498741296e64.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ec7c0b712c0d41d28bc4498741296e64-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ec7c0b712c0d41d28bc4498741296e64-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ec7c0b712c0d41d28bc4498741296e64-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ec7c0b712c0d41d28bc4498741296e64-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Multiplexaci\u00f3n por divisi\u00f3n de onda (<\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/wdm-optical-transceiver-module-applications\/\"><strong>WDM<\/strong><\/a><strong>)<\/strong> revolucion\u00f3 la fibra \u00f3ptica al permitir que m\u00faltiples flujos de datos viajen simult\u00e1neamente sobre una sola fibra. Dos variantes dominantes\u2014<strong>CWDM (Multiplexaci\u00f3n por divisi\u00f3n de longitud de onda en banda ancha) <\/strong>\u03ba\u03b1\u03b9 <strong>DWDM (Multiplexaci\u00f3n por Divisi\u00f3n de Longitud de Onda Densa)<\/strong>\u2014potencian las redes modernas. La principal diferencia entre CWDM y DWDM radica en la capacidad de canal, la velocidad de datos y el alcance. Ambas utilizan multiplexaci\u00f3n por divisi\u00f3n de longitudes de onda, pero CWDM frente a DWDM ofrece caracter\u00edsticas distintas. La tabla siguiente compara especificaciones clave de la multiplexaci\u00f3n por divisi\u00f3n de longitudes de onda, como el espaciado de canales y la amplificaci\u00f3n, utilizando productos como <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/483258.htm\">LINK-PP LS-CW5310-20C<\/a> \u03ba\u03b1\u03b9 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/488746.htm\">LINK-PP LS-DW3210-40I<\/a> M\u00f3dulos \u00f3pticos.<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p>Caracter\u00edstica<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>CWDM<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>DWDM<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p>Espaciado entre canales<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>20 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>0,8 nm (100 GHz), 0,4 nm (50 GHz)<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p>N\u00famero de canales<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Hasta 18<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>40\u2013160<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p>Distancia de transmisi\u00f3n<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>tramos cortos a medianos<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>transmisi\u00f3n de largo alcance<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p>L\u00e1ser de modulaci\u00f3n<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>DFB sin refrigeraci\u00f3n<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>EML refrigerado\/sintonizable<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p>Consumo de energ\u00eda<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>0,5 W por m\u00f3dulo<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>4 W por m\u00f3dulo<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p>Capacidad de amplificaci\u00f3n<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>No<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u039d\u03b1\u03b9<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >Conclusiones clave<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>CWDM<\/strong> ofrece una soluci\u00f3n rentable y sencilla para distancias cortas a medianas con necesidades moderadas de datos, lo que la convierte en ideal para redes metropolitanas y empresariales.<\/p><\/li><li><p><strong>DWDM<\/strong> soporta una capacidad de datos mucho mayor y mayores distancias, utilizando tecnolog\u00eda avanzada adecuada para redes troncales y de largo recorrido que requieren escalabilidad y alto rendimiento.<\/p><\/li><li><p>Elegir entre CWDM y DWDM depende de la distancia de su red, los requisitos de capacidad, el presupuesto y los planes de crecimiento futuro, para garantizar la mejor adaptaci\u00f3n y valor.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >CWDM \u03ad\u03bd\u03b1\u03bd\u03c4\u03b9 DWDM<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/980ea5a903da45debe19da9ef0ef606c.webp\" alt=\"CWDM vs. DWDM\" class=\"wp-image-5937\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/980ea5a903da45debe19da9ef0ef606c.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/980ea5a903da45debe19da9ef0ef606c-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/980ea5a903da45debe19da9ef0ef606c-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/980ea5a903da45debe19da9ef0ef606c-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/980ea5a903da45debe19da9ef0ef606c-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" >Espaciado de canales y capacidad de longitud de onda<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>CWDM<\/strong>: Utiliza <strong>espaciado de 20 nm<\/strong> en un espectro amplio (1270\u20131610 nm), admitiendo hasta <strong>18 canales<\/strong>. Este espaciado relajado permite l\u00e1seres sin refrigeraci\u00f3n y filtros m\u00e1s simples, reduciendo significativamente los costos.<\/p><\/li><li><p style=\"margin: 0px;\"><span class=\"qc-p1-tag\"><strong>DWDM<\/strong>: Emplea espaciado ultraestrecho <strong>de 0,8\/0,4 nm<\/strong> (rejilla de 100 GHz\/50 GHz) en la banda C (1525\u20131565 nm) y la banda L (1570\u20131610 nm), integrando <strong>40\u2013160+ canales<\/strong> por fibra. Los l\u00e1seres de precisi\u00f3n refrigerados mantienen la estabilidad de longitud de onda para tr\u00e1fico de alta densidad.<\/span><\/p><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" >Distancia y amplificaci\u00f3n de se\u00f1al<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"text-align: left;\"><strong>CWDM<\/strong> es ideal para <strong>tramos cortos a medianos<\/strong> (hasta ~70\u201380 km), pero normalmente no puede amplificarse \u00f3pticamente debido a su espaciado amplio.<\/p><\/li><li><p style=\"text-align: left;\"><strong>DWDM<\/strong>, sin embargo, est\u00e1 dise\u00f1ado para<strong> transmisi\u00f3n de largo alcance<\/strong> transmisi\u00f3n (cientos a miles de kil\u00f3metros) y admite amplificaci\u00f3n \u00f3ptica, como EDFA, dentro de la banda C. <\/p><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" >Costo y eficiencia energ\u00e9tica<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El costo es una consideraci\u00f3n importante al planificar una red. Las diferencias en dise\u00f1o y rendimiento entre CWDM y DWDM generan variaciones significativas tanto en los gastos iniciales como en los operativos.<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p>Aspecto<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>CWDM<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>DWDM<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p>Inversi\u00f3n inicial<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>M\u00e1s bajo; adecuado para redes m\u00e1s peque\u00f1as<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>M\u00e1s alto; adecuado para redes a gran escala<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p>Costos operativos<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>M\u00e1s bajos; mantenimiento y consumo de energ\u00eda m\u00e1s sencillos<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>M\u00e1s altos; gesti\u00f3n y consumo de energ\u00eda m\u00e1s complejos<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p>Complejidad del equipo<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Componentes simples y pasivos<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Componentes complejos y activos<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">CWDM ofrece una soluci\u00f3n rentable para ampliar el ancho de banda sin tender nueva fibra. Sus transceptores y multiplexores son menos costosos, y el sistema consume menos energ\u00eda. DWDM requiere una inversi\u00f3n inicial mayor debido al equipo especializado y a los requisitos m\u00e1s estrictos de control, pero ofrece una capacidad y escalabilidad mucho mayores.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px 0px 4px;\"><strong>Los sistemas CWDM cuestan aproximadamente <span class=\"tp3t\">50%<\/span> menos<\/strong> que DWDM. Los ahorros clave provienen de:<\/p><ul><li><p style=\"margin: 0px;\">L\u00e1seres sin control de temperatura (0,5 W frente a los 4 W de DWDM)<\/p><\/li><li><p style=\"margin: 0px;\">Filtros y unidades de multiplexaci\u00f3n\/demultiplexaci\u00f3n de menor precisi\u00f3n.<\/p><\/li><\/ul><\/li><li><p style=\"margin: 0px;\"><strong>El precio premium de DWDM<\/strong> refleja su \u00f3ptica compleja, los amplificadores EDFA y los compensadores de dispersi\u00f3n para alcances ultra largos.<\/p><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" >Complejidad<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La complejidad afecta la instalaci\u00f3n, la gesti\u00f3n y la operaci\u00f3n a largo plazo. CWDM y DWDM difieren notablemente en este aspecto.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>CWDM<\/strong> utiliza componentes pasivos y l\u00e1seres sin refrigeraci\u00f3n, lo que resulta en menor complejidad. La instalaci\u00f3n y el mantenimiento son sencillos, y el sistema requiere menos energ\u00eda y control ambiental.<\/p><\/li><li><p><strong>DWDM<\/strong> implica hardware m\u00e1s complejo, incluidos l\u00e1seres refrigerados y gesti\u00f3n precisa de la temperatura. El espaciado denso de canales exige una configuraci\u00f3n cuidadosa y un monitoreo continuo. Los sistemas DWDM tambi\u00e9n requieren experiencia especializada para su configuraci\u00f3n y resoluci\u00f3n de problemas.<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La simplicidad de CWDM lo hace atractivo para organizaciones que buscan una implementaci\u00f3n f\u00e1cil y una baja sobrecarga operativa. La complejidad de DWDM se justifica por su capacidad para ofrecer alta capacidad y soporte para transmisiones de alta capacidad a largas distancias.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Aplicaciones<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CWDM es ideal para:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Redes empresariales o universitarias<\/strong>: Conexi\u00f3n de edificios separados \u226440 km.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Actualizaciones orientadas al costo<\/strong>: Adici\u00f3n de 4\u20138 canales sin sustituir la fibra.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>IoT industrial<\/strong>: Entornos robustos sin control de temperatura (p. ej., plantas de fabricaci\u00f3n).<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El DWDM domina:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Redes troncales de telecomunicaciones<\/strong>: Rutas de larga distancia entre ciudades.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Centros de datos hipercalibrados<\/strong>: Interconexiones de 400 G+ entre campus.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Fronthaul \/ backhaul 5G<\/strong>: Agregaci\u00f3n de alta densidad para unidades de banda base.<\/p><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" >\u03a3\u03cd\u03bd\u03bf\u03c8\u03b7<\/h3>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"width: 240px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\" colwidth=\"240\"><p>Caracter\u00edstica<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>CWDM<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>DWDM<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"240\"><p>Espaciado entre canales<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>~20\u202fnm (grueso)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>~0,8\u202fnm (denso)<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"240\"><p>Canales m\u00e1ximos<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Hasta ~18<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>40\u201396+<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"240\"><p>Distancia<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Hasta ~70\u201380\u202fkm, sin amplificaci\u00f3n<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Cientos a miles de km con amplificaci\u00f3n<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"240\"><p>Coste y consumo energ\u00e9tico<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Coste m\u00e1s bajo, l\u00e1seres y filtros sin refrigeraci\u00f3n<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Coste m\u00e1s alto, requiere refrigeraci\u00f3n y amplificadores<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\" colwidth=\"240\"><p>Casos de uso ideales<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Metro\/acceso, necesidades de pocos canales<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>N\u00facleo, red troncal, enlaces de alta velocidad y larga distancia<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >Elecci\u00f3n de la soluci\u00f3n adecuada<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >Opte por CWDM si necesita:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\">Implementaci\u00f3n r\u00e1pida para enlaces \u226480 km.<\/p><\/li><li><p style=\"margin: 0px;\">Escalabilidad econ\u00f3mica (p. ej., agregar 8 canales de forma incremental).<\/p><\/li><li><p style=\"margin: 0px;\">Compatibilidad con switches SFP+ existentes.<\/p><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" >Elija DWDM para:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\">Preparaci\u00f3n futura m\u00e1s all\u00e1 de los 100 G.<\/p><\/li><li><p style=\"margin: 0px;\">Maximizaci\u00f3n del retorno de la inversi\u00f3n en la fibra en conductos congestionados.<\/p><\/li><li><p style=\"margin: 0px;\">Requerimientos de larga distancia \/ alta capacidad ultra.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >Transceptores \u00f3pticos LINK\u2011PP: CWDM y DWDM<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0397 LINK\u2011PP \u03c0\u03c1\u03bf\u03c3\u03c6\u03ad\u03c1\u03b5\u03b9 \u03c5\u03c8\u03b7\u03bb\u03ae\u03c2 \u03c0\u03bf\u03b9\u03cc\u03c4\u03b7\u03c4\u03b1\u03c2 \u03bc\u03bf\u03bd\u03ac\u03b4\u03b5\u03c2 \u03c0\u03bf\u03c5 \u03c0\u03c1\u03bf\u03c3\u03b1\u03c1\u03bc\u03cc\u03b6\u03bf\u03bd\u03c4\u03b1\u03b9 \u03b1\u03ba\u03c1\u03b9\u03b2\u03ce\u03c2 \u03c3\u03b5 \u03ba\u03b1\u03b9 \u03c4\u03b9\u03c2 \u03b4\u03cd\u03bf \u03c4\u03b5\u03c7\u03bd\u03bf\u03bb\u03bf\u03b3\u03af\u03b5\u03c2:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>\u039f\u03c0\u03c4\u03b9\u03ba\u03bf\u03af \u03bc\u03b5\u03c4\u03b1\u03b4\u03cc\u03c4\u03b5\u03c2-\u03b4\u03ad\u03ba\u03c4\u03b5\u03c2 LINK\u2011PP CWDM:<\/strong> \u0395\u03be\u03b5\u03c1\u03b5\u03c5\u03bd\u03ae\u03c3\u03c4\u03b5 \u03c4\u03bf\u03c5\u03c2 \u03bc\u03b5\u03c4\u03b1\u03b4\u03cc\u03c4\u03b5\u03c2-\u03b4\u03ad\u03ba\u03c4\u03b5\u03c2 CWDM, \u03b9\u03b4\u03b1\u03bd\u03b9\u03ba\u03bf\u03cd\u03c2 \u03b3\u03b9\u03b1 \u03b5\u03c6\u03b1\u03c1\u03bc\u03bf\u03b3\u03ad\u03c2 \u03bc\u03b7\u03c4\u03c1\u03bf\u03c0\u03bf\u03bb\u03b9\u03c4\u03b9\u03ba\u03ae\u03c2 \u03c0\u03c1\u03cc\u03c3\u03b2\u03b1\u03c3\u03b7\u03c2 \u03c0\u03bf\u03c5 \u03b5\u03c0\u03b9\u03b4\u03b9\u03ce\u03ba\u03bf\u03c5\u03bd \u03b1\u03c0\u03bb\u03cc\u03c4\u03b7\u03c4\u03b1 \u03ba\u03b1\u03b9 \u03bf\u03b9\u03ba\u03bf\u03bd\u03bf\u03bc\u03b9\u03ba\u03ae \u03c0\u03c1\u03bf\u03c3\u03b9\u03c4\u03cc\u03c4\u03b7\u03c4\u03b1 \u2192 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm?ca=1484&amp;cv=8851\">\u039c\u03bf\u03bd\u03ac\u03b4\u03b1 LINK\u2011PP CWDM<\/a>.<\/p><\/li><li><p><strong>\u039f\u03c0\u03c4\u03b9\u03ba\u03bf\u03af \u03bc\u03b5\u03c4\u03b1\u03b4\u03cc\u03c4\u03b5\u03c2-\u03b4\u03ad\u03ba\u03c4\u03b5\u03c2 LINK\u2011PP DWDM:<\/strong> \u03a0\u03c1\u03bf\u03c3\u03c6\u03ad\u03c1\u03bf\u03c5\u03bd \u03b1\u03ba\u03c1\u03b9\u03b2\u03ae \u03ad\u03bb\u03b5\u03b3\u03c7\u03bf \u03bc\u03ae\u03ba\u03bf\u03c5\u03c2 \u03ba\u03cd\u03bc\u03b1\u03c4\u03bf\u03c2 \u03ba\u03b1\u03b9 \u03c3\u03c4\u03b1\u03b8\u03b5\u03c1\u03cc\u03c4\u03b7\u03c4\u03b1 \u03b8\u03b5\u03c1\u03bc\u03bf\u03ba\u03c1\u03b1\u03c3\u03af\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03b5\u03b3\u03ba\u03b1\u03c4\u03b1\u03c3\u03c4\u03ac\u03c3\u03b5\u03b9\u03c2 \u03c5\u03c0\u03bf\u03b4\u03bf\u03bc\u03ae\u03c2 \u03ba\u03b1\u03b9 \u03bc\u03b1\u03ba\u03c1\u03ac\u03c2 \u03b1\u03c0\u03cc\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2 \u2192 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm?ca=1484&amp;cv=8852\">\u039c\u03bf\u03bd\u03ac\u03b4\u03b1 LINK\u2011PP DWDM<\/a>.<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0393\u03b9\u03b1\u03c4\u03af \u03bf\u03b9 \u03bc\u03b7\u03c7\u03b1\u03bd\u03b9\u03ba\u03bf\u03af \u03b5\u03bc\u03c0\u03b9\u03c3\u03c4\u03b5\u03cd\u03bf\u03bd\u03c4\u03b1\u03b9 \u03c4\u03b7\u03bd LINK-PP<\/strong>:<br\/>\u2705 \u03a0\u03bb\u03ae\u03c1\u03b7\u03c2 \u03b4\u03b9\u03b1\u03b3\u03bd\u03c9\u03c3\u03c4\u03b9\u03ba\u03ae \u03bb\u03b5\u03b9\u03c4\u03bf\u03c5\u03c1\u03b3\u03af\u03b1 DOM \u03b3\u03b9\u03b1 \u03c0\u03b1\u03c1\u03b1\u03ba\u03bf\u03bb\u03bf\u03cd\u03b8\u03b7\u03c3\u03b7 \u03c4\u03b7\u03c2 \u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2 \u03c3\u03b5 \u03c0\u03c1\u03b1\u03b3\u03bc\u03b1\u03c4\u03b9\u03ba\u03cc \u03c7\u03c1\u03cc\u03bd\u03bf.<br\/>\u2705 \u0395\u03b3\u03b3\u03cd\u03b7\u03c3\u03b7 3 \u03b5\u03c4\u03ce\u03bd \u03ba\u03b1\u03b9 \u03b4\u03b9\u03b1\u03bb\u03b5\u03b9\u03c4\u03bf\u03c5\u03c1\u03b3\u03b9\u03ba\u03cc\u03c4\u03b7\u03c4\u03b1 \u03bc\u03b5 \u03c0\u03bf\u03bb\u03bb\u03b1\u03c0\u03bb\u03bf\u03cd\u03c2 \u03c0\u03c1\u03bf\u03bc\u03b7\u03b8\u03b5\u03c5\u03c4\u03ad\u03c2 (Cisco\/Juniper\/Arista).<br\/>\u2705 \u03a3\u03c7\u03b5\u03b4\u03b9\u03b1\u03c3\u03bc\u03bf\u03af \u03c7\u03b1\u03bc\u03b7\u03bb\u03ae\u03c2 \u03ba\u03b1\u03b8\u03c5\u03c3\u03c4\u03ad\u03c1\u03b7\u03c3\u03b7\u03c2 \u03b3\u03b9\u03b1 \u03c7\u03c1\u03b7\u03bc\u03b1\u03c4\u03bf\u03c0\u03b9\u03c3\u03c4\u03c9\u03c4\u03b9\u03ba\u03ac\/\u03a4\u039d \u03c3\u03c5\u03bc\u03c0\u03bb\u03ad\u03b3\u03bc\u03b1\u03c4\u03b1.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >V\u00e9ase tambi\u00e9n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/wdm-optical-transceiver-module-applications\/\">Exploraci\u00f3n de la tecnolog\u00eda WDM y sus aplicaciones en redes \u00f3pticas<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/ddm-dom-in-optical-transceivers\/\">\u0397 \u03c3\u03b7\u03bc\u03b1\u03c3\u03af\u03b1 \u03c4\u03b7\u03c2 \u03c8\u03b7\u03c6\u03b9\u03b1\u03ba\u03ae\u03c2 \u03c0\u03b1\u03c1\u03b1\u03ba\u03bf\u03bb\u03bf\u03cd\u03b8\u03b7\u03c3\u03b7\u03c2 \u03c3\u03c4\u03b9\u03c2 \u03c3\u03c5\u03c3\u03ba\u03b5\u03c5\u03ad\u03c2 \u03bf\u03c0\u03c4\u03b9\u03ba\u03ce\u03bd \u03bc\u03b5\u03c4\u03b1\u03b4\u03bf\u03c4\u03ce\u03bd-\u03b4\u03b5\u03ba\u03c4\u03ce\u03bd<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/dwdm-tunable-optical-transceiver-modules\/\">\u0397 \u03c0\u03b1\u03c1\u03bf\u03c5\u03c3\u03af\u03b1\u03c3\u03b7 \u03c4\u03bf\u03c5 \u03b4\u03b9\u03ba\u03c4\u03cd\u03bf\u03c5 LINK-PP \u03ba\u03b1\u03b9 \u03c4\u03c9\u03bd \u03bc\u03b5\u03bb\u03ce\u03bd \u03c4\u03b7\u03c2 \u03ba\u03bf\u03b9\u03bd\u03cc\u03c4\u03b7\u03c4\u03ac\u03c2 \u03c4\u03bf\u03c5<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>CWDM frente a DWDM: \u00d3ptica metropolitana de 8 canales rentable frente a sistemas de larga distancia de alta densidad con 96+ canales. Elija los transceptores \u00f3pticos LINK-PP para ambas soluciones WDM.<\/p>","protected":false},"author":1,"featured_media":5936,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[26],"class_list":["post-5938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowledge-center","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/comments?post=5938"}],"version-history":[{"count":4,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5938\/revisions"}],"predecessor-version":[{"id":11462,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5938\/revisions\/11462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/media\/5936"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/media?parent=5938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/categories?post=5938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/tags?post=5938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}