{"id":5417,"date":"2025-08-16T00:00:00","date_gmt":"2025-08-16T00:00:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/knowledge-center\/100g-qsfp28-optical-transceivers-selection-guide\/"},"modified":"2026-06-22T09:08:37","modified_gmt":"2026-06-22T09:08:37","slug":"100g-qsfp28-optical-transceivers-selection-guide","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/100g-qsfp28-optical-transceivers-selection-guide","title":{"rendered":"\u039f\u03bb\u03bf\u03ba\u03bb\u03b7\u03c1\u03c9\u03bc\u03ad\u03bd\u03bf\u03c2 \u03bf\u03b4\u03b7\u03b3\u03cc\u03c2 \u03b5\u03c0\u03b9\u03bb\u03bf\u03b3\u03ae\u03c2 \u03bf\u03c0\u03c4\u03b9\u03ba\u03ce\u03bd \u03bc\u03b5\u03c4\u03b1\u03b4\u03bf\u03c4\u03ce\u03bd-\u03b1\u03c0\u03bf\u03b4\u03ad\u03ba\u03c4\u03b7\u03c2 100G QSFP28: SR4, LR4, CWDM4 \u03ba\u03b1\u03b9 \u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03cc\u03c4\u03b5\u03c1\u03b1"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/a117d9c4ef2b4fb1ba276f80e39727aa.webp\" alt=\"100g qsfp28 transceivers\" class=\"wp-image-5415\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/a117d9c4ef2b4fb1ba276f80e39727aa.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/a117d9c4ef2b4fb1ba276f80e39727aa-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/a117d9c4ef2b4fb1ba276f80e39727aa-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/a117d9c4ef2b4fb1ba276f80e39727aa-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/a117d9c4ef2b4fb1ba276f80e39727aa-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><span class=\"qc-p1-tag\">Cuando elija un <\/span><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-27045-100g-qsfp28-sfp-dd.htm\"><span class=\"qc-p1-tag\"><strong>transceptor QSFP28 de 100 G<\/strong><\/span><\/a><span class=\"qc-p1-tag\">, considere las necesidades de su red. Verifique aspectos clave como la compatibilidad, la distancia que deben recorrer los datos, el tipo de fibra, el tipo de conector, el entorno de uso y su capacidad de funcionamiento futuro. Elegir transceptores \u00f3pticos QSFP28 que se adapten a su sistema mejora el rendimiento de su red y protege su inversi\u00f3n. <\/span><span class=\"qc-p1-tag\" style=\"color: rgb(64, 64, 64);\">Esta gu\u00eda definitiva aclara la confusi\u00f3n, analizando todas las principales opciones QSFP28 de 100 G \u2014desde <\/span><span class=\"qc-p1-tag\"><strong>SR4<\/strong><\/span><span class=\"qc-p1-tag\" style=\"color: rgb(64, 64, 64);\"> \u03ba\u03b1\u03b9 <\/span><span class=\"qc-p1-tag\"><strong>LR4<\/strong><\/span><span class=\"qc-p1-tag\" style=\"color: rgb(64, 64, 64);\"> hasta <\/span><span class=\"qc-p1-tag\"><strong>CWDM4<\/strong><\/span><span class=\"qc-p1-tag\" style=\"color: rgb(64, 64, 64);\">, <\/span><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/100g-single-lambda-transceivers-benefits-upgrades-performance\/\"><span class=\"qc-p1-tag\"><strong>Single Lambda<\/strong><\/span><\/a><span class=\"qc-p1-tag\" style=\"color: rgb(64, 64, 64);\">, y m\u00e1s all\u00e1\u2014, ayud\u00e1ndole a tomar una decisi\u00f3n informada para su <\/span><span class=\"qc-p1-tag\"><strong>conectividad de alta velocidad<\/strong><\/span><span class=\"qc-p1-tag\" style=\"color: rgb(64, 64, 64);\"> necesidades.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd \u00bfQu\u00e9 es un m\u00f3dulo \u00f3ptico QSFP28?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span class=\"qc-p1-tag\" style=\"color: rgb(64, 64, 64);\">\u03a4\u03bf \/ \u0397 \/ \u039f <strong>QSFP28 (QSFP28, factor de forma peque\u00f1o cu\u00e1druple)<\/strong> es el factor de forma est\u00e1ndar de la industria para Ethernet de 100 Gigabit (100GbE) y conexiones intercentro de datos de alta velocidad. Integra cuatro canales que operan a 25 Gbps o un \u00fanico canal de alta velocidad en un m\u00f3dulo compacto y extra\u00edble en caliente.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Desmitificando sus opciones QSFP28 de 100 G: un an\u00e1lisis t\u00e9cnico<\/strong><\/h2>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p style=\"margin: 0px 0px 4px;\"><strong>100G-SR4 (Alcance corto)<\/strong><\/p><ul><li><p style=\"margin: 0px;\"><strong>Tecnolog\u00eda:<\/strong> Fibra multimodo (MMF) paralela mediante 4 canales (4\u00d725G NRZ).<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Alcance:<\/strong> Hasta 70 m (MMF OM3), 100 m (MMF OM4) o 150 m (MMF OM5).<\/p><\/li><li><p style=\"margin: 0px;\"><strong>(MMF \u2013 OM3\/OM4\/OM5).<\/strong> Requiere <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/mpo-connectors-differences-8-12-16-24-fiber-comparison\/\"><strong>Conector MTP\/MPO-12<\/strong><\/a> Utiliza 4 fibras para transmisi\u00f3n (Tx) y 4 fibras para recepci\u00f3n (Rx) <strong>(8 fibras en total)<\/strong>.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Ideal para:<\/strong> <strong>Conmutaci\u00f3n en la parte superior del bastidor<\/strong>, <strong>enlaces intra-centro de datos<\/strong>, conectividad servidor-a-hoja dentro de bastidores o filas mediante <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/om1-om2-om3-om4-om5-multimode-fiber-guide\/\"><strong>cableado de fibra multimodo<\/strong><\/a>. Econ\u00f3mico para distancias cortas.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Ejemplo de modelo:<\/strong> QSFP28-100G-SR4 <strong>LINK-PP <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/473115.htm\"><strong>LQ-M85100-SR4C<br><\/strong><\/a> (compatible con OM3\/OM4\/OM5)<\/p><\/li><\/ul><\/li><li><p style=\"margin: 0px 0px 4px;\"><strong>100G-PSM4 (4 canales paralelos en fibra monomodo)<\/strong><\/p><ul><li><p style=\"margin: 0px;\"><strong>Tecnolog\u00eda:<\/strong> Fibra monomodo (SMF) paralela <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/what-is-single-mode-fiber-and-how-does-it-work\/\"><strong>(SMF)<\/strong><\/a> mediante 4 canales (4\u00d725G NRZ).<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Alcance:<\/strong> Normalmente hasta 500 m sobre SMF est\u00e1ndar.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>(MMF \u2013 OM3\/OM4\/OM5).<\/strong> Requiere <strong>Conector MTP\/MPO-12<\/strong> Utiliza 4 fibras para transmisi\u00f3n (Tx) y 4 fibras para recepci\u00f3n (Rx) <strong>(8 fibras en total)<\/strong>.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Ideal para:<\/strong> Enlaces intra-centro de datos o campus m\u00e1s largos que los permitidos por SR4, donde ya se ha desplegado infraestructura SMF o se prefiere por su escalabilidad futura. Menos com\u00fan que CWDM4\/LR4 para alcances SMF m\u00e1s largos.<\/p><\/li><\/ul><\/li><li><p style=\"margin: 0px 0px 4px;\"><strong>100G-LR4 \/ ER4 \/ ZR4 (Alcance largo \/ extendido \/ extendido+)<\/strong><\/p><ul><li><p style=\"margin: 0px;\"><strong>Tecnolog\u00eda:<\/strong> multiplexaci\u00f3n por divisi\u00f3n de longitud de onda gruesa <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/what-is-cwdm-understanding-coarse-wavelength-division-multiplexing\/\"><strong>(CWDM)<\/strong><\/a> sobre fibra monomodo d\u00faplex. Combina 4 longitudes de onda (aprox. 1295, 1300, 1304 y 1309 nm) sobre 2 fibras (1 Tx, 1 Rx). LR4 es el est\u00e1ndar; ER4 ofrece mayor alcance; ZR4 ofrece el alcance m\u00e1s largo.<\/p><\/li><li><p style=\"margin: 0px 0px 4px;\"><strong>Alcance:<\/strong><\/p><ul><li><p style=\"margin: 0px;\"><strong>LR4:<\/strong> Hasta 10 km<br><\/p><\/li><li><p style=\"margin: 0px;\"><strong>ER4:<\/strong> Hasta 40 km<\/p><\/li><li><p style=\"margin: 0px;\"><strong>ZR4:<\/strong> Hasta 80 km+<\/p><\/li><\/ul><\/li><li><p style=\"margin: 0px;\"><strong>(MMF \u2013 OM3\/OM4\/OM5).<\/strong> Utiliza conectores est\u00e1ndar <strong>duplex LC<\/strong> Requiere solo 2 fibras.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Ideal para:<\/strong> <strong>Interconexi\u00f3n entre centros de datos (DCI)<\/strong>, <strong>redes metropolitanas<\/strong>, enlaces entre edificios, capas de agregaci\u00f3n. Imprescindible para <strong>transmisi\u00f3n \u00f3ptica de larga distancia<\/strong>. ER4\/ZR4 est\u00e1n destinados a aplicaciones especializadas de mayor alcance.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Ejemplo de modelo:<\/strong> LINK-PP QSFP28-100G-LR4 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/472118.htm\"><strong>LQ-LW100-LR4C<br><\/strong><\/a> (10 km), LINK-PP QSFP28-100G-ER4 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/472708.htm\"><strong>LQ-LW100-ER4C<\/strong><\/a> (40 km), LINK-PP QSFP28-100G-ZR4 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/482513.htm\"><strong>LQ-LW100-ZR4C<\/strong><\/a> (80 km)<\/p><\/li><\/ul><\/li><li><p style=\"margin: 0px 0px 4px;\"><strong>100G-CWDM4<\/strong><\/p><ul><li><p style=\"margin: 0px;\"><strong>Tecnolog\u00eda:<\/strong> Similar al LR4, utiliza <strong>CWDM<\/strong> sobre fibra monomodo d\u00faplex, pero con longitudes de onda ligeramente diferentes (1271, 1291, 1311, 1331 nm) optimizadas para menor costo y consumo de energ\u00eda.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Alcance:<\/strong> Hasta 2 km. Definido por la MSA CWDM4.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>(MMF \u2013 OM3\/OM4\/OM5).<\/strong> Utiliza conectores est\u00e1ndar <strong>duplex LC<\/strong> Requiere solo 2 fibras.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Ideal para:<\/strong> Soluci\u00f3n rentable para <strong>enlaces SMF dentro del centro de datos<\/strong> hasta 2 km (por ejemplo, entre edificios en un campus o entre salas de datos m\u00e1s grandes). Una alternativa popular a PSM4 para fibra monomodo d\u00faplex.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Ejemplo de modelo:<\/strong> LINK-PP QSFP-100G-CWDM4 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/472577.htm\"><strong>LQ-CW100-FR4C<\/strong><\/a> (2 km)<\/p><\/li><\/ul><\/li><li><p style=\"margin: 0px 0px 4px;\"><strong>100G de una sola lambda (por ejemplo, FR1\/LR1\/ER1\/DR1\/ZR1)<\/strong><\/p><ul><li><p style=\"margin: 0px 0px 4px;\"><strong>Tecnolog\u00eda:<\/strong> Utiliza una <em>\u00fanica<\/em> longitud de onda de alta velocidad (por ejemplo, 53,125 Gbaud <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/what-is-pam4-four-level-pulse-amplitude-modulation-basics\/\"><strong>PAM4 \u03bc\u03bf\u03b4\u03cd\u03bb\u03c9\u03c3\u03b7<\/strong><\/a>) sobre fibra monomodo d\u00faplex. Incluye distintos alcances:<\/p><ul><li><p style=\"margin: 0px;\"><strong>FR1 (2 km) \/ LR1 (10 km):<\/strong> Est\u00e1ndares comunes.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>DR1 (500 m):<\/strong> Suele utilizar la longitud de onda de 1310 nm.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>ER1 (40 km) \/ ZR1 (80 km+):<\/strong> Variantes de mayor alcance.<\/p><\/li><\/ul><\/li><li><p style=\"margin: 0px;\"><strong>Alcance:<\/strong> Variable (500 m, 2 km, 10 km, 40 km, 80 km+).<\/p><\/li><li><p style=\"margin: 0px;\"><strong>(MMF \u2013 OM3\/OM4\/OM5).<\/strong> Utiliza conectores est\u00e1ndar <strong>duplex LC<\/strong> Requiere solo 2 fibras.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Ideal para:<\/strong> <strong>Arquitecturas de centros de datos de pr\u00f3xima generaci\u00f3n<\/strong>, simplificando la infraestructura de fibra (solo se necesitan 2 fibras por enlace) y prepar\u00e1ndose para 400G\/800G (que dependen fuertemente de PAM4). Ofrece <strong>mayor densidad de puertos<\/strong> potencial. Fundamental para <strong>dise\u00f1os de red preparados para el futuro<\/strong>.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Ejemplo de modelo:<\/strong> LINK-PP QSFP-100G-DR1 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/482616.htm\"><strong>LQ-SM31100-DR1C<\/strong><\/a> (10 km).<\/p><\/li><\/ul><\/li><li><p style=\"margin: 0px 0px 4px;\"><strong>100G-SWDM4 (Multiplexaci\u00f3n por divisi\u00f3n de longitud de onda de corta longitud)<\/strong><\/p><ul><li><p style=\"margin: 0px;\"><strong>Tecnolog\u00eda:<\/strong> Utiliza multiplexaci\u00f3n por divisi\u00f3n de longitud de onda sobre fibra multimodo. Combina 4 <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/overview-of-vcsel\/\"><strong>l\u00e1ser VCSEL.<\/strong><\/a>longitudes de onda basadas en l\u00e1ser (850, 880, 910, 940 nm) sobre 2 fibras (1 de transmisi\u00f3n, 1 de recepci\u00f3n).<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Alcance:<\/strong> Hasta 75 m (OM3), 100 m (OM4), 150 m (OM5).<\/p><\/li><li><p style=\"margin: 0px;\"><strong>(MMF \u2013 OM3\/OM4\/OM5).<\/strong> Utiliza conectores est\u00e1ndar <strong>duplex LC<\/strong> Requiere solo 2 fibras.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Ideal para:<\/strong> Aprovechando la infraestructura existente de <strong>cableado de fibra multimodo d\u00faplex LC<\/strong> para 100G, evitando la necesidad de actualizaciones a conectores MTP\/MPO. Ideal para <strong>estrategias de migraci\u00f3n de fibra<\/strong> donde predomina la fibra multimodo d\u00faplex.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Ejemplo de modelo:<\/strong> LINK-PP QSFP-100G-SWDM4 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/473140.htm\"><strong>ofrece una combinaci\u00f3n perfecta de rendimiento y valor, cumpliendo plenamente con los est\u00e1ndares MSA y sometido rigurosamente a pruebas de interoperabilidad.<\/strong><\/a> (100 m)<\/p><\/li><\/ul><\/li><li><p style=\"margin: 0px 0px 4px;\"><strong>100G bidireccional (BiDi)<\/strong><\/p><ul><li><p style=\"margin: 0px;\"><strong>Tecnolog\u00eda:<\/strong> Utiliza una <em>\u00fanica<\/em> de fibra. Logra comunicaci\u00f3n d\u00faplex completa a 100G transmitiendo y recibiendo en dos longitudes de onda diferentes (por ejemplo, Tx 1330 nm \/ Rx 1270 nm) sobre la misma fibra.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Alcance:<\/strong> Normalmente hasta 10 km o 20 km sobre fibra monomodo.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>(MMF \u2013 OM3\/OM4\/OM5).<\/strong> Utiliza una <strong>conector LC simplex \u00fanico<\/strong> Requiere solo una hebra de fibra por enlace.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Ideal para:<\/strong> <strong>Maximizaci\u00f3n de la infraestructura de fibra existente<\/strong> (duplicando la capacidad), <strong>escenarios de agotamiento de fibra<\/strong>, actualizaciones rentables donde la fibra es escasa. Fundamental para <strong>la optimizaci\u00f3n de la capacidad de fibra<\/strong>.<\/p><\/li><\/ul><\/li><li><p style=\"margin: 0px 0px 4px;\"><strong>M\u00f3dulos duales de tasa 100G\/112G<\/strong><\/p><ul><li><p style=\"margin: 0px;\"><strong>Tecnolog\u00eda:<\/strong> TOSA herm\u00e9tica con <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/what-is-lwdm-and-why-important-for-lans\/\"><strong>LAN-WDM<\/strong><\/a> soporte de l\u00e1ser DFB basado en 25,78 G\/s y 27,95 G\/s.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Alcance:<\/strong> Normalmente hasta 10 km sobre fibra monomodo<\/p><\/li><li><p style=\"margin: 0px;\"><strong>(MMF \u2013 OM3\/OM4\/OM5).<\/strong> Utiliza conectores est\u00e1ndar <strong>duplex LC<\/strong> Requiere solo 2 fibras.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Ideal para:<\/strong> Enlaces Ethernet 100GBASE-LR4, interconexiones Infiniband QDR y DDR, conexiones telecomunicaciones cliente de 100 G.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Ejemplo de modelo:<\/strong> LINK-PP <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/488452.htm\"><strong><strong>LQ-LW112-LR4C<\/strong><\/strong><\/a>.<\/p><\/li><\/ul><\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5d7fcaaefde14dedb89f4bc7ecd50005.webp\" alt=\"100g qsfp28 module\" class=\"wp-image-5416\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5d7fcaaefde14dedb89f4bc7ecd50005.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5d7fcaaefde14dedb89f4bc7ecd50005-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5d7fcaaefde14dedb89f4bc7ecd50005-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5d7fcaaefde14dedb89f4bc7ecd50005-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5d7fcaaefde14dedb89f4bc7ecd50005-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comparaci\u00f3n de transceptores QSFP28 de 100 G a primera vista<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p><strong>Tipo de m\u00f3dulo<br><\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>Tecnolog\u00eda<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>Longitud de onda<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>Tipo de fibra y conector<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>Alcance m\u00e1ximo<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>\u039a\u03cd\u03c1\u03b9\u03b1 \u0395\u03c6\u03b1\u03c1\u03bc\u03bf\u03b3\u03ae<\/strong><\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>100G-SR4<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>4\u00d725 G NRZ (MMF)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>850nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>MMF \/ MPO-12<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>70 m\u2013150 m<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Corto intra-DC, conmutaci\u00f3n ToR<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>100G-PSM4<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>4\u00d725 G NRZ (SMF)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>1310 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>SMF \/ MPO-12<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>500m<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Medio intra-DC\/campus (paralelo)<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>100G-LR4<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>4\u00d725 G LWDM<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>~1295\u20131310 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>SMF \/ LC Duplex<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>10km<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>DCI, metro, enlaces entre edificios<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>100G-ER4\/ZR4<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>4\u00d725 G LWDM<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>~1295\u20131310 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>SMF \/ LC Duplex<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>40 km \/ 80 km+<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>DCI de largo alcance, metro<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>100G-CWDM4<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>4\u00d725 G CWDM<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>1271\u20131331 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>SMF \/ LC Duplex<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>2km<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>SMF intra-DC rentable<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>100 G de una sola lambda<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>1\u00d7100 G PAM4<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>1310 nm (p. ej.)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>SMF \/ LC Duplex<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>500 m\u201380 km+<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>DC de pr\u00f3xima generaci\u00f3n, fibra simplificada<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>100G-SWDM4<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>4\u00d725 G WDM (MMF)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>850\u2013940 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>MMF \/ LC Duplex<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>75 m\u2013150 m<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Aprovechar el cableado MMF d\u00faplex<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>100G BiDi<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>1\u00d7100 G BiDi<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>p. ej., Tx1330\/Rx1270<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>SMF \/ LC simple<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>10 km\/20 km\/40 km<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Agotamiento de fibra, \u00fanica hebra<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Tasa dual (p. ej., LR4)<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>100 G \/ 112 G <\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>LAN-WDM, 1295\u20131309 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>SMF \/ LC d\u00faplex<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Depende del modo<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Flexibilidad de migraci\u00f3n y agregaci\u00f3n<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Selecci\u00f3n del m\u00f3dulo LINK-PP QSFP28 adecuado: consideraciones clave<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Distancia requerida:<\/strong> Este es el factor principal (SR4 para MMF &lt;150 m, CWDM4 para SMF de 2 km, LR4 para 10 km, etc.).<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Infraestructura de fibra:<\/strong> \u00bfQu\u00e9 ya est\u00e1 instalado? (MMF frente a SMF, MPO frente a LC d\u00faplex\/simple). SWDM4 usa MMF d\u00faplex; BiDi usa SMF simple.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Costo:<\/strong> SR4 y CWDM4 suelen tener un costo menor que LR4\/ER4 o Single Lambda. Los m\u00f3dulos BiDi pueden reducir los costos de fibra.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Consumo de energ\u00eda:<\/strong> CWDM4 y los m\u00f3dulos PAM4 m\u00e1s recientes <strong>(Lambda \u00fanica)<\/strong> suelen tener un consumo de energ\u00eda menor que LR4.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Preparaci\u00f3n para el futuro:<\/strong> Los m\u00f3dulos Single Lambda est\u00e1n alineados con las tecnolog\u00edas de 400G\/800G que utilizan <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/what-is-pam4-four-level-pulse-amplitude-modulation-basics\/\"><strong>PAM4<\/strong><\/a>.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Necesidades de tasa dual:<\/strong> \u00bfRequiere conectividad 4\u00d725 G o 4\u00d728 G ahora o en el futuro?<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Capacidad de fibra:<\/strong> \u00bfEs escasa la fibra? Los m\u00f3dulos BiDi duplican efectivamente su capacidad de fibra.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Optimice su red de 100 G con confianza<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La selecci\u00f3n del <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-27045-100g-qsfp28-sfp-dd.htm\"><strong>transceptor QSFP28 de 100 G<\/strong><\/a> es fundamental para lograr <strong>redes de alto rendimiento<\/strong>, <strong>arquitectura escalable de centros de datos<\/strong>, \u03ba\u03b1\u03b9 <strong>maximizar el retorno de la inversi\u00f3n (ROI)<\/strong> en su <strong>infraestructura de fibra \u00f3ptica<\/strong>. Al comprender las ventajas de cada tecnolog\u00eda \u2014desde la rentabilidad de los m\u00f3dulos <strong>100G-SR4<\/strong> para racks hasta las capacidades de largo alcance de <strong>100G-LR4\/ER4<\/strong>, la eficiencia en el uso de fibra de <strong>100G-BiDi<\/strong>, o la preparaci\u00f3n para el futuro de los <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/100g-single-lambda-transceivers-benefits-upgrades-performance\/\"><strong>m\u00f3dulos 100G Single Lambda (PAM4)<\/strong><\/a> \u2014, puede tomar decisiones estrat\u00e9gicas que se alineen con sus espec\u00edficos <strong>requisitos de dise\u00f1o de red<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfListo para implementar conectividad de 100 G de alto rendimiento?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LINK-PP ofrece un portafolio integral de m\u00f3dulos \u00f3pticos, <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/multi-source-agreements-optical-transceivers\/\"><strong>compatibles con el est\u00e1ndar MSA,<\/strong><\/a><strong> 100G QSFP28 confiables<\/strong>, incluyendo todos los tipos analizados: <strong>SR4<\/strong>, <strong>LR4<\/strong>, <strong>ER4<\/strong>, <strong>CWDM4<\/strong>, <strong>Lambda \u00fanica (DR1\/FR1)<\/strong>, <strong>SWDM4,<\/strong>, <strong>SR, LR, ER, BiDi<\/strong>, \u03ba\u03b1\u03b9 <strong>operaci\u00f3n <strong>dual-rate<\/strong>.<\/strong> Nuestros transceptores se someten a pruebas rigurosas de <strong>y cobertura de garant\u00eda m\u00e1s prolongada.<\/strong> y rendimiento, garantizando una integraci\u00f3n perfecta en sus <strong>Cisco<\/strong>, <strong>Arista<\/strong>, <strong>Juniper<\/strong>, <strong>switches y routers Mellanox<\/strong>, \u03ae <strong>Huawei<\/strong> .<\/p>\n\n\n\n<div class=\"alignnone qc-cover-wrapper has-custom-content-position is-position-center\" elementtype=\"div\" useimagebackground=\"false\" imgbg=\"\" imgbgpositionleft=\"50\" imgbgpositiontop=\"50\" overlay=\"#165DFF\" overlayopacity=\"0.8\" contentposition=\"center\" alt=\"\" parallax=\"false\" style=\"border-radius: 12px; padding-left: var(--qc-preset--spacing--60); padding-right: var(--qc-preset--spacing--60); padding-top: var(--qc-preset--spacing--50); padding-bottom: var(--qc-preset--spacing--50); background-color: rgb(245, 245, 245); height: auto;\"><div class=\"qc-cover-wrapper__inner-container\"><div style=\"flex-wrap: wrap; justify-content: center; display: flex;\"><div colmd=\"10\" class=\"col col-md-10\"><p style=\"text-align: center;\"><span class=\"qc-h1-tag\" style=\"color: var(--qc-color5);\">Soluciones LINK-PP<\/span><\/p><p style=\"text-align: center;\"><strong>\u00a1Explore hoy mismo la gama completa de m\u00f3dulos 100G QSFP28!<\/strong><\/p><div class=\"qc-buttons-wrapper\"><div justification=\"center\" class=\"qc-buttons-container is-horizontal is-content-justification-center\" style=\"margin-top: var(--qc-preset--spacing--0); margin-bottom: var(--qc-preset--spacing--0); gap: var(--qc-preset--spacing--40);\"><div link=\"https:\/\/www.l-p.com\/store-27045-100g-qsfp28-sfp-dd.htm\" opennewtab=\"true\" width=\"\" outline=\"false\" class=\"qc-button-wrapper\" style=\"background-color: var(--qc-color1);\"><a class=\"qc-button-container\" href=\"https:\/\/www.l-p.com\/store-27045-100g-qsfp28-sfp-dd.htm\" target=\"_blank\"><span style=\"color: rgb(191, 61, 55);\"><strong>\ud83d\udd0dSolicite ahora<\/strong><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Vea tambi\u00e9n<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/100g-optical-transceiver-form-factors-guide\/\">Factores de forma de los m\u00f3dulos transceptores \u00f3pticos de 100 G: CFP, CFP2, CFP4, CXP, QSFP28<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/100g-single-lambda-transceivers-benefits-upgrades-performance\/\">Lo que debe saber sobre las \u00f3pticas de 100 G Single Lambda<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/100g-single-lambda-vs-4-channel-optical-modules-comparison\/\">Comparaci\u00f3n entre m\u00f3dulos \u00f3pticos de 100 G de lambda \u00fanico y de 4 canales: diferencias clave<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/psm4-vs-cwdm4-which-optical-transceiver-for-your-network\/\">Transceptor PSM4 frente a CWDM4: explicaci\u00f3n de la diferencia clave<\/a><\/p>\n\n\n\n<script>const link1 = document.createElement('link');link1.rel = 'stylesheet';link1.type = 'text\/css';link1.href = 'https:\/\/statics.quickcreator.io\/static\/theme\/css\/qcb-theme-additional.css';const link2 = document.createElement('link');link2.rel = 'stylesheet';link2.type = 'text\/css';link2.href = 'https:\/\/statics.quickcreator.io\/static\/aaapycm22qmuab44\/theme\/css\/qcb-main-theme.css';document.head.appendChild(link1);document.head.appendChild(link2);<\/script>","protected":false},"excerpt":{"rendered":"<p>\u0395\u03c0\u03b9\u03bb\u03ad\u03be\u03c4\u03b5 \u03c4\u03bf\u03bd \u03ba\u03b1\u03bb\u03cd\u03c4\u03b5\u03c1\u03bf \u03bf\u03c0\u03c4\u03b9\u03ba\u03cc \u03bc\u03b5\u03c4\u03b1\u03b4\u03cc\u03c4\u03b7-\u03b1\u03c0\u03bf\u03b4\u03ad\u03ba\u03c4\u03b7 100G QSFP28 \u03b3\u03b9\u03b1 \u03c4\u03bf \u03b4\u03af\u03ba\u03c4\u03c5\u03cc \u03c3\u03b1\u03c2, \u03c3\u03c5\u03b3\u03ba\u03c1\u03af\u03bd\u03bf\u03bd\u03c4\u03b1\u03c2 \u03c3\u03c5\u03bc\u03b2\u03b1\u03c4\u03cc\u03c4\u03b7\u03c4\u03b1, \u03b1\u03c0\u03cc\u03c3\u03c4\u03b1\u03c3\u03b7, \u03c4\u03cd\u03c0\u03bf \u03bf\u03c0\u03c4\u03b9\u03ba\u03ae\u03c2 \u03af\u03bd\u03b1\u03c2 \u03ba\u03b1\u03b9 \u03b5\u03c0\u03b9\u03bb\u03bf\u03b3\u03ad\u03c2 \u03bc\u03b5\u03bb\u03bb\u03bf\u03bd\u03c4\u03b9\u03ba\u03ae\u03c2 \u03b5\u03be\u03ad\u03bb\u03b9\u03be\u03b7\u03c2.<\/p>","protected":false},"author":1,"featured_media":5415,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[13],"class_list":["post-5417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowledge-center","tag-100g-modules"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/comments?post=5417"}],"version-history":[{"count":4,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5417\/revisions"}],"predecessor-version":[{"id":11392,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5417\/revisions\/11392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/media\/5415"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/media?parent=5417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/categories?post=5417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/tags?post=5417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}