{"id":5407,"date":"2025-08-18T00:00:00","date_gmt":"2025-08-18T00:00:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/knowledge-center\/qsfp28-100g-psm4-transceivers-for-data-centers\/"},"modified":"2026-06-22T08:21:27","modified_gmt":"2026-06-22T08:21:27","slug":"qsfp28-100g-psm4-transceivers-for-data-centers","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/qsfp28-100g-psm4-transceivers-for-data-centers","title":{"rendered":"\u0391\u03c0\u03b5\u03bb\u03b5\u03c5\u03b8\u03b5\u03c1\u03ce\u03c3\u03c4\u03b5 \u03a5\u03c8\u03b7\u03bb\u03ae\u03c2 \u03a0\u03c5\u03ba\u03bd\u03cc\u03c4\u03b7\u03c4\u03b1\u03c2 \u03a3\u03c5\u03bd\u03b4\u03b5\u03c3\u03b9\u03bc\u03cc\u03c4\u03b7\u03c4\u03b1 100G: \u03a4\u03bf \u0395\u03b3\u03c7\u03b5\u03b9\u03c1\u03af\u03b4\u03b9\u03cc \u03c3\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03c4\u03bf \u039f\u03c0\u03c4\u03b9\u03ba\u03cc \u039c\u03cc\u03bd\u03c4\u03bf\u03c5\u03bb 100G PSM4"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e8c59990135f47488a1f089f23f62ace.webp\" alt=\"QSFP28 100G PSM4 Transceivers\" class=\"wp-image-5405\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e8c59990135f47488a1f089f23f62ace.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e8c59990135f47488a1f089f23f62ace-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e8c59990135f47488a1f089f23f62ace-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e8c59990135f47488a1f089f23f62ace-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/e8c59990135f47488a1f089f23f62ace-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><span class=\"qc-p1-tag\" style=\"color: rgb(64, 64, 64);\">La implacable expansi\u00f3n de la computaci\u00f3n en la nube, la inteligencia artificial y las aplicaciones hipercaladas exige interconexiones cada vez m\u00e1s r\u00e1pidas, densas y rentables entre centros de datos (DCI). Aqu\u00ed entra en juego el <\/span><span class=\"qc-p1-tag\"><strong>m\u00f3dulo \u00f3ptico 100G PSM4 (Paralelo de modo \u00fanico, 4 canales)<\/strong><\/span><span class=\"qc-p1-tag\" style=\"color: rgb(64, 64, 64);\"> \u2014un componente fundamental que impulsa enlaces eficientes de Ethernet de 100 Gigabits (100GbE). Esta gu\u00eda profundiza en lo que convierte al PSM4 en una soluci\u00f3n esencial para la infraestructura de red moderna.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udca1 Conocer la tecnolog\u00eda PSM4 ayuda a los ingenieros de redes a elegir la mejor opci\u00f3n para un rendimiento s\u00f3lido y en constante crecimiento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\ud83d\udcdd \u00bfQu\u00e9 es un m\u00f3dulo \u00f3ptico 100G PSM4?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un transceptor 100G PSM4 es un m\u00f3dulo \u00f3ptico enchufable dise\u00f1ado para Ethernet de 1<strong>00G<\/strong> transmisi\u00f3n sobre <strong>fibra monomodo est\u00e1ndar <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/what-is-single-mode-fiber-and-how-does-it-work\/\"><strong>(SMF)<\/strong><\/a>. Utiliza cuatro canales \u00f3pticos independientes, cada uno operando a 25 Gbps (mediante <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/understanding-non-return-to-zero-in-digital-communication\/\"><strong>, seg\u00fan la velocidad y la aplicaci\u00f3n<\/strong><\/a>) en los <strong>longitud de onda de 1310 nm<\/strong>. A diferencia de <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/100g-cwdm4-transceiver-efficient-2km-links\/\"><strong>100G<\/strong> <strong>transceptores CWDM4<\/strong><\/a>, que multiplexan longitudes de onda sobre un par de fibras, el PSM4 requiere <strong>ocho fibras<\/strong> (4 de transmisi\u00f3n, 4 de recepci\u00f3n): un par dedicado para cada canal. Este enfoque de \u201c\u00f3ptica paralela\u201d ofrece ventajas distintivas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\ud83d\udcdd Principales ventajas de la tecnolog\u00eda 100G PSM4<\/strong><\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Eficiencia de costos:<\/strong> \ud83d\udcb0 El PSM4 aprovecha componentes \u00f3pticos de menor costo en comparaci\u00f3n con soluciones de multiplexaci\u00f3n por longitud de onda como <strong>CWDM4<\/strong>. La \u00f3ptica m\u00e1s sencilla se traduce en un <strong>transceptor 100G de menor costo<\/strong>, especialmente significativo en despliegues a gran escala.<\/p><\/li>\n\n\n\n<li><p style=\"margin: 0px;\"><strong>Baja latencia:<\/strong> \u26a1 La ruta de transmisi\u00f3n paralela directa minimiza la complejidad del procesamiento de se\u00f1ales, lo que resulta en <strong>latencia ultra baja<\/strong> \u2014fundamental para operaciones burs\u00e1tiles de alta frecuencia, cl\u00fasteres de IA y aplicaciones financieras.<\/p><\/li>\n\n\n\n<li><p style=\"margin: 0px;\"><strong>Alta densidad y escalabilidad:<\/strong> \u2b50 Los m\u00f3dulos PSM4 suelen ser <strong>factor de forma QSFP28<\/strong>, lo que permite una alta densidad de puertos en switches y routers. Son ideales para <strong>Arquitecturas de hoja-rama<\/strong> \u03ba\u03b1\u03b9 <strong>conexiones de switch de top-of-rack (ToR)<\/strong> hasta <strong>de agregaci\u00f3n\/distribuci\u00f3n<\/strong> dentro de una sala de centro de datos.<\/p><\/li>\n\n\n\n<li><p style=\"margin: 0px;\"><strong>Rendimiento fiable en fibra monomodo (SMF):<\/strong> \ud83d\ude80 Al utilizar fibra monomodo probada, garantiza <strong>mayor alcance potencial<\/strong> (hasta 500 m, y a menudo hasta 2 km con m\u00f3dulos de calidad como los de LINK-PP) y <strong>un rendimiento superior<\/strong> en comparaci\u00f3n con soluciones en fibra multimodo (como SR4) a distancias similares.<\/p><\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\ud83d\udcdd Aplicaciones ideales para los m\u00f3dulos 100G PSM4<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>\u0394\u03b9\u03b1\u03c3\u03cd\u03bd\u03b4\u03b5\u03c3\u03b7 \u0394\u03b5\u03c1\u03bc\u03b5\u03bd\u03b5\u03af\u03c9\u03bd \u0394\u03b5\u03b4\u03bf\u03bc\u03ad\u03bd\u03c9\u03bd (DCI):<\/strong> Dentro de un \u00fanico edificio de centro de datos o campus (hasta 500 m\u20132 km).<\/p><\/li>\n\n\n\n<li><p style=\"margin: 0px;\"><strong>Computaci\u00f3n de alto rendimiento <\/strong><a href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/what-is-hpc-high-performance-computing\/\" target=\"_blank\" rel=\"\"><strong>(HPC)<\/strong><\/a><strong> Cl\u00fasteres:<\/strong> Donde la baja latencia y el alto ancho de banda son imprescindibles.<\/p><\/li>\n\n\n\n<li><p style=\"margin: 0px;\"><strong>N\u00facleo\/agregaci\u00f3n de red empresarial:<\/strong> Actualizaci\u00f3n de los enlaces troncales para aplicaciones intensivas en ancho de banda.<\/p><\/li>\n\n\n\n<li><p style=\"margin: 0px;\"><strong>Infraestructura del proveedor de nube:<\/strong> Conexi\u00f3n de servidores, almacenamiento y conmutadores en entornos de nube a gran escala.<\/p><\/li>\n\n\n\n<li><p style=\"margin: 0px;\"><strong>Redes financieras:<br><\/strong> Soporte para plataformas de negociaci\u00f3n de baja latencia.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\ud83d\udcdd PSM4 frente a CWDM4: Elecci\u00f3n de la soluci\u00f3n adecuada de 100G para fibra monomodo<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p><strong>Caracter\u00edstica<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>100G PSM4<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>m\u00f3dulos 100G CWDM4<\/strong><\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Tecnolog\u00eda<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u00d3ptica paralela (4 canales)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/wdm-optical-transceiver-module-applications\/\"><strong>WDM<\/strong><\/a> (4 longitudes de onda en 1 par)<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Cantidad de fibras<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p><strong>8 fibras<\/strong> (4 transmisiones, 4 recepciones)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p><strong>2 fibras<\/strong> (1 transmisor, 1 receptor)<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>\u0391\u03c0\u03cc\u03c3\u03c4\u03b1\u03c3\u03b7<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Hasta 500 m (com\u00fan), <strong>2 km o m\u00e1s<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Hasta 2 km<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>\u039a\u03cc\u03c3\u03c4\u03bf\u03c2<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p><strong>\u0393\u03b5\u03bd\u03b9\u03ba\u03ac \u03a7\u03b1\u03bc\u03b7\u03bb\u03cc\u03c4\u03b5\u03c1\u03bf<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Mayor<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Latencia<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p><strong>Ultra baja<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u03a7\u03b1\u03bc\u03b7\u03bb\u03cc<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Complejidad<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Menor (\u00f3ptica)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Mayor (se requiere multiplexor\/demultiplexor WDM)<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Ideal para<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Enlaces intra-DC de alta densidad y sensibles al costo, &lt; 2 km<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Enlaces donde la fibra es escasa, hasta 2 km<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\ud83d\udcdd \u00bfPor qu\u00e9 elegir los m\u00f3dulos \u00f3pticos LINK-PP 100G PSM4?<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"608\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/39cdcc49922c4d8ebdd258250cf678e9-1024x608.webp\" alt=\"LINK-PP 100G PSM4 Solutions\" class=\"wp-image-5406\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/39cdcc49922c4d8ebdd258250cf678e9-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/39cdcc49922c4d8ebdd258250cf678e9-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/39cdcc49922c4d8ebdd258250cf678e9-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/39cdcc49922c4d8ebdd258250cf678e9-18x12.webp 18w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/39cdcc49922c4d8ebdd258250cf678e9.webp 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando la fiabilidad, el rendimiento y el valor son primordiales, <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.link-pp.com\/\"><strong>LINK-PP<\/strong><\/a> destaca. Nuestros <strong>transceptores 100G PSM4 QSFP28<\/strong> est\u00e1n dise\u00f1ados para la excelencia:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Compatibilidad garantizada:<\/strong> Rigurosamente probados para funcionar sin interrupciones con conmutadores OEM principales (Cisco, Juniper, Arista, etc.). Evite los riesgos de los m\u00f3dulos gen\u00e9ricos.<\/p><\/li>\n\n\n\n<li><p style=\"margin: 0px;\"><strong>Calidad y fiabilidad superiores:<\/strong> Fabricados seg\u00fan los est\u00e1ndares m\u00e1s exigentes, lo que garantiza una baja <strong>tasas de error de bit <\/strong><a href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/understanding-what-is-bit-error-rate\/\" target=\"_self\"><strong>\u03c3\u03b5 \u03b1\u03c0\u03b1\u03b9\u03c4\u03b7\u03c4\u03b9\u03ba\u03ad\u03c2 \u03c3\u03c5\u03bd\u03b4\u03ad\u03c3\u03b5\u03b9\u03c2 PAM4. \u0397 \u03b5\u03c0\u03b9\u03bb\u03bf\u03b3\u03ae<\/strong><\/a> y larga vida \u00fatil operativa \u2014ideal para <strong>enlaces cr\u00edticos de centros de datos<\/strong>.<\/p><\/li>\n\n\n\n<li><p style=\"margin: 0px;\"><strong>Alcance extendido:<\/strong> \u039c\u03b1\u03c2 <strong>LINK-PP <\/strong><a href=\"https:\/\/www.l-p.com\/products\/488422.htm\" target=\"_blank\" rel=\"\"><strong>LQ-M31100-FR4C<\/strong><\/a> modelo logra de forma fiable <strong>hasta 2 km<\/strong> sobre fibra monomodo, ofreciendo mayor flexibilidad de implementaci\u00f3n.<\/p><\/li>\n\n\n\n<li><p style=\"margin: 0px;\"><strong>Ahorros de costos:<\/strong> Experimente una reducci\u00f3n significativa <strong>de la inversi\u00f3n de capital (CAPEX)<\/strong> sin comprometer el rendimiento ni la estabilidad.<\/p><\/li>\n\n\n\n<li><p style=\"margin: 0px;\"><strong>Garant\u00eda y soporte integral:<\/strong> Apoyado por soporte y garant\u00eda l\u00edderes en la industria.<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a1Desbloquee su potencial 100G con LINK-PP!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Optimice su infraestructura de centro de datos con soluciones de alto rendimiento y rentables <strong>de conectividad 100G<\/strong>. Ya sea que est\u00e9 desplegando nueva infraestructura o actualizando enlaces existentes, <strong>los transceptores 100G PSM4 de LINK-PP<\/strong> brindan la base fiable y de baja latencia que necesita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfListo para explorar los m\u00f3dulos LINK-PP 100G PSM4?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u27a1\ufe0f <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/488422.htm\"><strong>LQ-M31100-FR4C (2 km)<\/strong><\/a><br>\u27a1\ufe0f <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/488423.htm\"><strong>LQ-M31100-LR4C (10 km)<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\ud83d\udcdd FAQ<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 significa PSM4?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">PSM4 significa \u201cModo \u00danico Paralelo de 4 canales\u201d. El transceptor utiliza cuatro fibras para enviar datos y otras cuatro fibras para recibirlos. Cada canal transmite 25 Gbps.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfPueden los transceptores QSFP28 100G PSM4 funcionar con fibra monomodo existente?<\/h3>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">S\u00ed, los transceptores QSFP28 100G PSM4 funcionan con fibra monomodo est\u00e1ndar (OS2). Muchos centros de datos ya utilizan este tipo de fibra, lo que facilita las actualizaciones y reduce costos.<\/p>\n<\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfC\u00f3mo se supervisa el estado de salud de un transceptor PSM4?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los administradores de red utilizan la supervisi\u00f3n digital de diagn\u00f3stico, denominada DDM. El DDM muestra elementos como la temperatura, el voltaje y la intensidad de la se\u00f1al. Esto les ayuda a detectar y resolver problemas tempranamente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 conector utiliza el transceptor QSFP28 100G PSM4?<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>El transceptor utiliza un conector MPO\/MTP-12.<\/p><\/li>\n\n\n\n<li><p>Este conector aloja doce fibras en una sola fila.<\/p><\/li>\n\n\n\n<li><p>Ocho fibras transmiten datos y cuatro no se utilizan.<\/p><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfEs el transceptor QSFP28 100G PSM4 extra\u00edble en caliente?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed, puede insertar o retirar el transceptor sin apagar el dispositivo. Esto permite que la red siga funcionando durante actualizaciones o reparaciones.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>V\u00e9ase tambi\u00e9n<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/100g-qsfp28-optical-transceivers-selection-guide\/\">Explore los transceptores \u00f3pticos 100G QSFP28: SR4, LR4, CWDM4, PSM4 y m\u00e1s<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/psm4-vs-cwdm4-which-optical-transceiver-for-your-network\/\">PSM4 frente a CWDM4: \u00bfcu\u00e1les son las diferencias?<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/100g-single-lambda-vs-4-channel-optical-modules-comparison\/\">Diferencias clave entre m\u00f3dulos \u00f3pticos de 100G de longitud de onda \u00fanica y de 4 longitudes de onda<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/100g-optical-transceiver-form-factors-guide\/\">Factores de forma de los transceptores \u00f3pticos 100G: \u00bfQSFP28, CFP, CFP2, CFP4?<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>\u039f\u03b9 \u03bc\u03b5\u03c4\u03b1\u03b4\u03cc\u03c4\u03b5\u03c2-\u03b1\u03c0\u03bf\u03b4\u03ad\u03ba\u03c4\u03b5\u03c2 QSFP28 100G PSM4 \u03c0\u03c1\u03bf\u03c3\u03c6\u03ad\u03c1\u03bf\u03c5\u03bd \u03c5\u03c8\u03b7\u03bb\u03ae\u03c2 \u03c4\u03b1\u03c7\u03cd\u03c4\u03b7\u03c4\u03b1\u03c2, \u03ba\u03bf\u03c3\u03c4\u03bf\u03b1\u03c0\u03bf\u03c4\u03b5\u03bb\u03b5\u03c3\u03bc\u03b1\u03c4\u03b9\u03ba\u03cc Ethernet 100G \u03c3\u03b5 \u03bc\u03bf\u03bd\u03cc\u03c4\u03c1\u03bf\u03c0\u03b7 \u03af\u03bd\u03b1, \u03b9\u03b4\u03b1\u03bd\u03b9\u03ba\u03cc \u03b3\u03b9\u03b1 \u03ba\u03ad\u03bd\u03c4\u03c1\u03b1 \u03b4\u03b5\u03b4\u03bf\u03bc\u03ad\u03bd\u03c9\u03bd \u03ba\u03b1\u03b9 \u03b5\u03c0\u03b9\u03c7\u03b5\u03b9\u03c1\u03b7\u03c3\u03b9\u03b1\u03ba\u03ac \u03b4\u03af\u03ba\u03c4\u03c5\u03b1.<\/p>","protected":false},"author":1,"featured_media":5405,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[13],"class_list":["post-5407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowledge-center","tag-100g-modules"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/comments?post=5407"}],"version-history":[{"count":4,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5407\/revisions"}],"predecessor-version":[{"id":11245,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5407\/revisions\/11245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/media\/5405"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/media?parent=5407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/categories?post=5407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/tags?post=5407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}