{"id":5323,"date":"2025-08-27T00:00:00","date_gmt":"2025-08-27T00:00:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/knowledge-center\/sfp28-25g-esr-vs-sfp28-25g-sr-key-differences\/"},"modified":"2026-06-22T08:06:06","modified_gmt":"2026-06-22T08:06:06","slug":"sfp28-25g-esr-vs-sfp28-25g-sr-key-differences","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/sfp28-25g-esr-vs-sfp28-25g-sr-key-differences","title":{"rendered":"SFP28 25G SR \u03ad\u03bd\u03b1\u03bd\u03c4\u03b9 ESR: \u03a4\u03bf \u03bf\u03c1\u03b9\u03c3\u03c4\u03b9\u03ba\u03cc \u03c3\u03b1\u03c2 \u03b5\u03b3\u03c7\u03b5\u03b9\u03c1\u03af\u03b4\u03b9\u03bf \u03b3\u03b9\u03b1 \u03c4\u03b7\u03bd \u03b5\u03c0\u03b9\u03bb\u03bf\u03b3\u03ae \u03c4\u03bf\u03c5 \u03ba\u03b1\u03c4\u03ac\u03bb\u03bb\u03b7\u03bb\u03bf\u03c5 \u03bc\u03b5\u03c4\u03b1\u03b4\u03cc\u03c4\u03b7-\u03b4\u03ad\u03ba\u03c4\u03b7 25G"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/08c2502efd6f4a5392fdecca6e858dec.webp\" alt=\"SFP28-25G-ESR vs SFP28-25G-SR Key Differences and Best Use Cases\" class=\"wp-image-5321\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/08c2502efd6f4a5392fdecca6e858dec.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/08c2502efd6f4a5392fdecca6e858dec-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/08c2502efd6f4a5392fdecca6e858dec-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/08c2502efd6f4a5392fdecca6e858dec-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/08c2502efd6f4a5392fdecca6e858dec-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En el mundo de alta velocidad de las redes modernas, el 25GbE se ha convertido en el punto \u00f3ptimo para conmutaci\u00f3n en la parte superior del bastidor, interconexiones de centros de datos y enlaces troncales empresariales. Al implementar esta tecnolog\u00eda, dos de los tipos de transceptores m\u00e1s comunes que encontrar\u00e1 son los <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/473141.htm\"><strong>SFP28-25G-SR<\/strong><\/a> y el <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/476088.htm\"><strong>SFP28-25G-ESR<\/strong><\/a>. Aunque podr\u00edan parecer similares a simple vista, comprender sus diferencias es fundamental para optimizar el rendimiento y la eficiencia de costos de su red.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta gu\u00eda ofrecer\u00e1 una comparaci\u00f3n profesional para disipar cualquier confusi\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 Comprensi\u00f3n de los conceptos b\u00e1sicos: SR frente a ESR<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ambos m\u00f3dulos est\u00e1n dise\u00f1ados para comunicaciones de corto alcance sobre <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/om1-om2-om3-om4-om5-multimode-fiber-guide\/\"><strong>\u039c\u03bf\u03c1\u03c6\u03ae \u03c6\u03b9\u03bb\u03bc \u03c6\u03cc\u03c1\u03bc\u03b1 (MMF)<\/strong><\/a>, utilizando una longitud de onda de 850 nm. La distinci\u00f3n principal radica en su alcance y en la tecnolog\u00eda subyacente que lo posibilita.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>SFP28-25G-SR (Alcance corto):<\/strong> Este es el est\u00e1ndar habitual para conexiones de corta distancia. Est\u00e1 dise\u00f1ado para alcanzar hasta 100 metros en fibra OM4.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>SFP28-25G-ESR (Alcance corto extendido):<\/strong> Como su nombre indica, este m\u00f3dulo ampl\u00eda a\u00fan m\u00e1s los l\u00edmites. Aprovecha \u00f3pticas m\u00e1s sofisticadas para lograr un <strong>alcance extendido<\/strong> de hasta 400 metros en fibra OM4.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 Comparaci\u00f3n directa: Diferencias clave<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Profundicemos en los detalles t\u00e9cnicos. La siguiente tabla describe las diferencias cr\u00edticas entre estos dos <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-26225-25g-sfp28.htm\"><strong>Transceptores SFP28 de 25 G<\/strong><\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p><strong>Caracter\u00edstica<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>SFP28-25G-SR<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>SFP28-25G-ESR<\/strong><\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Nombre completo<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Alcance corto<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Alcance corto extendido<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Alcance est\u00e1ndar<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Hasta 70 m en OM3 \/ 100 m en OM4<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Hasta 300 m en OM3 \/ 400 m en OM4<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Tipo de fibra<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Fibra multimodo (OM3, OM4)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Fibra multimodo (OM3, OM4)<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Longitud de onda<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>850nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>850nm<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Consumo m\u00e1ximo de potencia<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Normalmente &lt; 1,0 W<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Ligeramente mayor, ~1,2 W<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Aplicaci\u00f3n<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Enlaces cortos dentro de un bastidor o entre bastidores adyacentes<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Enlaces intra-centro de datos m\u00e1s largos, troncales universitarias<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>\u039a\u03cc\u03c3\u03c4\u03bf\u03c2<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u2705 M\u00e1s bajo (est\u00e1ndar de la industria)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u26a1 M\u00e1s alto (rendimiento extendido)<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 Selecci\u00f3n del m\u00f3dulo adecuado para su aplicaci\u00f3n<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Su elecci\u00f3n no se basa \u00fanicamente en la distancia, sino tambi\u00e9n en el caso de uso.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px 0px 4px;\"><strong>Elija el SFP28-25G-SR si:<\/strong><\/p><ul><li><p style=\"margin: 0px;\">Est\u00e1 conectando servidores a un <strong>conmutador de la parte superior del bastidor (ToR)<\/strong> dentro del mismo bastidor.<\/p><\/li><li><p style=\"margin: 0px;\">Sus distancias de enlace est\u00e1n claramente por debajo de los 100 metros.<\/p><\/li><li><p style=\"margin: 0px;\">Su prioridad es lograr el menor costo posible por puerto para aplicaciones est\u00e1ndar de corto alcance.<\/p><\/li><\/ul><\/li><li><p style=\"margin: 0px 0px 4px;\"><strong>Elija el SFP28-25G-ESR si:<\/strong><\/p><ul><li><p style=\"margin: 0px;\">Necesita cubrir distancias mayores dentro de un <strong>sal\u00f3n de centro de datos<\/strong> o entre edificios de una <strong>red universitaria<\/strong> sin necesidad de actualizar a fibra monomodo.<\/p><\/li><li><p style=\"margin: 0px;\">Sus enlaces oscilan entre 100 m y 400 m.<\/p><\/li><li><p style=\"margin: 0px;\">Valora la flexibilidad para cubrir recorridos m\u00e1s largos y evitar el costo de instalar nueva infraestructura de fibra monomodo.<\/p><\/li><\/ul><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Para quienes buscan <strong>\u00f3pticas de alta calidad y compatibles<\/strong> que cumplan con sus especificaciones, los <strong>LINK-PP <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/473141.htm\"><strong>LS-MM8525-S1C<\/strong><\/a> \u03ba\u03b1\u03b9 <strong>LINK-PP <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/476088.htm\"><strong>LS-MM8525-S3C<\/strong><\/a> m\u00f3dulos est\u00e1n dise\u00f1ados para ofrecer un rendimiento y una fiabilidad m\u00e1ximos. Se someten a pruebas rigurosas de <strong>compatibilidad<\/strong> con conmutadores OEM principales de Cisco, Arista, Juniper y otros, garantizando una integraci\u00f3n perfecta en su infraestructura de red existente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 Conclusi\u00f3n y pr\u00f3ximos pasos<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No existe un \u201cm\u00f3dulo mejor\u201d: solo el m\u00f3dulo adecuado para sus necesidades espec\u00edficas. El <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/473141.htm\"><strong>SFP28-25G-SR<\/strong><\/a> ofrece una soluci\u00f3n rentable para la mayor\u00eda de las aplicaciones de corto alcance, mientras que el <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/476088.htm\"><strong>SFP28-25G-ESR<\/strong><\/a> proporciona el alcance adicional esencial para dise\u00f1os de red m\u00e1s exigentes.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/941a57c76dd5479e8df3313a500e574c.webp\" alt=\"SFP28 Module\" class=\"wp-image-5322\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/941a57c76dd5479e8df3313a500e574c.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/941a57c76dd5479e8df3313a500e574c-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/941a57c76dd5479e8df3313a500e574c-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/941a57c76dd5479e8df3313a500e574c-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/941a57c76dd5479e8df3313a500e574c-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfTodav\u00eda no est\u00e1 seguro de qu\u00e9 transceptor de 25 G es el ideal para su topolog\u00eda de red?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestros expertos en <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/page\/aboutus.htm\"><strong>LINK-PP<\/strong><\/a> est\u00e1n aqu\u00ed para ayudarlo. Ofrecemos <strong>consultas gratuitas<\/strong> \u03ba\u03b1\u03b9 <strong>garant\u00edas de por vida<\/strong> en todos nuestros transceptores \u00f3pticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u27a1\ufe0f <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-26225-25g-sfp28.htm\"><strong>\u00a1Explore nuestro cat\u00e1logo completo de m\u00f3dulos SFP28 y solicite una cotizaci\u00f3n hoy mismo!<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 Preguntas frecuentes (FAQ)<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P1: \u00bfPuedo usar un m\u00f3dulo ESR para un enlace muy corto (por ejemplo, 10 metros)?<\/strong><br\/><strong>A:<\/strong> S\u00ed, t\u00e9cnicamente puede hacerlo. Los m\u00f3dulos SFP28-25G-ESR son compatibles hacia atr\u00e1s con distancias m\u00e1s cortas. Sin embargo, no es rentable. Estar\u00eda gastando m\u00e1s en el m\u00f3dulo ESR sin aprovechar su caracter\u00edstica principal (alcance extendido). La variante SR es la opci\u00f3n \u00f3ptima y econ\u00f3mica para enlaces cortos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P2: \u00bfSon compatibles estos m\u00f3dulos con mi conmutador Cisco\/Juniper\/Arista existente?<\/strong><br\/><strong>A:<\/strong> La mayor\u00eda de los m\u00f3dulos de terceros, incluidos los de <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.link-pp.com\/\"><strong>LINK-PP<\/strong><\/a>, est\u00e1n dise\u00f1ados para ser <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/multi-source-agreements-optical-transceivers\/\"><strong>Acuerdo Multifabricante (MSA)<\/strong><\/a> compatibles. Esto garantiza una amplia interoperabilidad. No obstante, siempre es fundamental elegir un proveedor reputado que realice pruebas rigurosas de <strong>compatibilidad<\/strong> para evitar cualquier problema. Todos los transceptores LINK-PP est\u00e1n preprogramados y probados para garantizar compatibilidad total con marcas importantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P3: \u00bfPuedo usar fibra OM5 con estos transceptores?<\/strong><br\/><strong>A:<\/strong> \u00a1S\u00ed! Tanto los m\u00f3dulos SR como ESR son totalmente compatibles con fibra OM5. OM5 est\u00e1 dise\u00f1ada para ser compatible hacia atr\u00e1s con OM4. Puede esperar el mismo rendimiento de alcance en OM5 que en OM4 (100 m para SR, 400 m para ESR). La principal ventaja de OM5 radica en aplicaciones de espectro m\u00e1s amplio como <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/100g-swdm4-transceiver-explained-network-professionals-guide\/\"><strong>SWDM<\/strong><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P4: \u00bfCu\u00e1l es la diferencia entre ESR y LR? \u00bfPor qu\u00e9 no usar siempre LR para distancias largas?<\/strong><br\/><strong>A:<\/strong> <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/476046.htm\"><strong>SFP28-25G-LR<\/strong><\/a> (Alcance largo) utiliza un <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/what-is-single-mode-fiber-and-how-does-it-work\/\"><strong>\u03bf\u03bc\u03bf\u03bc\u03bf\u03c1\u03c6\u03b9\u03ba\u03ae \u03c6\u03b9\u03bb\u03bc \u03c6\u03cc\u03c1\u03bc\u03b1 (SMF)<\/strong><\/a> y un l\u00e1ser de 1310 nm para alcanzar distancias de hasta 10 km. La diferencia clave es el tipo de fibra. ESR le permite aprovechar su infraestructura existente de fibra multimodo para distancias de hasta 400 m. Pasar a LR requiere un sistema de cableado de fibra monomodo m\u00e1s costoso, con un costo inicial de instalaci\u00f3n mayor. ESR constituye una soluci\u00f3n perfecta de ahorro de costos para distancias intermedias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P5: \u00bfLos m\u00f3dulos ESR generan m\u00e1s calor o consumen m\u00e1s energ\u00eda?<\/strong><br\/><strong>A:<\/strong> En general, s\u00ed. La capacidad de alcance extendido del m\u00f3dulo ESR requiere una mayor potencia de salida del l\u00e1ser, lo que normalmente da como resultado un consumo ligeramente mayor de energ\u00eda (y, por ende, una mayor disipaci\u00f3n de calor) en comparaci\u00f3n con la variante SR. Sin embargo, la diferencia suele ser marginal (por ejemplo, 1,0 W frente a 1,2 W) y est\u00e1 bien dentro de los l\u00edmites de dise\u00f1o t\u00e9rmico de los switches modernos.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u03a3\u03c5\u03b3\u03ba\u03c1\u03af\u03bd\u03b5\u03c4\u03b5 \u03c4\u03b1 \u03c0\u03c1\u03cc\u03c4\u03c5\u03c0\u03b1 sfp28-25g-esr \u03ba\u03b1\u03b9 sfp28-25g-sr \u03b3\u03b9\u03b1 \u03b4\u03af\u03ba\u03c4\u03c5\u03b1 25G. \u0394\u03b5\u03af\u03c4\u03b5 \u03c4\u03b9\u03c2 \u03b2\u03b1\u03c3\u03b9\u03ba\u03ad\u03c2 \u03b4\u03b9\u03b1\u03c6\u03bf\u03c1\u03ad\u03c2 \u03cc\u03c3\u03bf\u03bd \u03b1\u03c6\u03bf\u03c1\u03ac \u03c4\u03b7\u03bd \u03b1\u03c0\u03cc\u03c3\u03c4\u03b1\u03c3\u03b7, \u03c4\u03bf\u03bd \u03c4\u03cd\u03c0\u03bf \u03bf\u03c0\u03c4\u03b9\u03ba\u03ae\u03c2 \u03af\u03bd\u03b1\u03c2 \u03ba\u03b1\u03b9 \u03c4\u03b9\u03c2 \u03ba\u03b1\u03bb\u03cd\u03c4\u03b5\u03c1\u03b5\u03c2 \u03c0\u03b5\u03c1\u03b9\u03c0\u03c4\u03ce\u03c3\u03b5\u03b9\u03c2 \u03c7\u03c1\u03ae\u03c3\u03b7\u03c2 \u03c3\u03b5 \u03ba\u03ad\u03bd\u03c4\u03c1\u03b1 \u03b4\u03b5\u03b4\u03bf\u03bc\u03ad\u03bd\u03c9\u03bd.<\/p>","protected":false},"author":1,"featured_media":5321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[26],"class_list":["post-5323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowledge-center","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/comments?post=5323"}],"version-history":[{"count":4,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5323\/revisions"}],"predecessor-version":[{"id":11217,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5323\/revisions\/11217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/media\/5321"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/media?parent=5323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/categories?post=5323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/tags?post=5323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}