{"id":5197,"date":"2025-09-05T00:00:00","date_gmt":"2025-09-05T00:00:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/knowledge-center\/applications-of-100m-optical-module-in-modern-networks\/"},"modified":"2026-06-22T07:42:33","modified_gmt":"2026-06-22T07:42:33","slug":"applications-of-100m-optical-module-in-modern-networks","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/applications-of-100m-optical-module-in-modern-networks","title":{"rendered":"Aplicaciones del m\u00f3dulo \u00f3ptico de 100 M."},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ced69f2990e346e6bdfd840946606d43.webp\" alt=\"The applications of 100M Optical Module\" class=\"wp-image-5195\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ced69f2990e346e6bdfd840946606d43.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ced69f2990e346e6bdfd840946606d43-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ced69f2990e346e6bdfd840946606d43-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ced69f2990e346e6bdfd840946606d43-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/ced69f2990e346e6bdfd840946606d43-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En una era dominada por discusiones sobre redes de m\u00faltiples gigabits y terabits, es f\u00e1cil pasar por alto la tecnolog\u00eda que constituye la columna vertebral de muchos sistemas robustos y especializados: el <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25833-100m-sfp.htm\"><strong>m\u00f3dulo \u00f3ptico de 100 M<\/strong><\/a>. Tambi\u00e9n conocido como <strong>SFP de Fast Ethernet<\/strong> \u03ae <strong>100BASE<br> <\/strong>m\u00f3dulos, estos transceptores est\u00e1n lejos de estar obsoletos. Ofrecen una combinaci\u00f3n perfecta de fiabilidad, extensi\u00f3n de distancia y aislamiento el\u00e9ctrico para entornos en los que la velocidad bruta no es la principal preocupaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este art\u00edculo explora las aplicaciones duraderas de los m\u00f3dulos \u00f3pticos de fibra de 100 M y ofrece una gu\u00eda integral para seleccionar el modelo adecuado seg\u00fan sus necesidades.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 \u00bfPor qu\u00e9 elegir m\u00f3dulos \u00f3pticos de fibra de 100 M? Principales ventajas<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfPor qu\u00e9 elegir\u00eda alguien 100 M en un mundo de 10 G? La respuesta radica en sus ventajas espec\u00edficas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Inmunidad al ruido:<\/strong> Las fibras \u00f3pticas son inmunes a <strong>Interferencia electromagn\u00e9tica <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/what-is-electromagnetic-interference\/\"><strong>(EMI)<\/strong><\/a> \u03ba\u03b1\u03b9 <strong>interferencias de radiofrecuencia <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/rfi-radio-frequency-interference-causes-effects-solutions\/\"><strong>(RFI)<\/strong><\/a>, lo que las hace ideales para entornos industriales severos.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Transmisi\u00f3n a larga distancia:<\/strong> Cubren f\u00e1cilmente distancias de 2 km a m\u00e1s de 120 km, superando con creces el l\u00edmite de 100 metros de los cables Ethernet tradicionales de cobre.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Limitado a aproximadamente 4.3 billones de direcciones.<\/strong> Es extremadamente dif\u00edcil intervenir un cable de fibra \u00f3ptica sin ser detectado, lo que proporciona un enlace de datos m\u00e1s seguro.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Integraci\u00f3n con sistemas heredados:<\/strong> Son ideales para modernizar sistemas de control industrial (ICS) antiguos y <strong>sistemas SCADA<\/strong> que operan a velocidades de Fast Ethernet, sin requerir una renovaci\u00f3n completa de la infraestructura.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 Aplicaciones principales de los transceptores \u00f3pticos de 100 M<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Estos m\u00f3dulos no est\u00e1n destinados a transmitir video en 4K, sino a operaciones cr\u00edticas donde la estabilidad es primordial. Las \u00e1reas clave de aplicaci\u00f3n incluyen:<\/p>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p style=\"margin: 0px;\"><strong>Redes industriales y automatizaci\u00f3n:<\/strong> Las plantas de fabricaci\u00f3n est\u00e1n llenas de maquinaria que genera una interferencia electromagn\u00e9tica (EMI) significativa. <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25833-100m-sfp.htm\"><strong>Los m\u00f3dulos SFP de 100 M<\/strong><\/a> se utilizan para conectar de forma fiable PLC, sensores y sistemas de control en toda una planta de fabricaci\u00f3n.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Capas perif\u00e9rica y de acceso de redes empresariales:<\/strong> Se usan en conductos verticales antiguos de edificios o para conectar interruptores remotos de acceso donde las demandas de ancho de banda son bajas, pero la distancia es un factor determinante.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Sistemas de vigilancia y seguridad:<\/strong> Ideales para conectar c\u00e1maras IP, especialmente a largas distancias dentro de un campus, hacia un grabador de video en red (NVR) central.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Gesti\u00f3n de servicios p\u00fablicos y energ\u00eda:<\/strong> Ampliamente desplegados en <strong>redes inteligentes<\/strong> para automatizaci\u00f3n y monitoreo de subestaciones, donde el equipo suele comunicarse mediante Fast Ethernet.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Enlaces punto a punto:<\/strong> Una soluci\u00f3n sencilla y rentable para conectar dos edificios o ubicaciones mediante un enlace dedicado de fibra.<\/p><\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 C\u00f3mo elegir el m\u00f3dulo SFP de 100 M adecuado: Gu\u00eda de selecci\u00f3n LINK-PP<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/646162cabe5348f6bd3633420f57d63e.webp\" alt=\"OPTICAL TRANSCEIVER\" class=\"wp-image-5196\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/646162cabe5348f6bd3633420f57d63e.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/646162cabe5348f6bd3633420f57d63e-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/646162cabe5348f6bd3633420f57d63e-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/646162cabe5348f6bd3633420f57d63e-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/646162cabe5348f6bd3633420f57d63e-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La selecci\u00f3n del m\u00f3dulo correcto depende del tipo de fibra, la distancia requerida y la longitud de onda. Como fabricante l\u00edder en el \u00e1mbito de la fibra \u00f3ptica, <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.link-pp.com\/\"><strong>LINK-PP<\/strong><\/a> ofrece una amplia gama de transceptores \u00f3pticos de 100 M <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25833-100m-sfp.htm\"><strong>de alta calidad y compatibles.<\/strong><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n se presenta una tabla de referencia r\u00e1pida para ayudarle a elegir el <strong>m\u00f3dulo SFP de 100 M LINK-PP<\/strong> adecuado para su aplicaci\u00f3n:<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p>N\u00famero de modelo LINK-PP<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Interfaz<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Longitud de onda<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Tipo de fibra<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Distancia m\u00e1xima<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Soporte DOM<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>LS-MM3101-02C<br><\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>LC \u03a0\u03bf\u03bb\u03c5\u03bc\u03b5\u03c1\u03ae\u03c2<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>1310 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>FMM (62,5\/125 \u00b5m)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>2km<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u039d\u03b1\u03b9<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/478922.htm\"><strong>LS-SM3101-20C<br><\/strong><\/a><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>LC \u03a0\u03bf\u03bb\u03c5\u03bc\u03b5\u03c1\u03ae\u03c2<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>1310 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>FUM (9\/125 \u00b5m)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>20 km<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u039d\u03b1\u03b9<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/478519.htm\"><strong>LS-BL315501-10C<\/strong><\/a><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>LC sencillo<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Tx: 1310 nm \/ Rx: 1550 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>FUM (9\/125 \u00b5m)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>10km<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u039d\u03b1\u03b9<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/478164.htm\"><strong>LS-BL553101-10C<br><\/strong><\/a><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>LC sencillo<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Tx: 1550 nm \/ Rx: 1310 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>FUM (9\/125 \u00b5m)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>10km<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u039d\u03b1\u03b9<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/478907.htm\"><strong>LS-SM3101-10C<br><\/strong><\/a><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>LC \u03a0\u03bf\u03bb\u03c5\u03bc\u03b5\u03c1\u03ae\u03c2<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>1310 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>FUM (9\/125 \u00b5m)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>10km<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u039d\u03b1\u03b9<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/475948.htm\"><strong>LS-SM3101-40C<\/strong><\/a><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>LC \u03a0\u03bf\u03bb\u03c5\u03bc\u03b5\u03c1\u03ae\u03c2<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>1310 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>FUM (9\/125 \u00b5m)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>40 km<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u039d\u03b1\u03b9<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/476884.htm\"><strong>LS-SM5501-80C<\/strong><\/a><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>LC \u03a0\u03bf\u03bb\u03c5\u03bc\u03b5\u03c1\u03ae\u03c2<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>1550 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>FUM (9\/125 \u00b5m)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>80 km<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u039d\u03b1\u03b9<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\ud83d\udd0d <\/em><strong><em>Clave:<\/em><\/strong><em> <\/em><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/om1-om2-om3-om4-om5-multimode-fiber-guide\/\"><em>FMM (Fibra multimodo)<\/em><\/a><em>, <\/em><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/what-is-single-mode-fiber-and-how-does-it-work\/\"><em>FUM (Fibra monomodo)<\/em><\/a><em>, <\/em><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/ddm-dom-in-optical-transceivers\/\"><em>DOM (Monitoreo \u00f3ptico digital)<\/em><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Consejo profesional:<\/strong> Para conexiones bidireccionales sobre un \u00fanico hilo de fibra, los <strong>modelos LINK-PP LS-BL315501-10C<\/strong> \u03ba\u03b1\u03b9 <strong>LS-BL553101-10C<br><\/strong> son una excelente opci\u00f3n, duplicando efectivamente su capacidad de fibra.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 Conclusi\u00f3n: Un rendidor especializado, pero vital<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u03a4\u03bf \/ \u0397 \/ \u039f <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25833-100m-sfp.htm\"><strong>m\u00f3dulo \u00f3ptico de 100 M<\/strong><\/a> ejemplifica que, en redes, la tecnolog\u00eda \u201cmejor\u201d es aquella que resuelve de forma m\u00e1s eficaz el problema concreto. Para conectividad a larga distancia, libre de ruidos y segura en entornos industriales, empresariales y de servicios p\u00fablicos, estos m\u00f3dulos siguen siendo una soluci\u00f3n indispensable y \u00f3ptima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al elegir un proveedor de confianza como <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.link-pp.com\/\"><strong>LINK-PP<\/strong><\/a>, garantiza que su infraestructura cr\u00edtica cuente con componentes robustos y fiables.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 \u03a3\u03c5\u03c7\u03bd\u03ad\u03c2 \u0395\u03c1\u03c9\u03c4\u03ae\u03c3\u03b5\u03b9\u03c2<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >\u00bfCon qu\u00e9 dispositivos puede usar un m\u00f3dulo \u00f3ptico de 100 M?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Puede usar m\u00f3dulos \u00f3pticos de 100 M con muchos dispositivos de red. Estos dispositivos incluyen switches, routers, servidores y convertidores de medios. Siempre consulte el manual de su dispositivo para verificar si el m\u00f3dulo es compatible.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >\u00bfC\u00f3mo instala un m\u00f3dulo \u00f3ptico de 100 M?<\/h3>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Inserte el m\u00f3dulo en el puerto adecuado de su dispositivo. Emp\u00fajelo hasta escuchar un clic. A continuaci\u00f3n, conecte el cable de fibra. No es necesario apagar su dispositivo. Su dise\u00f1o hot-swappable facilita esta tarea.<\/p><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\" >\u00bfPuede usar un m\u00f3dulo \u00f3ptico de 100 M al aire libre?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Puede usar estos m\u00f3dulos al aire libre siempre que los proteja del agua y el polvo. Use cajas resistentes a la intemperie para obtener los mejores resultados. Algunos m\u00f3dulos funcionan mejor en entornos exigentes. Consulte siempre los detalles del producto antes de su instalaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >\u00bfQu\u00e9 tipo de fibra funciona con un m\u00f3dulo \u00f3ptico de 100 M?<\/h3>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p>Tipo de m\u00f3dulo<br><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Tipo de fibra<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Distancia m\u00e1xima<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p>Multimodo de 100 M<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Fibra multimodo<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>100 metros<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p>Monomodo de 100 M<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Fibra monomodo<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Hasta 80 km<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Debe usar la fibra adecuada con su m\u00f3dulo para obtener los mejores resultados.<\/p>","protected":false},"excerpt":{"rendered":"<p>El m\u00f3dulo \u00f3ptico de 100 M permite conexiones r\u00e1pidas y fiables para oficinas, f\u00e1bricas, sistemas de seguridad y redes de telecomunicaciones, apoyando una transferencia eficiente de datos a corta distancia.<\/p>","protected":false},"author":1,"featured_media":5195,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[26],"class_list":["post-5197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowledge-center","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/comments?post=5197"}],"version-history":[{"count":4,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5197\/revisions"}],"predecessor-version":[{"id":11176,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5197\/revisions\/11176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/media\/5195"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/media?parent=5197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/categories?post=5197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/tags?post=5197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}