{"id":5008,"date":"2025-09-18T11:12:00","date_gmt":"2025-09-18T11:12:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/knowledge-center\/onu-vs-ont-understanding-the-main-distinctions-guide\/"},"modified":"2026-06-22T07:00:47","modified_gmt":"2026-06-22T07:00:47","slug":"onu-vs-ont-understanding-the-main-distinctions-guide","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/onu-vs-ont-understanding-the-main-distinctions-guide","title":{"rendered":"ONU frente a ONT: descifrar las diferencias clave en su red de fibra"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1312\" height=\"736\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/08e240cab6a445a3be8e091f44f1f6b6.webp\" alt=\"ONU vs ONT Understanding the Main Distinctions\" class=\"wp-image-5005\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/08e240cab6a445a3be8e091f44f1f6b6.webp 1312w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/08e240cab6a445a3be8e091f44f1f6b6-300x168.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/08e240cab6a445a3be8e091f44f1f6b6-1024x574.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/08e240cab6a445a3be8e091f44f1f6b6-768x431.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/08e240cab6a445a3be8e091f44f1f6b6-18x10.webp 18w\" sizes=\"(max-width: 1312px) 100vw, 1312px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Bienvenido al mundo de alta velocidad de Internet de fibra \u00f3ptica! Si eres uno de los afortunados que cuenta con una <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/what-is-ftth-fiber-to-the-home\/\"><strong>Fibra hasta el hogar (FTTH)<\/strong><\/a> conexi\u00f3n, probablemente ya hayas visto un peque\u00f1o y elegante dispositivo instalado en alguna parte de tu hogar. Es posible que tu t\u00e9cnico lo haya llamado \u201cONT\u201d o \u201cONU\u201d y te hayas preguntado: \u201c\u00bfNo son lo mismo?\u201d.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No est\u00e1s solo. Los t\u00e9rminos ONT y ONU suelen usarse indistintamente, pero existe una sutil diferencia t\u00e9cnica entre ellos. Comprender esta distinci\u00f3n es clave para saber c\u00f3mo funciona realmente tu conexi\u00f3n de Internet ultrarr\u00e1pida. En este art\u00edculo, desmitificaremos estas piezas cruciales de hardware, analizaremos sus funciones y te ayudaremos a entender por qu\u00e9 la elecci\u00f3n correcta importa para tu red dom\u00e9stica o empresarial.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 Primero, la visi\u00f3n general: \u00bfQu\u00e9 es una OLT?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para comprender las ONT y las ONU, primero debemos conocer a su controlador: la <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/what-is-olt-and-its-importance-in-fiber-optic-networks\/\"><strong>OLT (Terminal de L\u00ednea \u00d3ptica)<\/strong><\/a>. Imagina la OLT como el cerebro de toda la red de fibra. Se trata de un equipo grande ubicado en la oficina central de tu proveedor de servicios de Internet (ISP). Su funci\u00f3n es transmitir datos a todos sus clientes y recibir datos de ellos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La OLT se comunica con los dispositivos de tu extremo mediante un delgado cable de fibra de vidrio. Aqu\u00ed es donde entran en escena nuestros dos protagonistas principales: la ONT y la ONU.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 \u00bfQu\u00e9 es una ONU? (Unidad de Red \u00d3ptica)<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1312\" height=\"640\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5bdb061545d04dc8aa8ec69ef61a0381.webp\" alt=\"Optical Network Unit\" class=\"wp-image-5006\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5bdb061545d04dc8aa8ec69ef61a0381.webp 1312w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5bdb061545d04dc8aa8ec69ef61a0381-300x146.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5bdb061545d04dc8aa8ec69ef61a0381-1024x500.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5bdb061545d04dc8aa8ec69ef61a0381-768x375.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/5bdb061545d04dc8aa8ec69ef61a0381-18x9.webp 18w\" sizes=\"(max-width: 1312px) 100vw, 1312px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">An <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/what-is-onu-and-why-it-matters-for-your-internet-connection\/\"><strong>ONU (Unidad de Red \u00d3ptica)<\/strong><\/a> es un t\u00e9rmino gen\u00e9rico para el dispositivo que convierte la se\u00f1al entrante <strong>\u00f3ptica<\/strong> de la l\u00ednea de fibra \u00f3ptica de tu ISP en una <strong>se\u00f1alizaci\u00f3n el\u00e9ctrica sobre cobre twinax. \u00d3ptimos para distancias muy cortas (&lt; 7 m). Menor consumo de energ\u00eda, menor costo y latencia m\u00e1s baja. Predominantes dentro de los racks.<br><\/strong> se\u00f1al que tus dispositivos cotidianos (port\u00e1tiles, tel\u00e9fonos m\u00f3viles, televisores inteligentes) pueden entender.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ONU es un puente crucial entre el tronco principal de fibra y tu red de \u00e1rea local (LAN). Normalmente admite funciones como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Conversi\u00f3n de se\u00f1al:<\/strong> Conversi\u00f3n \u00f3ptica-a-el\u00e9ctrica (O\/E) y el\u00e9ctrica-a-\u00f3ptica (E\/O).<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Servicios m\u00faltiples:<\/strong> Suele gestionar datos (Internet), voz (VoIP) y, en algunos casos, incluso tr\u00e1fico de video.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 \u00bfQu\u00e9 es una ONT? (Terminal de Red \u00d3ptica)<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1312\" height=\"638\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/6ccfc413cf004f5c964ff16c1ce95c86.webp\" alt=\"Optical Network Terminal\" class=\"wp-image-5007\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/6ccfc413cf004f5c964ff16c1ce95c86.webp 1312w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/6ccfc413cf004f5c964ff16c1ce95c86-300x146.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/6ccfc413cf004f5c964ff16c1ce95c86-1024x498.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/6ccfc413cf004f5c964ff16c1ce95c86-768x373.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/6ccfc413cf004f5c964ff16c1ce95c86-18x9.webp 18w\" sizes=\"(max-width: 1312px) 100vw, 1312px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed es donde las cosas se vuelven interesantes. Una <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/ont-optical-network-terminal-how-it-works-fiber-internet\/\"><strong>ONT (Terminal de Red \u00d3ptica)<\/strong><\/a> es un tipo espec\u00edfico <em>de ONU. El factor diferenciador clave es su<\/em> ubicaci\u00f3n. <strong>Una ONT es una<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ONU ubicada directamente en las instalaciones del usuario, <strong>\u2014en tu hogar, oficina o edificio\u2014. Es el punto final de terminaci\u00f3n de la l\u00ednea de fibra \u00f3ptica. Por tanto, si el cable de fibra entra directamente en un dispositivo dentro de tu vivienda, ese dispositivo se denomina con mayor precisi\u00f3n ONT.<\/strong>\u27a4 Diferencia fundamental entre ONT y ONU: explicaci\u00f3n simplificada.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>En la conversaci\u00f3n cotidiana, la diferencia es m\u00ednima. Sin embargo, desde el punto de vista t\u00e9cnico:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">t\u00e9rmino espec\u00edfico del abonado<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>ONT<\/strong> \u03b5\u03af\u03bd\u03b1\u03b9 \u03ad\u03bd\u03b1 <strong>usado en<\/strong> es un t\u00e9rmino m\u00e1s <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/glossary\/what-is-ftth-fiber-to-the-home\/\"><strong>FTTH (fibra hasta el hogar)<\/strong><\/a> implementaciones.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>ONU<\/strong> general y multifuncional <strong>que puede emplearse en otras arquitecturas de fibra, como<\/strong> o FTTC (Fibra hasta la acera). <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/el\/knowledge-center\/what-is-fttb-fiber-to-the-building\/\"><strong>FTTB (fibra hasta el edificio)<\/strong><\/a> La forma m\u00e1s sencilla de recordarlo:.<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Todas las ONT son ONU, pero no todas las ONU son ONT.<\/strong> Definici\u00f3n principal.<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p>Caracter\u00edstica<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>ONT (Terminal de Red \u00d3ptica)<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>ONU (Unidad de Red \u00d3ptica)<\/strong><\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>dispositivo terminal \u00f3ptico ubicado en las instalaciones del usuario.<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>A <strong>t\u00e9rmino gen\u00e9rico<\/strong> para dispositivos de red \u00f3ptica.<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>A <strong>Dentro de las instalaciones del usuario<\/strong> (hogar\/oficina).<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Ubicaci\u00f3n<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p><strong>Puede estar ubicado en cualquier lugar: instalaciones del usuario, acera o s\u00f3tano de un edificio.<\/strong> Usado espec\u00edficamente en.<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Usado en diversas implementaciones: FTTH,.<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Despliegue<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>FTTB (edificio), <strong>FTTH (fibra hasta el hogar)<\/strong>.<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>, FTTC (acera)., <strong>Alcance funcional<\/strong>, Termina.<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>la l\u00ednea de fibra directamente en el abonado.<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p><strong>Act\u00faa como un punto intermedio<\/strong> de conversi\u00f3n.<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Normalmente utilizado por <strong>consumidores finales.<\/strong> Un t\u00e9rmino m\u00e1s amplio usado por.<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Uso habitual<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>ingenieros de redes y proveedores de servicios de Internet (ISP). <strong>\u27a4 \u00bfPor qu\u00e9 esto te importa? Elegir el dispositivo adecuado<\/strong>.<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Ya sea que tu ISP lo llame ONT u ONU, la <strong>calidad y las capacidades<\/strong>.<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>de este dispositivo son fundamentales para tu experiencia de Internet. Un dispositivo robusto garantiza:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Conexiones estables y de alta velocidad: <strong>Minimiza la latencia y la p\u00e9rdida de paquetes para juegos y transmisi\u00f3n en streaming.<\/strong> Admite tecnolog\u00edas m\u00e1s recientes, como Wi-Fi 6 y niveles superiores de ancho de banda.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Fiabilidad de la red:<\/strong> Reduce tiempos de inactividad y problemas de sobrecalentamiento.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Preparaci\u00f3n para el futuro:<\/strong> Aqu\u00ed es donde elegir equipos de una marca confiable como.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>marca una diferencia significativa. LINK-PP se especializa en unidades de red \u00f3ptica de alto rendimiento y grado operador, dise\u00f1adas para estabilidad y eficiencia.<\/strong> \u27a4 Caracter\u00edsticas clave a considerar en tu ONT\/ONU.<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Al evaluar tu dispositivo, ya sea proporcionado por tu ISP o si lo adquieres por tu cuenta, ten en cuenta estos elementos esenciales de <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.link-pp.com\/\"><strong>LINK-PP<\/strong><\/a> redes de fibra \u00f3ptica:.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>Cumplimiento del est\u00e1ndar GPON:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Garantiza compatibilidad con la OLT de tu ISP. <strong>N\u00famero de puertos Ethernet:<\/strong> \u00bfNecesitas m\u00faltiples conexiones cableadas?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p style=\"margin: 0px;\"><strong>Capacidad Wi-Fi:<\/strong> \u00bfEst\u00e1 integrada (unidad de pasarela dom\u00e9stica \u2013 HGU) o necesitas un router independiente?.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Velocidad de Internet admitida:<\/strong> \u00bfSe ajusta a tu plan contratado (por ejemplo, 1 Gbps, 2,5 Gbps)?<\/p><\/li><li><p style=\"margin: 0px;\"><strong>Funciones adicionales:<\/strong> Puertos VoIP para servicio telef\u00f3nico fijo, puertos USB o interfaces de gesti\u00f3n sencillas.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>\u27a4 Veredicto final: ONT frente a ONU<\/strong> Aunque la distinci\u00f3n t\u00e9cnica entre<\/p><\/li><li><p style=\"margin: 0px;\"><strong>ONT y ONU<\/strong> se refiere principalmente a cuestiones sem\u00e1nticas y de ubicaci\u00f3n, la conclusi\u00f3n pr\u00e1ctica es clara: este dispositivo es el coraz\u00f3n de tu conexi\u00f3n de fibra. Comprender su papel te permite formular las preguntas adecuadas y asegurarte de contar con el mejor equipo para tus necesidades.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>Para una conexi\u00f3n fiable y de alto rendimiento que maximice tu inversi\u00f3n en fibra, optar por tecnolog\u00eda probada de marcas como<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">es una decisi\u00f3n inteligente. Sus dispositivos est\u00e1n dise\u00f1ados para soportar las exigencias de la moderna <strong>tecnolog\u00eda FTTH,<\/strong> garantizando que obtengas cada bit de velocidad por el que pagas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCu\u00e1l es la diferencia principal entre ONU y ONT? <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/page\/aboutus.htm\"><strong>LINK-PP<\/strong><\/a> Usas una ONU en lugares donde muchas personas comparten Internet, como apartamentos. Usas una ONT para un hogar o una oficina individual. Ambos se conectan a redes de fibra, pero atienden a distintos n\u00fameros de usuarios. <strong>Tecnolog\u00eda FTTH<\/strong>, lo que garantiza que obtenga toda la velocidad por la que paga.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\u27a4 \u03a3\u03c5\u03c7\u03bd\u03ad\u03c2 \u0395\u03c1\u03c9\u03c4\u03ae\u03c3\u03b5\u03b9\u03c2<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >\u00bfCu\u00e1l es la diferencia principal entre ONU y ONT?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Utiliza una ONU en lugares donde muchas personas comparten internet, como apartamentos. Utiliza una ONT para una \u00fanica vivienda u oficina. Ambas se conectan a redes de fibra \u00f3ptica, pero atienden a distintos n\u00fameros de usuarios.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >\u00bfPuedo usar un ONT en lugar de un ONU en mi edificio?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">No debe usar un ONT para muchos usuarios en un solo edificio. Un ONU funciona mejor en espacios compartidos. Un ONT es ideal para hogares o peque\u00f1as oficinas donde solo un usuario necesita una conexi\u00f3n directa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >\u00bfQu\u00e9 dispositivo ofrece internet m\u00e1s r\u00e1pido: ONU o ONT?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Obtiene velocidades similares con ambos dispositivos si su red lo admite. Un ONT suele ofrecerle velocidades m\u00e1s estables porque no comparte su conexi\u00f3n con otros usuarios. Un ONU divide el ancho de banda entre muchos usuarios.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >\u00bfC\u00f3mo decido entre ONU y ONT para mi red?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Debe considerar su ubicaci\u00f3n y la cantidad de personas que necesitan internet. Para una conexi\u00f3n privada y directa, elija un ONT. Para internet compartido en un edificio grande, elija un ONU. Esto le ayuda a obtener la configuraci\u00f3n \u00f3ptima.<\/p>","protected":false},"excerpt":{"rendered":"<p>Explicaci\u00f3n de ONU frente a ONT: comprenda las diferencias clave, funciones y qu\u00e9 dispositivo se adapta mejor a sus necesidades de Internet por fibra \u00f3ptica, ya sea para el hogar o edificios compartidos.<\/p>","protected":false},"author":1,"featured_media":5005,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[26],"class_list":["post-5008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowledge-center","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/comments?post=5008"}],"version-history":[{"count":4,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5008\/revisions"}],"predecessor-version":[{"id":11108,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/posts\/5008\/revisions\/11108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/media\/5005"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/media?parent=5008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/categories?post=5008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/el\/wp-json\/wp\/v2\/tags?post=5008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}