{"id":5672,"date":"2025-07-17T00:00:00","date_gmt":"2025-07-17T00:00:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/products\/how-to-choose-the-right-10g-sfp-plus-transceiver\/"},"modified":"2026-06-22T08:58:08","modified_gmt":"2026-06-22T08:58:08","slug":"how-to-choose-the-right-10g-sfp-plus-transceiver","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/de\/products\/how-to-choose-the-right-10g-sfp-plus-transceiver","title":{"rendered":"10G SFP+ Optischer Transceiver Auswahlguide"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1ecfd6b495d942f3a64e2b376621c7ac.webp\" alt=\"10G SFP+ Transceiver Buying Guide\" class=\"wp-image-5671\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1ecfd6b495d942f3a64e2b376621c7ac.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1ecfd6b495d942f3a64e2b376621c7ac-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1ecfd6b495d942f3a64e2b376621c7ac-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1ecfd6b495d942f3a64e2b376621c7ac-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/1ecfd6b495d942f3a64e2b376621c7ac-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">10G-SFP+-Module sind essentielle Komponenten in Hochgeschwindigkeits-Netzwerken wie Rechenzentren, Unternehmens-Backbones und Telekommunikationsinfrastrukturen. Die Auswahl des richtigen SFP+-Moduls gew\u00e4hrleistet nicht nur eine optimale Leistung, sondern reduziert auch Kompatibilit\u00e4tsprobleme und Wartungskosten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In diesem Kaufleitfaden f\u00fchren wir Sie durch die wichtigsten Entscheidungskriterien, Unterschiede zwischen den Modultypen, Kompatibilit\u00e4tshinweise sowie einige empfohlene Produkte von <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-26192-10g-sfp.htm\">LINK-PPs 10G-SFP+-Produktlinie<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie einen 10G-SFP+-Transceiver w\u00e4hlen, beachten Sie diese wesentlichen Schritte:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>Pr\u00fcfen Sie die Kompatibilit\u00e4t mit Ihrer Switch-Marke und dem Steckertyp.<\/p><\/li><li><p>W\u00e4hlen Sie das richtige \u00dcbertragungsmedium und den passenden Transceivertyp entsprechend Ihrer Reichweitenanforderungen.<\/p><\/li><li><p>Pr\u00fcfen Sie die Unterst\u00fctzung von DDM (Digital Diagnostic Monitoring), den Stromverbrauch und die Garantiebedingungen.<\/p><\/li><li><p>Verwenden Sie eine Checkliste, um Fehler zu vermeiden und Ihr Netzwerk zukunftssicher zu gestalten.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >1\ufe0f\u20e3 Was ist ein 10G-SFP+-Transceiver?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">The <strong>SFP+ (Small Form-Factor Steckmodul Plus)<\/strong> Ein Transceiver ist ein kompaktes, hot-swap-f\u00e4higes Modul f\u00fcr 10-Gigabit-Ethernet-Anwendungen. Es handelt sich um eine verbesserte Version des herk\u00f6mmlichen SFP-Moduls mit Datenraten bis zu 10,7 Gbit\/s. Es verwendet <strong>LC-Glasfasersteckverbindern<\/strong> or <strong>Direct-Attach-Copper-(DAC)-Kabel<\/strong> f\u00fcr Kurzstreckenverbindungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udccc <strong>SFP \u2260 SFP+<\/strong>: Obwohl sie optisch \u00e4hnlich aussehen, unterst\u00fctzen Standard-SFPs lediglich bis zu 1 Gbit\/s. Nur <strong>SFP+-Module<\/strong> SFP+-Module.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >2\ufe0f\u20e3 Typen von 10G-SFP+-Modulen: SR, LR, ER, DAC u. a.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bei der Auswahl eines Moduls sind die wichtigsten Kriterien <strong>\u00dcbertragungsreichweite<\/strong>, <strong>Glasfasertyp<\/strong>, und <strong>Wellenl\u00e4nge<\/strong>. Hier eine kurze \u00dcbersicht:<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p>Type<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Entfernung<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Wellenl\u00e4nge<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Glasfaser<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Einsatzgebiet<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>SR (Kurzstrecke)<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u2264 300 m<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>850nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Multimod<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Innerhalb eines Racks, Kurzstrecke<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>LR (Langstrecke)<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u2264 10 km<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>1310 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Singlemode<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Geb\u00e4ude-zu-Geb\u00e4ude<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>ER\/ZR<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Bis zu 40 km \/ 80 km<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>1550 nm<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Singlemode<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Metro-Ethernet<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>DAC (Direct-Attach-Kupfer)<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u2264 10 m<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>N\/A<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Twinax-Kabel<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Kostenoptimiert, hohe Serverdichte<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>RJ45-Kupfer<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>\u2264 30 m<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>N\/A<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Cat6a-Kabel<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>10GBase-T \u00fcber verdrilltes Paar<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udc49 F\u00fcr das vollst\u00e4ndige Sortiment besuchen Sie die <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-26192-10g-sfp.htm\">LINK-PP-10G-SFP+-Kollektion<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >3\ufe0f\u20e3 Kompatibilit\u00e4t ist entscheidend: OEM- vs. kompatible Module<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Verschiedene Hersteller (z. B. Cisco, Juniper, Arista) sperren ihre Switches h\u00e4ufig auf bestimmte Modul-IDs. LINK-PP bietet jedoch <strong>kompatible SFP+-Transceiver<\/strong> an, die bereits vorcodiert sind, um mit f\u00fchrenden Switch-Herstellern zu funktionieren \u2013 <strong>ohne Leistung oder Zuverl\u00e4ssigkeit einzub\u00fc\u00dfen<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2705 LINK-PP-Module unterst\u00fctzen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>DDM (Digitale Diagnose\u00fcberwachung)<\/p><\/li><li><p>Konformit\u00e4t mit dem MSA-Standard<\/p><\/li><li><p>RoHS- und CE-Zertifizierung<\/p><\/li><li><p>Optionale industrielle Temperaturbereiche (\u221240 \u00b0C bis 85 \u00b0C)<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" >4\ufe0f\u20e3 Wichtige Aspekte beim Kauf eines 10G-SFP+-Moduls<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hier sind die wichtigsten Faktoren, die Sie vor dem Kauf pr\u00fcfen sollten:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>Entfernung<\/strong>: W\u00e4hlen Sie SR f\u00fcr kurze, LR f\u00fcr lange Strecken oder DAC f\u00fcr Rack-zu-Rack-Verbindungen.<\/p><\/li><li><p><strong>Anschlusstyp<\/strong>: LC-Duplex f\u00fcr Glasfaser, RJ45 f\u00fcr Kupfer.<\/p><\/li><li><p><strong>Fasertyp<\/strong>: Passen Sie den Einsatz (MMF oder SMF) an.<\/p><\/li><li><p><strong>Ger\u00e4tekompatibilit\u00e4t<\/strong>: Stellen Sie sicher, dass die EEPROM-Kompatibilit\u00e4t mit Ihrem Switch gegeben ist.<\/p><\/li><li><p><strong>Temperaturklasse<\/strong>: Verwenden Sie industriell zertifizierte Module in rauen Umgebungen.<\/p><\/li><li><p><strong>Leistungs-Budget<\/strong>: Stellen Sie sicher, dass der optische Leistungsbereich den Anforderungen Ihres Netzwerks entspricht.<\/p><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" >\ud83d\uded2 Empfohlene LINK-PP-10G-SFP+-Produkte<\/h3>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"532\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/0547a8fac21a4bcc9998034ed695c7ec.webp\" alt=\"\" class=\"wp-image-3857\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/0547a8fac21a4bcc9998034ed695c7ec.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/0547a8fac21a4bcc9998034ed695c7ec-300x133.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/0547a8fac21a4bcc9998034ed695c7ec-1024x454.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/0547a8fac21a4bcc9998034ed695c7ec-768x340.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/0547a8fac21a4bcc9998034ed695c7ec-18x8.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Im Folgenden finden Sie professionell entwickelte, leistungsstarke 10G-SFP+-Transceiver von LINK-PP. Diese Module wurden nach 100% getestet, erf\u00fcllen vollst\u00e4ndig die MSA-Anforderungen und sind mit f\u00fchrenden Netzwerkmarken kompatibel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >\ud83d\udd39 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/475415.htm\">LS-MM8510-S3C \u2013 10GBASE-SR-SFP+-Modul (MMF, 300 m)<\/a><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>Type<\/strong>: 10GBASE-SR<\/p><\/li><li><p><strong>Wellenl\u00e4nge<\/strong>: 850 nm<\/p><\/li><li><p><strong>Datenrate<\/strong>: 10,3125 Gbit\/s<\/p><\/li><li><p><strong>Entfernung<\/strong>: Bis zu 300 Meter<\/p><\/li><li><p><strong>Stecker<\/strong>: LC-Duplex<\/p><\/li><li><p><strong>Fasertyp<\/strong>: Multimode-Glasfaser (OM3\/OM4 empfohlen)<\/p><\/li><li><p><strong>Temperatur<\/strong>: 0 \u00b0C bis +70 \u00b0C (Commercial Grade)<\/p><\/li><li><p><strong>Digitale Diagnosefunktion (DDM)<\/strong>: Unterst\u00fctzt<\/p><\/li><li><p><strong>Konformit\u00e4t<\/strong>: MSA, RoHS, CE<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udccc <em>Ideal f\u00fcr Kurzstreckenanwendungen wie Intra-Rack-Verbindungen und Campus-Backbone-Verbindungen.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >\ud83d\udd39 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/475605.htm\">LS-SM3110-10I \u2013 10GBASE-LR-SFP+-Modul (SMF, 10 km)<\/a><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>Type<\/strong>: 10GBASE-LR<\/p><\/li><li><p><strong>Wellenl\u00e4nge<\/strong>: 1310 nm<\/p><\/li><li><p><strong>Datenrate<\/strong>: 10,7 Gbit\/s<\/p><\/li><li><p><strong>Entfernung<\/strong>: Bis zu 10 Kilometer<\/p><\/li><li><p><strong>Stecker<\/strong>: LC-Duplex<\/p><\/li><li><p><strong>Fasertyp<\/strong>: Einmodenglasfaser<\/p><\/li><li><p><strong>Temperatur<\/strong>: \u201340 \u00b0C bis +85 \u00b0C (Industrial Grade)<\/p><\/li><li><p><strong>Digitale Diagnosefunktion (DDM)<\/strong>: Unterst\u00fctzt<\/p><\/li><li><p><strong>Konformit\u00e4t<\/strong>: MSA, RoHS, CE<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udccc <em>Ideal f\u00fcr Langstreckendeployments zwischen Rechenzentren oder \u00fcber Geb\u00e4ude hinweg.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >\ud83d\udd39 <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/482688.htm\">LP-RJ45TG-3YI \u2013 10GBASE-T-SFP+-RJ45-Kupfertransceiver<\/a><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><strong>Type<\/strong>: 10GBASE-T-RJ45-SFP+<\/p><\/li><li><p><strong>Schnittstelle<\/strong>: RJ45-Kupferanschluss<\/p><\/li><li><p><strong>Datenrate<\/strong>: 10 Gbit\/s<\/p><\/li><li><p><strong>Entfernung<\/strong>: Bis zu 30 Meter \u00fcber Cat6a-\/Cat7-Kabel<\/p><\/li><li><p><strong>Kompatibilit\u00e4t<\/strong>: Abw\u00e4rtskompatibel mit 1000Base-T<\/p><\/li><li><p><strong>Temperatur<\/strong>: \u201340 \u00b0C bis +85 \u00b0C (Industrial Grade)<\/p><\/li><li><p><strong>Konformit\u00e4t<\/strong>: IEEE 802.3an, RoHS<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udccc <em>Perfekt f\u00fcr Kurzstrecken-Kupfer-Deployments bei Switch-zu-Server-Verbindungen, wo keine Glasfaser verf\u00fcgbar ist.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\udcda Bonus: H\u00e4ufig gestellte Fragen<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >\u2753 Kann ich ein 1G-SFP-Modul in einem 10G-SFP+-Anschluss verwenden?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u2705 Ja, die meisten 10G-SFP+-Anschl\u00fcsse sind abw\u00e4rtskompatibel mit 1G-SFP-Modulen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >\u2753 Kann ich SFP+-Marken mischen?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a0\ufe0f Das Mischen ist m\u00f6glich, <strong>sofern die Kompatibilit\u00e4t best\u00e4tigt wurde.<\/strong>. LINK-PP bietet ger\u00e4tespezifische Codierung, um einen Plug-and-Play-Einsatz zu gew\u00e4hrleisten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >\u2753 Sind SFP+-Module hot-swap-f\u00e4hig?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u2705 Ja, alle LINK-PP-SFP+-Transceiver unterst\u00fctzen <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/the-hot-pluggable-nature-of-optical-modules\/\">Hot-Swapping<\/a>.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h2 class=\"wp-block-heading\" >\u2705 Conclusion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Auswahl des richtigen 10G-SFP+-Transceivers h\u00e4ngt von Ihrer Netzwerkumgebung, dem Fasertyp, der Kompatibilit\u00e4t mit Ihrem Switch und der gew\u00fcnschten \u00dcbertragungsreichweite ab. Ob Sie ein hochdichtes Rechenzentrum aufbauen oder ein Unternehmensnetzwerk aktualisieren \u2013 LINK-PP bietet ein umfassendes Portfolio kosteng\u00fcnstiger, hochwertiger 10G-SFP+-Module f\u00fcr jedes Szenario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\uded2 <strong>Entdecken Sie hier unsere gesamte Auswahl:<\/strong> <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-26192-10g-sfp.htm\">10G-SFP+-Optiktransceiver<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >Siehe auch<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/glossary\/wdm-optical-transceiver-module-applications\/\">Grundlagen der WDM-Technologie und ihre Anwendung in optischen Netzen<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/knowledge-center\/1x9-transceiver-optical-network-guide\/\">Stellen Sie sich der LINK-PP-Netzwerk-Community vor<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>W\u00e4hlen Sie den richtigen 10G-SFP+-Transceiver aus, indem Sie Kompatibilit\u00e4t, Geschwindigkeit, Medientyp, Reichweite und Kosten f\u00fcr zuverl\u00e4ssige Netzwerk-Upgrades vergleichen.<\/p>","protected":false},"author":1,"featured_media":5671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[28],"tags":[14,26],"class_list":["post-5672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-products","tag-10g-sfp-transceivers","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/posts\/5672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/comments?post=5672"}],"version-history":[{"count":4,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/posts\/5672\/revisions"}],"predecessor-version":[{"id":11331,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/posts\/5672\/revisions\/11331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/media\/5671"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/media?parent=5672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/categories?post=5672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/tags?post=5672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}