{"id":4466,"date":"2025-11-08T11:12:00","date_gmt":"2025-11-08T11:12:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/knowledge-center\/silicon-photonic-modulators-vs-traditional-optical-modulators\/"},"modified":"2026-06-22T05:22:10","modified_gmt":"2026-06-22T05:22:10","slug":"silicon-photonic-modulators-vs-traditional-optical-modulators","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/de\/knowledge-center\/silicon-photonic-modulators-vs-traditional-optical-modulators","title":{"rendered":"Silizium-Photonik-Modulatoren im Vergleich zu herk\u00f6mmlichen optischen Modulatoren"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/28f952b2e8c14f70842d1c5e2b5819e6.webp\" alt=\"Silicon Photonic Modulators vs. Traditional Optical Modulators\" class=\"wp-image-4462\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/28f952b2e8c14f70842d1c5e2b5819e6.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/28f952b2e8c14f70842d1c5e2b5819e6-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/28f952b2e8c14f70842d1c5e2b5819e6-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/28f952b2e8c14f70842d1c5e2b5819e6-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/28f952b2e8c14f70842d1c5e2b5819e6-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\udd39 Einf\u00fchrung<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/what-is-optical-modulation-and-how-it-works-explained\/\"><strong>Optische Modulatoren<\/strong><\/a> spielen eine zentrale Rolle in Hochgeschwindigkeits-Faseroptik-Kommunikationssystemen. Sie sind die Schl\u00fcsselkomponenten, die <strong>elektrische Daten in optische Signale codieren<\/strong> zur \u00dcbertragung \u00fcber optische Fasern. Mit steigenden Datentransferraten jenseits von 400 G und 800 G ist eine neue Generation von <strong>Silizium-Photonik-Modulatoren (Si-Ph-Modulatoren)<\/strong> entstanden, um herk\u00f6mmliche volumin\u00f6se optische Modulatoren zu ersetzen und so die Art und Weise zu ver\u00e4ndern, wie Rechenzentren und Telekommunikationsnetzwerke Bandbreite und Energieeffizienz bew\u00e4ltigen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser Artikel erl\u00e4utert, was Silizium-Photonik-Modulatoren sind, wie sie sich von herk\u00f6mmlichen optischen Modulatoren unterscheiden und warum sie die Landschaft optischer Transceiver ver\u00e4ndern.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\udd39 Was ist ein optischer Modulator?<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d0e49b040252463ca14b30abb00ba8f5.webp\" alt=\" What Is Optical Modulator?\" class=\"wp-image-4463\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d0e49b040252463ca14b30abb00ba8f5.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d0e49b040252463ca14b30abb00ba8f5-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d0e49b040252463ca14b30abb00ba8f5-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d0e49b040252463ca14b30abb00ba8f5-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/d0e49b040252463ca14b30abb00ba8f5-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">An <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/what-is-optical-modulation-and-how-it-works-explained\/\"><strong>optischer Modulator<\/strong><\/a> ist ein Ger\u00e4t, das eine oder mehrere Eigenschaften einer Lichtwelle \u2013 typischerweise <strong>Amplitude, Phase oder Frequenz<\/strong>\u2013 als Reaktion auf ein elektrisches Signal ver\u00e4ndert.<br\/>Sein Kernzweck ist es, <strong>Daten auf einen Lichttr\u00e4ger zu codieren<\/strong>, wodurch digitale Kommunikation \u00fcber optische Fasern erm\u00f6glicht wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Traditionelle optische Modulatoren haben lange auf <strong>elektrooptischen Kristallen<\/strong> wie beispielsweise <strong>wie Lithiumniobat (LiNbO\u2083)<\/strong> oder Verbindungshalbleitern wie <strong>InP<\/strong> or <strong>GaAs<\/strong>. beruht. Diese Materialien zeigen den <strong>Pockels-Effekt<\/strong>, bei dem ein angelegtes elektrisches Feld den Brechungsindex direkt ver\u00e4ndert und so eine pr\u00e4zise, lineare und hochgeschwindigkeitsf\u00e4hige Modulation erm\u00f6glicht.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\udd39 Was ist ein Silizium-Photonik-Modulator?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>Silizium-Photonik-Modulator<\/strong> integriert die Lichtmodulation direkt auf einem <strong>Siliziumchip<\/strong>, unter Nutzung von <strong>CMOS-kompatiblen Herstellungsverfahren.<\/strong> Statt des Pockels-Effekts nutzt Silizium den <strong>freie-Ladungstr\u00e4ger-Plasma-Dispersionseffekt<\/strong>, bei dem das Einspeisen oder Entfernen von Ladungstr\u00e4gern den Brechungsindex von Silizium ver\u00e4ndert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser Mechanismus erm\u00f6glicht kompakte, kosteng\u00fcnstige und energieeffiziente Bauelemente, die ideal f\u00fcr <strong>gro\u00dffl\u00e4chige photonische Integration<\/strong> in Rechenzentren, <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/knowledge-center\/5g-fronthaul-high-speed-low-latency-communication-explained\/\">5G-Fronthaul<\/a>, und KI-Interconnects sind.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1200\" height=\"712\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/c86c2f5f054f4b228bbc2219ae746c26.webp\" alt=\"Main Types of Silicon Photonic Modulators\" class=\"wp-image-4464\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/c86c2f5f054f4b228bbc2219ae746c26.webp 1200w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/c86c2f5f054f4b228bbc2219ae746c26-300x178.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/c86c2f5f054f4b228bbc2219ae746c26-1024x608.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/c86c2f5f054f4b228bbc2219ae746c26-768x456.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/c86c2f5f054f4b228bbc2219ae746c26-18x12.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" >Haupttypen von Silizium-Photonik-Modulatoren<\/h3>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p><strong>Mach-Zehnder-Modulator (MZM)<\/strong><br\/>Nutzt Interferenz zwischen zwei Lichtpfaden. Durch \u00c4nderung der Phasendifferenz mittels elektrischer Signale moduliert er die Lichtintensit\u00e4t.<br\/>\u2192 Unterst\u00fctzt ultraschnelle Modulation mit bis zu \u00fcber 100 Gbps pro Kanal.<\/p><\/li><li><p><strong>Ringresonator-Modulator (RR)<\/strong><br\/>Basierend auf einem kleinen ringf\u00f6rmigen Resonanzhohlraum, dessen Resonanzwellenl\u00e4nge sich bei Spannungs\u00e4nderung verschiebt.<br\/>\u2192 Kompakte Bauform und geringer Stromverbrauch.<\/p><\/li><li><p><strong>Elektro-Absorptions-Modulator (EAM)<\/strong><br\/>\u00c4ndert die Lichtabsorptionseigenschaften unter elektrischen Feldern.<br\/>\u2192 Bietet schnelle Reaktionszeit und hohe Integrationsdichte.<\/p><\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\udd39 Wichtige Unterschiede: Silizium-basierte vs. traditionelle optische Modulatoren<\/h2>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p><strong>Aspekt<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><strong>Silizium-Photonik-Modulator<\/strong><\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/what-is-optical-modulation-and-how-it-works-explained\/\"><strong>Traditioneller optischer Modulator<\/strong><\/a><\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Material<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Silizium (Si), SiO\u2082<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>LiNbO\u2083, InP, GaAs<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Modulationsmechanismus<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Freie-Tr\u00e4ger-Effekt<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Elektro-optischer (Pockels-)Effekt<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Fertigung<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>CMOS-kompatibel, einfache Integration<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Spezieller photonischer Prozess<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Gr\u00f6\u00dfe &amp; Leistungsaufnahme<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Kompakt, geringer Stromverbrauch<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Gro\u00dfe Baugr\u00f6\u00dfe, h\u00f6here Leistungsaufnahme<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Bandbreite<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>&gt;100 GHz (mit integriertem Treiber)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Ausgezeichnete Linearit\u00e4t, hohe Pr\u00e4zision<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Integration<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Einfache Co-Packaging-M\u00f6glichkeit mit Treibern und Fotodioden<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Eingeschr\u00e4nkte Integration<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Cost<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Niedriger, skalierbar<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>H\u00f6her, aufw\u00e4ndige Fertigung<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Einsatzgebiet<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Rechenzentren, AI\/ML-Verbindungen, Kurzstrecken-Links<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Langstrecken-Telekommunikation, Verteidigung, Forschung<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\udd39 Warum Silizium-photonische Modulatoren die Zukunft sind<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Da sich optische Systeme hin zu <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/knowledge-center\/what-is-cpo-optical-module-and-why-it-matters\/\"><strong>Co-verpackte Optik (CPO)<\/strong><\/a> et <strong>Chiplet-basierten Architekturen<\/strong>, weiterentwickeln, bieten silizium-photonische Modulatoren entscheidende Vorteile:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>\u26a1 <strong>Hochgeschwindigkeitsbetrieb<\/strong> kompatibel mit <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/glossary\/what-is-pam4-four-level-pulse-amplitude-modulation-basics\/\">PAM4<\/a> und koh\u00e4renten Modulationsformaten (DP-QPSK, 16-QAM).<\/p><\/li><li><p>\ud83d\udca1 <strong>Monolithische Integration<\/strong> mit Fotodioden, Lasern (\u00fcber Hybridbonding) und Transimpedanzverst\u00e4rkern (<a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/glossary\/transimpedance-amplifiers-tias-how-they-work-and-applications\/\">TIAs<\/a>).<\/p><\/li><li><p>\ud83e\udde0 <strong>CMOS-Co-Packaging<\/strong> erm\u00f6glicht, dass Elektronik und Photonik auf demselben Substrat koexistieren.<\/p><\/li><li><p>\u267b\ufe0f <strong>Geringerer Stromverbrauch und kleinere Baugr\u00f6\u00dfe<\/strong>, \u2013 ideal f\u00fcr hyperskalige Rechenzentren.<\/p><\/li><li><p>\ud83e\udde9 <strong>Skalierbarkeit der Massenfertigung<\/strong>, \u2013 senkt Kosten und verbessert Zuverl\u00e4ssigkeit.<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Faktoren machen Siliziumphotonik zur Grundlage von <strong>zuk\u00fcnftigen 800G-, 1,6T- und noch h\u00f6heren \u00dcbertragungsraten<\/strong> <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-26044-200-400-800g-transceiver-modules.htm\">Optische Transceiver<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\udd39 Zuk\u00fcnftige Trends bei silizium-photonischen Modulatoren<\/h2>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p><strong>Heterogene Integration:<\/strong><br\/>Kombination von Silizium mit III\u2013V-Halbleitermaterialien f\u00fcr integrierte <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/knowledge-center\/laser-types-in-optical-transceiver-modules\/\">Laser<\/a> und EAMs auf derselben Die.<\/p><\/li><li><p><strong>Fortschrittliche Modulationsformate:<\/strong><br\/>Unterst\u00fctzung f\u00fcr <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/knowledge-center\/dp-qpsk-dual-polarization-qpsk-explained-and-its-uses\/\">DP-QPSK<\/a>, PAM4 und QAM erm\u00f6glichen eine h\u00f6here Datenrate pro Wellenl\u00e4nge.<\/p><\/li><li><p><strong>AI- und HPC-Verbindungen:<\/strong><br\/><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/knowledge-center\/silicon-photonics-comprehensive-guide\/\">Siliziumphotonik<\/a> erm\u00f6glicht optische Verbindungen mit geringer Latenz f\u00fcr KI-Beschleuniger und HPC-Cluster.<\/p><\/li><li><p><strong>Kostenwirksame ko-paketierte Optik (CPO):<\/strong><br\/>Ersetzen von steckbaren Modulen durch eingebettete photonische Motoren.<\/p><\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\udd39 Fazit<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Traditionelle optische Modulatoren ebneten den Weg f\u00fcr die optische Kommunikation mit ihrer Pr\u00e4zision und Linearit\u00e4t. Allerdings, <strong>Silizium-photonische Modulatoren<\/strong> definieren die Zukunft neu \u2013 sie vereinen Skalierbarkeit, Kosteneffizienz und Integration auf einer einzigen Plattform.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Da die Nachfrage nach h\u00f6herer Bandbreite und geringerem Stromverbrauch weiter steigt, <strong>Siliziumphotonik<\/strong> stellt den vielversprechendsten Weg nach vorn f\u00fcr optische Transceiver der n\u00e4chsten Generation dar.<\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" >\ud83d\udd39 Empfohlene Lekt\u00fcre<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/what-is-optical-modulation-and-how-it-works-explained\/\">Was ist optische Modulation und wie funktioniert sie?<\/a><\/p><\/li><li><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/glossary\/what-is-pam4-four-level-pulse-amplitude-modulation-basics\/\">Grundlagen der PAM4-Modulation<\/a><\/p><\/li><li><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/knowledge-center\/dp-qpsk-dual-polarization-qpsk-explained-and-its-uses\/\">DP-QPSK erkl\u00e4rt und ihre Anwendungsbereiche<\/a><\/p><\/li><li><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/glossary\/qam-modulation-how-it-improves-data-transmission-efficiency\/\">QAM-Modulation und Effizienz der Daten\u00fcbertragung<\/a><\/p><\/li><li><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/glossary\/transimpedance-amplifiers-tias-how-they-work-and-applications\/\">Transimpedanzverst\u00e4rker (TIAs): Funktionsweise<\/a><\/p><\/li><li><p><a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/knowledge-center\/silicon-photonics-comprehensive-guide\/\">Umfassender Leitfaden zur Siliziumphotonik<\/a><\/p><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Erfahren Sie mehr \u00fcber die Unterschiede zwischen Silizium-Photonik-Modulatoren und herk\u00f6mmlichen optischen Modulatoren, ihre Funktionsprinzipien, Vorteile sowie ihre Rolle in optischen Transceivern der n\u00e4chsten Generation.<\/p>","protected":false},"author":1,"featured_media":4465,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[26],"class_list":["post-4466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowledge-center","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/posts\/4466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/comments?post=4466"}],"version-history":[{"count":4,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/posts\/4466\/revisions"}],"predecessor-version":[{"id":10913,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/posts\/4466\/revisions\/10913"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/media\/4465"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/media?parent=4466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/categories?post=4466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/tags?post=4466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}