{"id":4284,"date":"2025-09-17T11:12:00","date_gmt":"2025-09-17T11:12:00","guid":{"rendered":"https:\/\/lp.szlogic.cn\/glossary\/differential-mode-delay-impact-on-fiber-speed-and-quality\/"},"modified":"2026-06-22T07:04:28","modified_gmt":"2026-06-22T07:04:28","slug":"differential-mode-delay-impact-on-fiber-speed-and-quality","status":"publish","type":"post","link":"https:\/\/resourceslp.szlogic.cn\/de\/glossary\/differential-mode-delay-impact-on-fiber-speed-and-quality","title":{"rendered":"Differential Mode Delay (DMD) entschl\u00fcsselt: Der verborgene Feind hochgeschwindigkeitsf\u00e4higer Multimode-Fasern"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1312\" height=\"736\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/65cf021a46e44a539769c59c83a63c09.webp\" alt=\"What Differential Mode Delay Means for Fiber Speed\" class=\"wp-image-4282\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/65cf021a46e44a539769c59c83a63c09.webp 1312w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/65cf021a46e44a539769c59c83a63c09-300x168.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/65cf021a46e44a539769c59c83a63c09-1024x574.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/65cf021a46e44a539769c59c83a63c09-768x431.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/65cf021a46e44a539769c59c83a63c09-18x10.webp 18w\" sizes=\"(max-width: 1312px) 100vw, 1312px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Bei der unerbittlichen Suche nach schnelleren Rechenzentren und Unternehmensnetzwerken, <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/knowledge-center\/om1-om2-om3-om4-om5-multimode-fiber-guide\/\"><strong>Multimode-Faser (MMF)<\/strong><\/a> war sie ein zuverl\u00e4ssiger Arbeitstier. Ihre Kosteneffizienz und einfache Handhabung machen sie zur bevorzugten L\u00f6sung f\u00fcr Kurzstreckenanwendungen. Doch wenn wir h\u00f6here Geschwindigkeiten anstreben \u2013 von 10\u00a0Gbit\/s \u00fcber 40\u00a0Gbit\/s und 100\u00a0Gbit\/s hinaus \u2013 tritt ein subtiler, aber entscheidender Effekt zutage: <strong>Differenzielle Modenverz\u00f6gerung (DMD)<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Vernachl\u00e4ssigung von DMD kann zu r\u00e4tselhaften Bitfehlern, verk\u00fcrzter \u00dcbertragungsreichweite und frustrierenden Netzwerkperformanceproblemen f\u00fchren. Dieser Leitfaden erl\u00e4utert dieses komplexe Thema, erkl\u00e4rt dessen Auswirkungen auf Ihr Netzwerk und zeigt Ihnen, wie die Auswahl der richtigen Komponenten \u2013 etwa <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/page\/aboutus.htm\"><strong>LINK-PP<\/strong><\/a>\u2018Premium-Optikmodule von <span class=\"company-name\">, der Schl\u00fcssel zur Bew\u00e4ltigung dieses Problems ist.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Key Takeaways<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>Differential Mode Delay (DMD) verlangsamt die Daten\u00fcbertragung in der Lichtwellenleiter-Technik. Das Verst\u00e4ndnis von DMD hilft Ihnen, die beste Faser f\u00fcr hohe Geschwindigkeiten auszuw\u00e4hlen.<\/p><\/li><li><p>Die Verwendung einer Few-Mode-Faser senkt die DMD. Dadurch bleiben Lichtpulse eng beieinander und sind leicht lesbar. Dies f\u00fchrt zu besserer Signalqualit\u00e4t und weniger Fehlern.<\/p><\/li><li><p>Testen Sie Ihre Faser regelm\u00e4\u00dfig auf DMD. So erkennen Sie Probleme fr\u00fchzeitig und halten Ihr Netzwerk schnell und stabil.<\/p><\/li><li><p>Richtige Installationsmethoden f\u00fcr Lichtwellenleiter sind \u00e4u\u00dferst wichtig. Vermeiden Sie scharfe Biegungen und halten Sie die Faser sauber. Dadurch wird die DMD gesenkt und die Funktionsf\u00e4higkeit der Faser verbessert.<\/p><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Was ist Differential Mode Delay (DMD)? Eine einfache Analogie<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Stellen Sie sich eine Stadionwelle vor. Wenn alle gleichzeitig aufstehen, <em>genau<\/em> zum gleichen Zeitpunkt, l\u00e4uft die Welle perfekt durch die Arena. Stehen jedoch Gruppen von Menschen jeweils leicht versetzt auf, wird die Welle unscharf, verzerrt und kollabiert schlie\u00dflich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Genau das passiert im Inneren einer <strong>Multimode-Faser<\/strong>. Licht breitet sich auf mehreren Pfaden \u2013 den sogenannten \u201cModi\u201d \u2013 aus.\u201d <strong>Differential Mode Delay ist die Variation in der Laufzeitverz\u00f6gerung (der Reisezeit) zwischen diesen verschiedenen Modi.<\/strong> Idealerweise w\u00fcrden alle Lichtpulse gleichzeitig am Ende eintreffen. In der Realit\u00e4t f\u00fchren Unvollkommenheiten im Kern der Faser jedoch dazu, dass einige Modi schneller als andere laufen und der urspr\u00fcnglich scharfe Puls sich zeitlich ausbreitet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Ausbreitung ist eine Form von <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/knowledge-center\/dispersion-in-optical-transceiver-signal-clarity-and-management\/\"><strong>Modaldispersion<\/strong><\/a>, wobei DMD deren spezifische, messbare Kenngr\u00f6\u00dfe darstellt.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1312\" height=\"1033\" src=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/cccba084eadf4fb79cb2d82edd400cad.webp\" alt=\"Differential Mode Delay (DMD)\" class=\"wp-image-4283\" srcset=\"https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/cccba084eadf4fb79cb2d82edd400cad.webp 1312w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/cccba084eadf4fb79cb2d82edd400cad-300x236.webp 300w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/cccba084eadf4fb79cb2d82edd400cad-1024x806.webp 1024w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/cccba084eadf4fb79cb2d82edd400cad-768x605.webp 768w, https:\/\/resourceslp.szlogic.cn\/wp-content\/uploads\/2026\/05\/cccba084eadf4fb79cb2d82edd400cad-15x12.webp 15w\" sizes=\"(max-width: 1312px) 100vw, 1312px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Warum ist DMD ein gro\u00dfes Problem f\u00fcr moderne Netzwerke?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">DMD wird zu einer kritischen Leistungsgrenze, wenn die Datenraten steigen. Die Impulse, die Datenbits repr\u00e4sentieren, werden bei h\u00f6heren Geschwindigkeiten immer enger zusammen \u00fcbertragen. Ist die Impulsstreckung (verursacht durch DMD) signifikant, l\u00e4uft die Energie eines Impulses in den Zeitraum des n\u00e4chsten Impulses hinein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser Effekt, bekannt als <strong>Inter-Symbol-Interferenz (ISI)<\/strong>, erschwert es dem Empf\u00e4nger enorm, zwischen einer \u20181\u2019 und einer \u20180\u2019 zu unterscheiden. Das Ergebnis? Eine erh\u00f6hte <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/glossary\/understanding-what-is-bit-error-rate\/\"><strong>Ein niedrigeres ER erh\u00f6ht die Wahrscheinlichkeit von Bit-Fehlinterpretationen, was zu einer h\u00f6heren BER f\u00fchrt. Ein ausreichendes ER hilft sicherzustellen, dass die \u00dcbertragung ohne Fehler \u00fcber lange Strecken oder hohe Geschwindigkeiten m\u00f6glich ist.<\/strong><\/a>, Link-Unstabilit\u00e4t und letztlich Netzwerk-Ausf\u00e4lle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dies ist besonders entscheidend f\u00fcr Anwendungen mit <a target=\"_blank\" rel=\"\" href=\"https:\/\/resourceslp.szlogic.cn\/de\/glossary\/overview-of-vcsel\/\"><strong>Vertical-Cavity Surface-Emitting Lasern (VCSELs)<\/strong><\/a>, der Standardlichtquelle f\u00fcr Hochgeschwindigkeits-Multimode-Faserverbindungen. Im Gegensatz zu LEDs, die den Faserkern mit Licht fluten, injizieren Laser einen kleinen, konzentrierten Lichtfleck. Dieser Fleck kann nur eine begrenzte Modenanzahl anregen, wodurch die Verbindung besonders anf\u00e4llig f\u00fcr DMD-bedingte Verzerrungen wird.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Bek\u00e4mpfung von DMD: Der Aufstieg optimierter Fasern und Optiken<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Branchenl\u00f6sung f\u00fcr diese Herausforderung besteht aus zwei Komponenten:<\/p>\n\n\n\n<ol class=\"wp-block-list\" >\n<li><p style=\"margin: 0px;\"><strong>DMD-optimierte Multimode-Fasern (OM3\/OM4\/OM5):<\/strong> Moderne Fasern werden mit strengen DMD-Spezifikationen hergestellt. Diese \u201claseroptimierten\u201d Fasern sind so konzipiert, dass sie die Laufzeitunterschiede zwischen den Moden minimieren und dadurch saubere Signal\u00fcbertragung bei 10 G, 40 G und 100 G gew\u00e4hrleisten.<\/p><\/li><li><p style=\"margin: 0px;\"><strong>DMD-getestete und konforme optische Transceiver:<\/strong> Nicht alle Transceiver sind gleichwertig. Hochwertige Module werden speziell entwickelt und getestet, um harmonisch mit DMD-optimierten Fasern zu arbeiten. Hier kommt es entscheidend auf die Wahl Ihres Lieferanten an.<\/p><\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Wie LINK-PP fehlerfreie Leistung in DMD-empfindlichen Anwendungen sicherstellt<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">At <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.link-pp.com\/\"><strong>LINK-PP<\/strong><\/a>, entwickeln wir unsere optischen Transceiver nicht nur zur Einhaltung, sondern zur \u00dcbertreffung der Industriestandards und gestalten proaktiv gegen Herausforderungen wie Differential Mode Delay (DMD).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unsere Module unterziehen wir umfangreichen Tests, um eine optimale <strong>Modalleistung<\/strong> et <strong>niedrige Bitfehlerrate (BER)<\/strong> selbst an den extremen Grenzen ihrer spezifizierten Reichweite sicherzustellen. Dies erreichen wir durch pr\u00e4zise Kontrolle \u00fcber die Laserparameter und fortschrittliche Signalverarbeitungsalgorithmen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zum Beispiel unser <strong>LINK-PP <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/475415.htm\"><strong>SFP-10G-SR<\/strong><\/a> et <strong>LINK-PP <\/strong><a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/products\/473115.htm\"><strong>QSFP-100G-SR4<\/strong><\/a> Transceiver sind sorgf\u00e4ltig darauf ausgelegt, Licht so einzuspeisen, dass die Anregung problematischer Modengruppen, die zur DMD beitragen, minimiert wird. Dies f\u00fchrt zu einem saubereren Signal, einem gr\u00f6\u00dferen <strong>Leistungs-Budget<\/strong>, und einer stabileren Verbindung f\u00fcr Ihre kritische Rechenzentrumsinfrastruktur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wichtige Spezifikationen von DMD-konformen Transceivern:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<colgroup><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><col style=\"min-width: 25px;\"\/><\/colgroup><tbody><tr><th colspan=\"1\" rowspan=\"1\"><p>Funktion<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Standard-Transceiver<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>LINK-PP DMD-optimierter Transceiver<\/p><\/th><th colspan=\"1\" rowspan=\"1\"><p>Vorteil<\/p><\/th><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Laser-Einleitprofil<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Unkontrolliert, kann den Faserkern \u00fcberf\u00fcllen<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Pr\u00e4zise gesteuert, zentral eingeleitet<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Minimiert die Anregung verz\u00f6gerungsempfindlicher Moden<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>DMD-Pr\u00fcfung<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Wird nicht immer durchgef\u00fchrt<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Streng getestet auf DMD-belasteten Fasern<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Garantierte Leistung unter realen Bedingungen<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Unterst\u00fctzte Datenraten<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Kann bei maximaler Nenn-Geschwindigkeit Probleme aufweisen<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Stabile Leistung bei 10 G, 40 G, 100 G und 400 G<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Zukunfts sichert Ihre Netzwerkinvestition<\/p><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><p><strong>Effektive Reichweite<\/strong><\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Kann eine reduzierte Reichweite aufweisen<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Erreicht die maximale spezifizierte Reichweite (z.\u202fB. 400 m auf OM4)<\/p><\/td><td colspan=\"1\" rowspan=\"1\"><p>Bietet Planungsflexibilit\u00e4t und Reserve<\/p><\/td><\/tr><\/tbody>\n<\/table>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd Fazit: Lassen Sie sich nicht durch DMD in Ihrer Netzwerkleistung beeintr\u00e4chtigen<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Das Verst\u00e4ndnis von <strong>Differenzielle Modenverz\u00f6gerung<\/strong> ist nicht mehr nur etwas f\u00fcr Faseroptikphysiker. F\u00fcr Netzwerkarchitekten und Rechenzentrummanager ist es ein entscheidender Faktor, um Zuverl\u00e4ssigkeit sicherzustellen und die gew\u00fcnschte Rendite bei Hochgeschwindigkeitsinfrastruktur zu erzielen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der einfachste Weg, das DMD-Risiko zu mindern, besteht darin, <strong>laseroptimierte OM4-\/OM5-Faser<\/strong> zu verwenden und mit einem <a target=\"_blank\" rel=\"\" href=\"https:\/\/www.l-p.com\/store-25432-optics-transceivers-sfp-modules.htm\"><strong>Optischer Transceiver<\/strong><\/a> Hersteller zusammenzuarbeiten, der Leistungsoptimierung priorisiert.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" ><strong>\ud83d\udcdd FAQ<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" >Was ist Differential Mode Delay (DMD) in der Faseroptik?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Differential Mode Delay tritt auf, wenn Lichtpulse sich innerhalb der Faser mit unterschiedlichen Geschwindigkeiten bewegen. Dies bemerken Sie bei Multimodefasern. Die Pulse treffen nicht gleichzeitig ein. Dadurch kann Ihre Daten\u00fcbertragung langsamer werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Was zeigt die DMD-Steigung bei der Fasertestung an?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die DMD-Steigung zeigt an, wie stark sich die Verz\u00f6gerung f\u00fcr verschiedene Moden \u00e4ndert. Sie nutzen sie, um die Qualit\u00e4t Ihrer Faser einzusch\u00e4tzen. Ist die DMD-Steigung gering, k\u00f6nnen Ihre Fasern Signale schneller und klarer \u00fcbertragen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Wodurch ist eine Multimodefaser mit gestuftem Brechungsindex und Glas-Kern f\u00fcr Daten\u00fcbertragung besser geeignet?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Multimodefaser mit gestuftem Brechungsindex und Glas-Kern besitzt eine spezielle Kernform. Diese Form bietet glattere Laufbahnen f\u00fcr das Licht. Dadurch wird verhindert, dass sich die Pulse zu stark ausbreiten. So k\u00f6nnen Sie Daten schneller \u00fcbertragen und weniger Fehler machen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Welche Probleme kann eine hohe Differential Mode Delay (DMD) in der Telekommunikation verursachen?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Eine hohe Differential Mode Delay (DMD) kann Ihr Netzwerk verlangsamen. M\u00f6glicherweise treten mehr Fehler auf und Verbindungen gehen verloren. Die Telekommunikation ben\u00f6tigt eine geringe Verz\u00f6gerung, um Signale stark und stabil zu halten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" >Welche Ma\u00dfnahmen helfen, die Differential Mode Delay (DMD) zu reduzieren?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sie k\u00f6nnen Few-Mode-Fasern w\u00e4hlen und diese sorgf\u00e4ltig installieren. Biegen Sie die Faser nicht zu stark und halten Sie sie sauber. Testen Sie Ihre Faser regelm\u00e4\u00dfig, um Probleme fr\u00fchzeitig zu erkennen und zu beheben.<\/p>","protected":false},"excerpt":{"rendered":"<p>Die differentielle Modenverz\u00f6gerung in Multimode-Glasfasern begrenzt Geschwindigkeit und Datenraten, indem sie eine Impulsstreuung verursacht, wodurch die Signaldeutlichkeit und die Netzwerkleistung verringert werden.<\/p>","protected":false},"author":1,"featured_media":4282,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[27],"tags":[26],"class_list":["post-4284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-glossary","tag-optics-transceivers"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/posts\/4284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/comments?post=4284"}],"version-history":[{"count":5,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/posts\/4284\/revisions"}],"predecessor-version":[{"id":11113,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/posts\/4284\/revisions\/11113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/media\/4282"}],"wp:attachment":[{"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/media?parent=4284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/categories?post=4284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resourceslp.szlogic.cn\/de\/wp-json\/wp\/v2\/tags?post=4284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}